{"id":4265,"date":"2019-11-05T08:15:27","date_gmt":"2019-11-05T11:15:27","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=4265"},"modified":"2019-11-05T08:15:27","modified_gmt":"2019-11-05T11:15:27","slug":"nas-entrelinhas-general-deixa-o-governo","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-general-deixa-o-governo\/","title":{"rendered":"Nas entrelinhas: General deixa o governo"},"content":{"rendered":"<p><em><strong>&#8220;Santa Rosa estava insatisfeito com o secret\u00e1rio-geral da Presid\u00eancia, Jorge Oliveira, um major da PM-DF, que engavetou seu pol\u00eamico projeto para a Calha Norte da Amaz\u00f4nia\u201d\u00a0<\/strong><\/em><\/p>\n<p>O general da reserva Maynard Marques de Santa Rosa, um quatro estrelas, deixou ontem a Secretaria Especial de Assuntos Estrat\u00e9gicos da Presid\u00eancia, com mais dois generais da reserva (Lauro Luiz Pires da Silva e Il\u00eddio Gaspar Filho) e dois oficiais de Estado-Maior, todos insatisfeitos com o engavetamento do Projeto Bar\u00e3o do Rio Branco, um plano de desenvolvimento da Calha Norte da Amaz\u00f4nia, que passou a ser considerado mais uma dor de cabe\u00e7a pelo presidente Jair Bolsonaro. A gota d\u2019\u00e1gua foi a apresenta\u00e7\u00e3o do projeto em um evento na C\u00e2mara, na sexta-feira, intitulado \u201cAmaz\u00f4nia Brasileira para Sempre\u201d, na qual o general adverte que a Fran\u00e7a e a Inglaterra teriam interesses \u201cimperialistas\u201d hist\u00f3ricos na regi\u00e3o.<\/p>\n<p>Santa Rosa anunciou o projeto logo ao assumir, em entrevista \u00e0 Voz do Brasil. Suas propostas mais pol\u00eamicas s\u00e3o a constru\u00e7\u00e3o de uma hidrel\u00e9trica no Rio Trombetas, a constru\u00e7\u00e3o de uma ponte no Rio Amazonas e a conclus\u00e3o da BR-163 at\u00e9 a fronteira entre Brasil e o Suriname. Santa Rosa j\u00e1 havia defendido a explora\u00e7\u00e3o da regi\u00e3o amaz\u00f4nica brasileira em um artigo escrito em 2013, intitulado Uma Estrat\u00e9gia Nacional para a Amaz\u00f4nia Legal, mas sua tese ganhou for\u00e7a em raz\u00e3o das propostas de campanha de Bolsonaro, que o levou para a SAE ap\u00f3s ser eleito. N\u00e3o foram poucas as entrevistas nas quais o presidente da Rep\u00fablica defendeu a intensifica\u00e7\u00e3o da explora\u00e7\u00e3o econ\u00f4mica da Amaz\u00f4nia, mas o debate internacional sobre a preserva\u00e7\u00e3o da bacia amaz\u00f4nica e sua repercuss\u00e3o nas exporta\u00e7\u00f5es brasileiras levaram o governo a um reposicionamento.<\/p>\n<p>O general \u00e9 um dos principais cr\u00edticos das pol\u00edticas ambiental e indigenista, que considera empecilhos \u00e0 soberania nacional. A constru\u00e7\u00e3o da hidrel\u00e9trica no Rio Trombetas teria como objetivo reduzir os apag\u00f5es na regi\u00e3o e garantir o fornecimento de energia para a Zona Franca de Manaus, al\u00e9m de possibilitar a explora\u00e7\u00e3o de min\u00e9rios, como o ouro e a bauxita, por grandes mineradoras. Com a expans\u00e3o da BR-163, haveria interliga\u00e7\u00e3o das hidrovias e maior mobilidade para os 800 mil habitantes da regi\u00e3o, que ficou praticamente fora da cadeia produtiva da borracha, por causa das caracter\u00edsticas espec\u00edficas de seu bioma.<\/p>\n<p>Na palestra na C\u00e2mara, que postou no YouTube, Santa Rosa destacou que a Amaz\u00f4nia teve uma coloniza\u00e7\u00e3o diferenciada e foi administrada diretamente de Portugal, pelo Conselho Ultramarino, de 1614 at\u00e9 1823, n\u00e3o sendo seccionada do Brasil por causa da l\u00edngua e da cultura do caboclo. Segundo ele, os Estados Unidos n\u00e3o se apropriaram da regi\u00e3o por causa da Guerra da Secess\u00e3o; e a Inglaterra, durante a Cabanagem (1835-1840), porque o l\u00edder da rebeli\u00e3o paraense, Eduardo Angelim, recusou o apoio brit\u00e2nico para declarar independ\u00eancia. Segundo ele, a Fran\u00e7a at\u00e9 hoje tem interesse no Amap\u00e1.<\/p>\n<p><b>Faltou combinar<\/b><br \/>\nLogo ap\u00f3s a assumir a SAE, o general anunciou que o \u201cPlano Nacional de Energia 2030\u201d do Minist\u00e9rio de Minas e Energia prev\u00ea a cria\u00e7\u00e3o de 15 hidrel\u00e9tricas na Bacia do Rio Trombetas. A primeira hidrel\u00e9trica seria a de Cachoeira Porteira, que inundaria terras ind\u00edgenas, quilombolas e unidades de conserva\u00e7\u00e3o. Tamb\u00e9m seriam exploradas as terras cultiv\u00e1veis do planalto da Guiana, que ficam entre o Amap\u00e1, Roraima e o norte do Par\u00e1 e do Amazonas. A Calha Norte do Par\u00e1, na fronteira, seria integrada ao centro produtivo do estado e do pa\u00eds.<\/p>\n<p>Extremamente pobre e com baixa densidade demogr\u00e1fica, a regi\u00e3o \u00e9 cortada por rios e de dif\u00edcil acesso. Tamb\u00e9m \u00e9 a mais preservada do Par\u00e1, estado campe\u00e3o em desmatamento. A rodovia BR-163, que come\u00e7ou a ser constru\u00edda nos anos 1970, seria estendida at\u00e9 a fronteira norte do Brasil, ligando hidrovias e cortando a Amaz\u00f4nia do Suriname at\u00e9 o \u201ccentro de poder\u201d, Bras\u00edlia \u2014 hoje, a rodovia vai de Tenente Portela, no Rio Grande do Sul, at\u00e9 Santar\u00e9m, no Par\u00e1. Com isso, seria poss\u00edvel escoar a produ\u00e7\u00e3o de soja do Centro-Oeste pelo Norte do pa\u00eds e integrar uma regi\u00e3o at\u00e9 agora \u201cdes\u00e9rtica\u201d, nas palavras do demission\u00e1rio secret\u00e1rio Especial de Assuntos Estrat\u00e9gicos da Presid\u00eancia da Rep\u00fablica.<\/p>\n<p>Faltou, por\u00e9m, combinar com o Congresso e o ministro da Economia, Paulo Guedes. O Plano precisaria de aprova\u00e7\u00e3o do Legislativo em decorr\u00eancia de ocupa\u00e7\u00e3o de terras ind\u00edgenas. Al\u00e9m disso, as prioridades de Bolsonaro, no momento, s\u00e3o outras: a aprova\u00e7\u00e3o do pacote de medidas que ser\u00e3o anunciadas hoje para destravar a economia, tr\u00eas das quais dependem de emendas constitucionais. Santa Rosa tamb\u00e9m estava insatisfeito com a troca de comando na Secretaria-Geral da Presid\u00eancia, cujo titular, Jorge Oliveira, \u00e9 um major reformado da Pol\u00edcia Militar de Bras\u00edlia, que engavetou o projeto Bar\u00e3o do Rio Branco. Ele substituiu o general Floriano Peixoto, atual presidente do Correios.\u00a0Outros projetos de sua secretaria tamb\u00e9m est\u00e3o engavetados, entre eles, industrializar \u00a0o enriquecimento de ur\u00e2nio e fomentar a pesquisa de fus\u00e3o nuclear; integrar os sistemas de defesa cibern\u00e9tica; e lan\u00e7ar um sat\u00e9lite nacional com ve\u00edculo pr\u00f3prio, da base de Alc\u00e2ntara.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Santa Rosa estava insatisfeito com o secret\u00e1rio-geral da Presid\u00eancia, Jorge Oliveira, um major da PM-DF, que engavetou seu pol\u00eamico projeto para a Calha Norte da Amaz\u00f4nia\u201d\u00a0 O general da reserva Maynard Marques de Santa Rosa, um quatro estrelas, deixou ontem a Secretaria Especial de Assuntos Estrat\u00e9gicos da Presid\u00eancia, com mais dois generais da reserva (Lauro Luiz Pires da Silva e [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,36,4,301,113,9,3,80],"tags":[488,130,77,114,556],"class_list":["post-4265","post","type-post","status-publish","format-standard","hentry","category-congresso","category-economia","category-governo","category-meio-ambiente","category-militares","category-politica-2","category-politica","category-seguranca","tag-amazonia","tag-bolsonaro","tag-congresso","tag-militares","tag-santarosa"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/4265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=4265"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/4265\/revisions"}],"predecessor-version":[{"id":4275,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/4265\/revisions\/4275"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=4265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=4265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=4265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}