{"id":3054,"date":"2018-10-08T08:12:39","date_gmt":"2018-10-08T11:12:39","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=3054"},"modified":"2018-10-08T09:22:23","modified_gmt":"2018-10-08T12:22:23","slug":"nas-entrelinhas-o-xadrez-do-segundo-turno","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-o-xadrez-do-segundo-turno\/","title":{"rendered":"Nas entrelinhas: O xadrez do segundo turno"},"content":{"rendered":"<p><em>&#8220;O primeiro turno, se examinarmos as elei\u00e7\u00f5es de governadores, senadores e deputados, mostra uma realidade pol\u00edtica mais complexa do que o antagonismo radical entre Bolsonaro e Haddad&#8221;<\/em><\/p>\n<p>Confirmando as expectativas, teremos segundo turno nas elei\u00e7\u00f5es para presidente da Rep\u00fablica, entre Jair Bolsonaro (PSL), que larga na frente, com cerca de 46, 3% dos votos, e Fernando Haddad (PT), com 29, 2%, aproximadamente. A onda Ciro Gomes (PDT), que teve em torno de 12,5% dos votos, esperan\u00e7a do movimento a favor do voto \u00fatil, n\u00e3o se confirmou. Geraldo Alckmin (PSDB) teve pouco mais de 4,8% dos votos e Marina Silva (Rede), completamente desidratada, apenas 1% dos votos \u2014 atr\u00e1s de Jo\u00e3o Amoedo (Novo), com 2,5%; Cabo Daciolo (Patriotas), 1,2%; e Henrique Meirelles, 1,2%.<\/p>\n<p>O realinhamento de for\u00e7as pol\u00edticas ser\u00e1 importante no segundo turno. Parcela consider\u00e1vel do eleitorado, por\u00e9m, se deslocar\u00e1 antecipadamente, o que dever\u00e1 fazer com que Bolsonaro comece o segundo turno com mais de 50% dos votos v\u00e1lidos nas pesquisas. \u00c9 uma conta simples de ser feita: a maioria dos votos de Amoedo, Daciolo e Meirelles, que somam em torno de 5%, tende a se transferir para o candidato do PSL, que precisaria de mais 4% dos votos v\u00e1lidos para vencer o pleito; Haddad, em contrapartida, mesmo com a maioria dos votos de Ciro e Marina, que somam 13,5%, alcan\u00e7aria no m\u00e1ximo 42% dos votos. Ou seja, por gravidade, Bolsonaro derrotaria Haddad no segundo turno.<\/p>\n<p>Entretanto, como j\u00e1 se viu v\u00e1rias vezes, teremos uma nova elei\u00e7\u00e3o. Haver\u00e1 debate pol\u00edtico entre os dois candidatos, que continuar\u00e3o se digladiando no hor\u00e1rio eleitoral gratuito e nas redes sociais. Bolsonaro, desta vez, ter\u00e1 paridade de meios para a propaganda no r\u00e1dio e na tev\u00ea. A rigor, n\u00e3o precisar\u00e1 de um grande esfor\u00e7o em dire\u00e7\u00e3o ao centro para vencer as elei\u00e7\u00f5es, porque j\u00e1 capturou uma parte desse eleitorado. Seu discurso politicamente incorreto, que aparentemente \u00e9 seu ponto fraco, n\u00e3o foi empecilho ao seu desempenho no primeiro turno; por\u00e9m, pode lev\u00e1-lo a perder os votos transferidos por gravidade.<\/p>\n<p>A situa\u00e7\u00e3o de Haddad \u00e9 mais complexa. Chegou ao segundo turno gra\u00e7as ao carisma de Lula, que abduziu sua identidade, mas isso lhe trouxe tamb\u00e9m a grande rejei\u00e7\u00e3o antipetista. O discurso de quem p\u00f5e a soberania nacional e a soberania popular acima de tudo \u00e9 envelhecido, passa a ideia de dubiedade quanto ao compromisso com as institui\u00e7\u00f5es democr\u00e1ticas e uma vis\u00e3o nacional desenvolvimentista ultrapassada, que dificulta suas alian\u00e7as. A sua soberba tamb\u00e9m pode p\u00f4r tudo a perder, porque precisa conquistar mais de 21% dos votos v\u00e1lidos para ganhar as elei\u00e7\u00f5es. Os votos da esquerda n\u00e3o chegam a tanto. Os 4,8% que ficaram at\u00e9 o fim com Geraldo Alckmin, por exemplo, podem fazer a diferen\u00e7a.<\/p>\n<p>Num artigo intitulado \u201cAo vencedor, as batatas\u201d, publicado ontem no jornal O Estado de S\u00e3o Paulo, o cientista pol\u00edtico Luiz Werneck Viana adverte: \u201cO artif\u00edcio de negar a identidade ao centro pol\u00edtico, de exist\u00eancia comprovada empiricamente em nossa sociedade h\u00e1 d\u00e9cadas, n\u00e3o tem como resistir ao imp\u00e9rio dos fatos. A imin\u00eancia de um segundo turno eleitoral nos devolve, em clima de p\u00e2nico, com o tempo fugindo das m\u00e3os, a busca pelo centro perdido. Sem ele, como vencer as elei\u00e7\u00f5es, pior, como governar? Com Haddad teremos o indulto de Lula e a convoca\u00e7\u00e3o de uma Assembleia Constituinte? Faltaria combinar com os russos, que, ali\u00e1s, s\u00e3o muitos. Que economia nos espera com Bolsonaro, a do Pinochet, neoliberalismo com fuzis?\u201d<\/p>\n<p><strong>Governadores<\/strong><\/p>\n<p>\u201cO centro pol\u00edtico, banido do sal\u00e3o, volta com for\u00e7a por todas as janelas\u201d, ironiza Werneck. Na verdade, quem quiser vencer o segundo turno ter\u00e1 que encontrar uma linha de a\u00e7\u00e3o compat\u00edvel com o novo Congresso, j\u00e1 eleito e mais conservador (destaque para o strike ocorrido no Senado), e com os governadores j\u00e1 eleitos ou que disputam o segundo turno. H\u00e1 um jogo a ser jogado nas disputas regionais: S\u00e3o Paulo, Minas, Rio de Janeiro, Bras\u00edlia, Santa Catarina, Rio Grande do Sul, Mato Grosso do Sul, Roraima, Rond\u00f4nia, Amap\u00e1, Amazonas, Par\u00e1, Rio Grande do Norte e Sergipe ter\u00e3o segundo turno para escolher seus governadores. \u00c9 um campeonato de xadrez pol\u00edtico que Bolsonaro e Haddad ter\u00e3o de jogar, pois s\u00e3o essas alian\u00e7as que podem mudar a deriva natural dos eleitores.<\/p>\n<p>A radicaliza\u00e7\u00e3o pol\u00edtica esquerda versus direita continuar\u00e1 a dividir o pa\u00eds, mas ser\u00e1 mitigada pelas alian\u00e7as ao centro. Vencer\u00e1 quem compreender a necessidade de construir uma ampla maioria em torno de um projeto exequ\u00edvel para o pa\u00eds, nos marcos das institui\u00e7\u00f5es democr\u00e1ticas. Quem insistir na l\u00f3gica da confronta\u00e7\u00e3o, num processo de desestabiliza\u00e7\u00e3o da democracia, se arrisca a perder as elei\u00e7\u00f5es, porque h\u00e1 uma forte consci\u00eancia democr\u00e1tica na maioria da sociedade. O resultado das urnas no primeiro turno, se examinarmos as elei\u00e7\u00f5es de governadores, senadores e deputados, mostra uma realidade pol\u00edtica mais complexa do que o antagonismo radical entre Bolsonaro e Haddad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;O primeiro turno, se examinarmos as elei\u00e7\u00f5es de governadores, senadores e deputados, mostra uma realidade pol\u00edtica mais complexa do que o antagonismo radical entre Bolsonaro e Haddad&#8221; Confirmando as expectativas, teremos segundo turno nas elei\u00e7\u00f5es para presidente da Rep\u00fablica, entre Jair Bolsonaro (PSL), que larga na frente, com cerca de 46, 3% dos votos, e Fernando Haddad (PT), com 29, [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,8,3],"tags":[130,67,208],"class_list":["post-3054","post","type-post","status-publish","format-standard","hentry","category-eleicoes","category-partidos","category-politica","tag-bolsonaro","tag-eleicoes2018","tag-haddad"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/3054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=3054"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/3054\/revisions"}],"predecessor-version":[{"id":3068,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/3054\/revisions\/3068"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=3054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=3054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=3054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}