{"id":2884,"date":"2018-08-17T07:33:34","date_gmt":"2018-08-17T10:33:34","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=2884"},"modified":"2018-08-17T07:33:34","modified_gmt":"2018-08-17T10:33:34","slug":"nas-entrelinhas-o-tipo-ideal","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-o-tipo-ideal\/","title":{"rendered":"Nas entrelinhas: O \u201ctipo ideal\u201d"},"content":{"rendered":"<p><em>&#8216;Havia dois tipos de domina\u00e7\u00e3o no governo Lula: a \u201ctradicional\u201d, muito bem representada pelas oligarquias patrimonialistas, e a \u201ccarism\u00e1tica\u201d, representada pelo l\u00edder petista&#8217;<\/em><\/p>\n<p>Chave da sociologia de Max Weber, o conceito de \u201ctipo ideal\u201d \u00e9 uma esp\u00e9cie de ovo de Colombo. Serve para equilibrar a rela\u00e7\u00e3o entre a subjetividade do analista e a objetividade do fato social. Quando desenvolveu esse conceito, o soci\u00f3logo alem\u00e3o n\u00e3o se enquadrava nas principais correntes de pensamento de sua \u00e9poca, que eram influenciadas por gigantes como Friedrich Hegel, Karl Marx e Immanuel Kant, mas respeitava a todos. As obras mais conhecidas de Weber s\u00e3o A \u00c9tica Protestante e O Esp\u00edrito do Capitalismo, que analisa a rela\u00e7\u00e3o entre as religi\u00f5es e o desenvolvimento do capitalismo, e A Pol\u00edtica como Voca\u00e7\u00e3o, que trata da rela\u00e7\u00e3o Estado, partido e sociedade, e conceitua os tipos de domina\u00e7\u00e3o em \u201clegal\u201d, \u201ctradicional\u201d e \u201ccarism\u00e1tica\u201d.<\/p>\n<p>Como outros intelectuais alem\u00e3es de sua gera\u00e7\u00e3o, Weber foi um cr\u00edtico do totalitarismo. Morreu de gripe espanhola, em 1920, logo ap\u00f3s a I Guerra Mundial. Ele admitiu, \u201ca priori\u201d, que toda pesquisa tem um ponto de partida subjetivo, estabelecido por seu autor, mas a objetividade de seu trabalho poderia ser assegurada com sistematiza\u00e7\u00e3o e padroniza\u00e7\u00e3o, para que o ponto de chegada fosse realmente objetivo. O \u201ctipo ideal\u201d \u00e9 uma constru\u00e7\u00e3o subjetiva do pesquisador, feita a partir de seus interesses. Com base na defini\u00e7\u00e3o de um determinado conceito, s\u00e3o selecionados certos elementos da realidade que, reunidos, formam um tipo idealmente perfeito.<\/p>\n<p>Conceitos n\u00e3o emanam diretamente da realidade, nem s\u00e3o formados apenas pela abstra\u00e7\u00e3o gen\u00e9rica. Na vis\u00e3o weberiana, servem para acentuar e tornar compreens\u00edveis determinados elementos da realidade. A narrativa do \u201cgolpe\u201d contra a presidente Dilma Rousseff \u00e9 uma esp\u00e9cie de \u201ctipo ideal\u201d, a partir da qual se constr\u00f3i toda a l\u00f3gica de atua\u00e7\u00e3o do PT no sentido de deslegitimar o seu impeachment e varrer para debaixo do tapete as responsabilidades dos governos Lula e Dilma em rela\u00e7\u00e3o \u00e0 crise econ\u00f4mica que o pa\u00eds atravessa e ao esc\u00e2ndalo da Petrobras, considerado o maior do g\u00eanero em todo o mundo.<\/p>\n<p>A partir desse conceito, a realidade \u00e9 interpretada de acordo com os interesses do partido e possibilita a constru\u00e7\u00e3o de um discurso ideol\u00f3gico, que unifica os militantes petistas e seus aliados. A realidade \u00e9 explicada de acordo essa narrativa, desprezando e distorcendo fatos que n\u00e3o se coadunam com as teses petistas. Por exemplo, o Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) acaba de divulgar os n\u00fameros do desemprego: 3,16 milh\u00f5es de brasileiros procuram emprego h\u00e1 mais de 2 anos. Trata-se do maior n\u00famero da s\u00e9rie hist\u00f3rica da pesquisa, iniciada em 2012.<\/p>\n<p>Esse n\u00famero corresponde a cerca de 24% do total de desempregados no pa\u00eds, que ficou em 13 milh\u00f5es no segundo trimestre. Na compara\u00e7\u00e3o com o primeiro trimestre do ano, houve um aumento de 238 mil no n\u00famero de brasileiros que est\u00e3o desempregados h\u00e1 mais de 2 anos. Desde o in\u00edcio da crise econ\u00f4mica, em 2014, ano da reelei\u00e7\u00e3o de Dilma Rousseff, esse contingente cresceu 162%. Ao todo, segundo o IBGE, s\u00e3o 27,6 milh\u00f5es de brasileiros subutilizados, o que representa 24,6% da for\u00e7a de trabalho. O grupo re\u00fane os desempregados, aqueles que est\u00e3o subocupados (menos de 40 horas semanais trabalhadas), os desalentados (que desistiram de procurar emprego) e os que poderiam estar ocupados, mas n\u00e3o trabalham por motivos diversos.<\/p>\n<p><strong>Domina\u00e7\u00e3o<\/strong><\/p>\n<p>Tudo isso o PT joga na conta do presidente Temer, que assumiu o governo com uma queda no Produto Interno Bruto (PIB) de 8,1%. Da posse de Dilma ao impeachment da petista, entre abril de 2014 e agosto de 2016, foram nove trimestres de quedas praticamente cont\u00ednuas, na mais longa recess\u00e3o no Brasil desde 1992. Somente em outubro de 2017, a recess\u00e3o acabou. Para usar uma categoria weberiana, Dilma foi afastada, porque seu governo estava fundado na \u201cdomina\u00e7\u00e3o legal\u201d, que pressup\u00f5e a aceita\u00e7\u00e3o das normas estabelecidas pela sociedade, no caso, a Constitui\u00e7\u00e3o e a Lei de Responsabilidade Fiscal. A condena\u00e7\u00e3o do ex-presidente Luiz In\u00e1cio Lula da Silva no caso do tr\u00edplex de Guaruj\u00e1, que o tornou ineleg\u00edvel, tem o mesmo fundamento.<\/p>\n<p>A Opera\u00e7\u00e3o Lava-Jato demonstrou que havia dois tipos de domina\u00e7\u00e3o no governo Lula: a \u201ctradicional\u201d, muito bem representada pelas oligarquias patrimonialistas, e a \u201ccarism\u00e1tica\u201d, representada pelo l\u00edder petista. Weber tomou emprestado do cristianismo esse conceito, conferindo-lhe sentido sociol\u00f3gico, e lhe atribuiu um poder de for\u00e7a revolucion\u00e1ria na hist\u00f3ria, por ser capaz de romper as formas normais de exerc\u00edcio do poder. Entretanto, a confian\u00e7a dos dominados no carisma do l\u00edder \u00e9 vol\u00favel, mais cedo ou mais tarde, morrer\u00e1 na praia da domina\u00e7\u00e3o tradicional ou legal. Esse \u00e9 o ponto em que estamos na novela da candidatura de Lula a presidente da Rep\u00fablica, que caminha para ser impugnada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;Havia dois tipos de domina\u00e7\u00e3o no governo Lula: a \u201ctradicional\u201d, muito bem representada pelas oligarquias patrimonialistas, e a \u201ccarism\u00e1tica\u201d, representada pelo l\u00edder petista&#8217; Chave da sociologia de Max Weber, o conceito de \u201ctipo ideal\u201d \u00e9 uma esp\u00e9cie de ovo de Colombo. Serve para equilibrar a rela\u00e7\u00e3o entre a subjetividade do analista e a objetividade do fato social. Quando desenvolveu esse [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37,46,4,22,7,5,8,9,3],"tags":[67,27,15,18,10],"class_list":["post-2884","post","type-post","status-publish","format-standard","hentry","category-desemprego","category-eleicoes","category-governo","category-impeachment","category-justica","category-lava-jato","category-partidos","category-politica-2","category-politica","tag-eleicoes2018","tag-governotemer","tag-dilma","tag-lava-jato","tag-lula"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=2884"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2884\/revisions"}],"predecessor-version":[{"id":2889,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2884\/revisions\/2889"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=2884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=2884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=2884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}