{"id":2844,"date":"2018-08-05T09:35:11","date_gmt":"2018-08-05T12:35:11","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=2844"},"modified":"2018-08-05T09:35:46","modified_gmt":"2018-08-05T12:35:46","slug":"nas-entrelinhas-os-tempos-sombrios","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-os-tempos-sombrios\/","title":{"rendered":"Nas entrelinhas: Os tempos sombrios"},"content":{"rendered":"<p><em>O Brasil est\u00e1 passando por um momento\u00a0 de radicaliza\u00e7\u00e3o pol\u00edtica, em meio a um choque de narrativas nas quais a primeira v\u00edtima das \u201ccertezas\u201d e \u201cverdades\u201d \u00e9 a fraternidade <\/em><\/p>\n<p>Um dos ensaios do livro Homens em tempos sombrios (Companhia de Bolso), da fil\u00f3sofa judia-alem\u00e3 Hanna Arendt, \u00e9 dedicado ao poeta, dramaturgo, fil\u00f3sofo e cr\u00edtico de arte alem\u00e3o Gotthold Ephraim Lessing (1729-1781) e discute a rela\u00e7\u00e3o entre a verdade e a humanidade. Considerado um dos maiores representantes do Iluminismo alem\u00e3o, Lessing \u00e9 autor da pe\u00e7a Nathan, o s\u00e1bio, de 1779, que se destaca pela defesa do livre pensamento e da toler\u00e2ncia religiosa, al\u00e9m da cr\u00edtica ao antissemitismo.<\/p>\n<p>\u00c0 \u00e9poca, a pe\u00e7a foi proibida pela Igreja; mais tarde, o mesmo aconteceu sob o nazismo e, depois, no comunismo. A obra descreve o modo como o comerciante judeu Nathan, o sult\u00e3o Saladin e um cavaleiro templ\u00e1rio superaram as diferen\u00e7as entre o Juda\u00edsmo, o Islamismo e o Cristianismo. Simultaneamente, aborda os temas da amizade, da toler\u00e2ncia, do relativismo divino e da necessidade de comunica\u00e7\u00e3o.<\/p>\n<p>Filho de um pastor luterano, Lessing estudou latim e matem\u00e1tica em Kamens, sua cidade natal, e, depois, medicina, teologia, literatura e filosofia na Universidade de Leipzig, mas trocou tudo pelo teatro. Acabou mudando-se para Berlim, onde se tornou dramaturgo e cr\u00edtico de arte. Entretanto, por causa de suas ideias avan\u00e7adas, nunca foi aceito nos c\u00edrculos da corte de Frederico II, o Grande, da Pr\u00fassia, principalmente por causa de Voltaire, que ent\u00e3o l\u00e1 vivia e cuja dramaturgia criticou duramente.<\/p>\n<p>Isolado, Lessing mudou-se para Breslau e, depois, Hamburgo, onde se tornou bibliotec\u00e1rio do duque Brunswick at Wolfenb\u00fcttel, o que lhe garantiu uma renda fixa, com a qual pode manter a fam\u00edlia e quitar as suas d\u00edvidas. No seu tempo, a verdade \u00fanica era a grande quest\u00e3o filos\u00f3fica e religiosa, com a qual Lessing polemizava. Divertia-se com o fato de que, t\u00e3o logo enunciada, a \u201cverdade\u201d imediatamente se transforma numa opini\u00e3o entre muitas outras, que era contestada, reformulada e reduzida a um tema de discurso entre outros.<\/p>\n<p>Com perd\u00e3o pelo pleonasmo, nada mais verdadeiro em tempos de sociedade l\u00edquida e de choques de narrativas. Uma \u00fanica verdade absoluta, se pudesse existir, seria a morte de todas as discuss\u00f5es. No seu ensaio sobre Lessing, Arendt estabelece a diferen\u00e7a entre as no\u00e7\u00f5es de possuir a verdade e estar certo, mas destaca que os dois pontos de vista t\u00eam algo em comum: os que assumem um ou outro geralmente n\u00e3o est\u00e3o preparados, em caso de conflito, para sacrificar seu ponto de vista \u00e0 humanidade ou \u00e0 amizade.\u201d<\/p>\n<p><strong>Humanismo<\/strong><br \/>\nChegamos ao que mais nos interessa. Nenhuma avalia\u00e7\u00e3o da natureza do islamismo, do juda\u00edsmo ou do cristianismo, segundo a Arendt, teria impedido Lessing de travar uma amizade com um mul\u00e7umano convicto, um judeu piedoso ou um crist\u00e3o crente. \u201cQualquer doutrina que, de princ\u00edpio, barrasse a possibilidade de amizade entre seres humanos seria rejeitada por sua consci\u00eancia livre e certeira. Teria imediatamente tomado o lado humano e n\u00e3o ligaria para a discuss\u00e3o culta ou inculta em cada parte&#8221;, destaca. A humanidade de Lessing pode ser resumida numa \u00fanica frase: \u201cQue cada um diga o que acha que \u00e9 verdade, e que a pr\u00f3pria verdade seja confiada a Deus!\u201d.<\/p>\n<p>Nos \u201ctempos sombrios\u201d a que se refere Hanna Arendt, o pano de fundo s\u00e3o a radicaliza\u00e7\u00e3o e o totalitarismo, em contraposi\u00e7\u00e3o \u00e0 amizade e ao humanismo. H\u00e1 o trauma alem\u00e3o decorrente do apoio ao nazismo e \u00e0 guerra, um dos temas recorrentes da fil\u00f3sofa, e tamb\u00e9m o trauma do que denominou de \u201cemigra\u00e7\u00e3o interna\u201d dos judeus, antes mesmo de Hitler ter chegado ao poder: a fuga do mundo para a oculta\u00e7\u00e3o; da vida p\u00fablica, para o anonimato. \u201cA fuga do mundo em tempos sombrios de impot\u00eancia sempre pode ser justificada, na medida em que n\u00e3o se ignore a realidade, mas \u00e9 constantemente reconhecida como algo a ser evitado\u201d, afirma Arendt em seu ensaio.<\/p>\n<p>\u00c0s v\u00e9speras de Hitler chegar ao poder, a for\u00e7a do escapismo brotava da persegui\u00e7\u00e3o aos judeus fugitivos na forma de resist\u00eancia \u00edntima, silenciosa e individual. \u201cMas h\u00e1 uma grande diferen\u00e7a entre for\u00e7a e poder. O poder surge apenas onde as pessoas agem em conjunto, mas n\u00e3o onde as pessoas se fortalecem como indiv\u00edduos\u201d, adverte. O Brasil est\u00e1 passando por um momento sombrio, de radicaliza\u00e7\u00e3o pol\u00edtica decorrente de projetos autorit\u00e1rios, em meio a um choque de narrativas nas quais a primeira v\u00edtima das \u201ccertezas\u201d e \u201cverdades\u201d \u00e9 a fraternidade, o humanismo.<\/p>\n<p>O escapismo em rela\u00e7\u00e3o ao processo eleitoral \u00e9 um fen\u00f4meno real, ainda mais porque o sistema pol\u00edtico descolou-se da maioria da sociedade. Entretanto, n\u00e3o resolve os problemas da pol\u00edtica e da economia, muito menos da dissemina\u00e7\u00e3o do \u00f3dio e da exacerba\u00e7\u00e3o de inimizades, inclusive em ambientes familiares. Faz muito sentido a advert\u00eancia de Hanna Arendt no ensaio sobre Lessing: \u201cComo era tentador, por exemplo, simplesmente ignorar o falastr\u00e3o insuportavelmente est\u00fapido dos nazistas. Mas, por mais sedutor que possa ser, render-se a tais tenta\u00e7\u00f5es e isolar-se em sua pr\u00f3pria psique, o resultado ser\u00e1 sempre uma perda do humano com a deser\u00e7\u00e3o da realidade\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Brasil est\u00e1 passando por um momento\u00a0 de radicaliza\u00e7\u00e3o pol\u00edtica, em meio a um choque de narrativas nas quais a primeira v\u00edtima das \u201ccertezas\u201d e \u201cverdades\u201d \u00e9 a fraternidade Um dos ensaios do livro Homens em tempos sombrios (Companhia de Bolso), da fil\u00f3sofa judia-alem\u00e3 Hanna Arendt, \u00e9 dedicado ao poeta, dramaturgo, fil\u00f3sofo e cr\u00edtico de arte alem\u00e3o Gotthold Ephraim Lessing [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2844","post","type-post","status-publish","format-standard","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=2844"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2844\/revisions"}],"predecessor-version":[{"id":2853,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2844\/revisions\/2853"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=2844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=2844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=2844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}