{"id":2829,"date":"2018-08-01T08:56:25","date_gmt":"2018-08-01T11:56:25","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=2829"},"modified":"2018-08-01T08:56:25","modified_gmt":"2018-08-01T11:56:25","slug":"nas-entrelinhas-agosto-no-supremo","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-agosto-no-supremo\/","title":{"rendered":"Nas entrelinhas: Agosto no Supremo"},"content":{"rendered":"<p>O Supremo Tribunal Federal (STF) retoma os trabalhos hoje com uma pauta importante, mas politicamente lateral: os julgamentos de tr\u00eas A\u00e7\u00f5es Diretas de Inconstitucionalidade (ADIs 2139, 2160 e 2237) que questionam dispositivo da Consolida\u00e7\u00e3o das Leis do Trabalho (CLT) e duas a\u00e7\u00f5es que discutem a validade de imposi\u00e7\u00e3o de idade m\u00ednima para a matr\u00edcula de alunos no ensino infantil e fundamental, uma Declarat\u00f3ria de Constitucionalidade (ADC) 17 e outra de Argui\u00e7\u00e3o de Descumprimento de Preceito Fundamental (ADPF) 292. A agenda principal, por\u00e9m, foi anunciada por 11 militantes do Movimento de Trabalhadores Sem-Terra (MST), que ontem iniciaram uma greve de fome pela liberta\u00e7\u00e3o do ex-presidente Luiz In\u00e1cio Lula da Silva, sob as marquises do Supremo. Foram removidos do local por ordem da presidente da Corte, ministra C\u00e1rmen L\u00facia.<\/p>\n<p>O Supremo est\u00e1 na imin\u00eancia de dar um basta a essas tentativas do ex-presidente de desmoralizar o Judici\u00e1rio. Ontem, a procuradora-geral da Rep\u00fablica, Raquel Dodge, enviou manifesta\u00e7\u00e3o ao STF contra o agravo regimental em que o ex-presidente Lula questiona decis\u00e3o do ministro Edson Fachin, relator da Lava-Jato, no caso do tr\u00edplex do Guaruj\u00e1 (SP). No documento, a PGR afirma que a decis\u00e3o do TRF4 \u2013 que condenou Lula a 12 anos e um m\u00eas de reclus\u00e3o por corrup\u00e7\u00e3o passiva e lavagem de dinheiro \u2013 deve ser mantida, e que o pedido da defesa \u00e9 inadmiss\u00edvel e n\u00e3o possui plausibilidade jur\u00eddica.<\/p>\n<p>Lula pleiteia efeito suspensivo ao recurso extraordin\u00e1rio apresentado contra o ac\u00f3rd\u00e3o do TRF4. Para Raquel Dodge, isso n\u00e3o \u00e9 poss\u00edvel, pois o recurso j\u00e1 foi negado pelo tribunal de origem. Em raz\u00e3o disso, e pela perda do objeto do pedido, o STF n\u00e3o deveria sequer apreciar a quest\u00e3o. Entretanto, caso os ministros aceitem julgar o caso, a procuradora-geral requer o n\u00e3o provimento do agravo regimental. Al\u00e9m de n\u00e3o preencher condi\u00e7\u00f5es m\u00ednimas de admissibilidade e plausibilidade jur\u00eddica, o recurso de Lula se baseia em supostas viola\u00e7\u00f5es a normas infraconstitucionais que o Minist\u00e9rio P\u00fablico Federal recha\u00e7a.<\/p>\n<p>A manifesta\u00e7\u00e3o da procuradora-geral da Rep\u00fablica desconstr\u00f3i a narrativa de que Lula foi condenado sem provas. Raquel Dodge recha\u00e7a o inconformismo do petista e destaca que os magistrados do TRF-4, \u201cnas duas decis\u00f5es, a \u00faltima inclusive por unanimidade\u201d, tiveram a seu dispor uma gama de material probat\u00f3rio e entenderam haver \u201cprovas robustas de que Lula praticou os crimes\u201d. A defesa do ex-presidente Lula apresentou dois embargos de declara\u00e7\u00e3o contra a decis\u00e3o do TRF-4 que aumentou a pena para 12 anos e um m\u00eas de reclus\u00e3o. A um foi dado provimento em parte e o outro n\u00e3o foi conhecido. Em seguida, foi interposto recurso especial no Superior Tribunal de Justi\u00e7a (STJ) e recurso extraordin\u00e1rio no STF. Ao mesmo tempo, foi apresentada Medida Cautelar perante o presidente do TRF-4 pedindo que os recursos Especial e Extraordin\u00e1rio fossem recebidos com efeito suspensivo.<\/p>\n<p>O nome desta cascata de recursos \u00e9 chicana. Ap\u00f3s o pedido ser indeferido, a defesa de Lula ajuizou nova medida cautelar no STF pedindo que o recurso extraordin\u00e1rio fosse recebido com efeito suspensivo. O recurso extraordin\u00e1rio n\u00e3o foi admitido pela vice-presidente do TRF-4 e, em fun\u00e7\u00e3o dessa decis\u00e3o, o ministro Edson Fachin considerou prejudicada a medida cautelar. Outro agravo regimental foi interposto, pedindo que fosse reconsiderada a decis\u00e3o do ministro do STF. Mas isso n\u00e3o ocorreu, e o agravo regimental ser\u00e1 submetido ao julgamento do plen\u00e1rio. Na manifesta\u00e7\u00e3o enviada ao Supremo, a PGR rebate todas as alega\u00e7\u00f5es da defesa do ex-presidente.<\/p>\n<p>Para Raquel Dodge, o recurso extremo de Lula n\u00e3o apresenta relev\u00e2ncia capaz de transcender seus interesses subjetivos e afetar outras pessoas em situa\u00e7\u00e3o semelhante. \u201cTampouco traz quest\u00f5es cuja resolu\u00e7\u00e3o dependa da an\u00e1lise do direito em tese e n\u00e3o de fatos estritamente relacionados \u00e0 causa concreta ora posta \u00e0 aprecia\u00e7\u00e3o judicial. Trata-se de recurso que versa sobre quest\u00f5es afetas unicamente \u00e0 situa\u00e7\u00e3o processual do requerente.\u201d<\/p>\n<p><strong>Candidatura<\/strong><\/p>\n<p>O uso ilimitado de recursos pela defesa de Lula n\u00e3o tem nada a ver com a boa advocacia, \u00e9 apenas uma estrat\u00e9gia pol\u00edtica para manter sua candidatura e embaralhar o jogo eleitoral. De certa forma, Lula est\u00e1 conseguindo iludir seus eleitores. Ontem, o presidente do Tribunal Superior Eleitoral (TSE), ministro Luiz Fux, deu um chega pra l\u00e1 nas inten\u00e7\u00f5es petistas, ao anunciar que Lula est\u00e1 ineleg\u00edvel e n\u00e3o h\u00e1 a menor hip\u00f3tese de registrar sua candidatura. Ou seja, mesmo que a conven\u00e7\u00e3o do PT venha a promover a provoca\u00e7\u00e3o de confirmar a candidatura de Lula, ela n\u00e3o ser\u00e1 aceita pela Corte, na avalia\u00e7\u00e3o de seu presidente. Na verdade, a regra vale para todos os pretendentes que estiverem condenados em segunda inst\u00e2ncia, em raz\u00e3o da Lei da Ficha Limpa e n\u00e3o apenas para Lula.<\/p>\n<p><strong>\u00bb Visto, lido e ouvido<\/strong> \u2013 Os leitores do Correio e o jornalismo brasileiro perderam, ontem, seu mais longevo colunista, o jornalista Ari Cunha, pioneiro de Bras\u00edlia. Um dos respons\u00e1veis pela circula\u00e7\u00e3o deste jornal desde o dia da inaugura\u00e7\u00e3o da nova capital, durante mais de 50 anos, foi um dos principais rep\u00f3rteres pol\u00edticos do pa\u00eds. RIP!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Supremo Tribunal Federal (STF) retoma os trabalhos hoje com uma pauta importante, mas politicamente lateral: os julgamentos de tr\u00eas A\u00e7\u00f5es Diretas de Inconstitucionalidade (ADIs 2139, 2160 e 2237) que questionam dispositivo da Consolida\u00e7\u00e3o das Leis do Trabalho (CLT) e duas a\u00e7\u00f5es que discutem a validade de imposi\u00e7\u00e3o de idade m\u00ednima para a matr\u00edcula de alunos no ensino infantil e [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,7,5,3],"tags":[67,18,10],"class_list":["post-2829","post","type-post","status-publish","format-standard","hentry","category-eleicoes","category-justica","category-lava-jato","category-politica","tag-eleicoes2018","tag-lava-jato","tag-lula"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=2829"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2829\/revisions"}],"predecessor-version":[{"id":2835,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2829\/revisions\/2835"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=2829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=2829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=2829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}