{"id":2806,"date":"2018-07-24T08:18:58","date_gmt":"2018-07-24T11:18:58","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=2806"},"modified":"2018-07-24T08:18:58","modified_gmt":"2018-07-24T11:18:58","slug":"nas-entrelinhas-apertem-os-cintos","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-apertem-os-cintos\/","title":{"rendered":"Nas entrelinhas: Apertem os cintos"},"content":{"rendered":"<p><em>Temer viaja, C\u00e1rmem L\u00facia assume a Presid\u00eancia e Dias Toffoli comanda o Supremo Tribunal Federal (STF)<\/em><\/p>\n<p>A presidente do Supremo Tribunal Federal (STF), ministra C\u00e1rmen L\u00facia, assumiu o Pal\u00e1cio do Planalto ontem. O presidente Michel Temer viajou ao M\u00e9xico, onde participa do encontro de l\u00edderes dos pa\u00edses do Mercosul e da Alian\u00e7a do Pac\u00edfico, e depois seguir\u00e1 para a 10\u00aa C\u00fapula do Brics, grupo que re\u00fane, al\u00e9m do Brasil, R\u00fassia, \u00cdndia, China e \u00c1frica do Sul, anfitri\u00e3 do encontro, em Joanesburgo.<\/p>\n<p>Com isso, o vice-presidente do STF, ministro Dias Toffoli, assumiu o comando da Corte interinamente. At\u00e9 o fim da semana, decidir\u00e1 quest\u00f5es urgentes que chegarem ao plant\u00e3o do tribunal. O Supremo est\u00e1 em recesso. Os trabalhos ser\u00e3o retomados somente em 1\u00ba de agosto. O primeiro da linha sucess\u00f3ria \u00e9 o presidente da C\u00e2mara dos Deputados, Rodrigo Maia (DEM-RJ); o segundo, o do Senado, Eun\u00edcio Oliveira (PMDB-CE). A legisla\u00e7\u00e3o eleitoral, por\u00e9m, impede a candidatura de ocupantes de cargos no Executivo nos seis meses que antecedem as elei\u00e7\u00f5es. Dessa forma, se Maia ou Eun\u00edcio assumissem a Presid\u00eancia, ficariam ineleg\u00edveis e n\u00e3o poderiam disputar as elei\u00e7\u00f5es de outubro.<\/p>\n<p>Em setembro, Dias Toffoli assumir\u00e1 a cadeira de presidente do STF por dois anos em fun\u00e7\u00e3o do t\u00e9rmino do mandato de C\u00e1rmen L\u00facia, que come\u00e7ou em 2016. A interinidade de Toffoli est\u00e1 sendo comemorada pelos advogados dos r\u00e9us da Opera\u00e7\u00e3o Lava-Jato, que veem nele uma oportunidade de ouro para conseguir habeas corpus em favor dos acusados, na linha que vem sendo adotada pela Segunda Turma do STF, conhecida como Jardim do \u00c9den. Foi numa das sess\u00f5es dessa turma que, monocraticamente, Toffoli concedeu habeas corpus ao ex-ministro Jos\u00e9 Dirceu, livre de qualquer restri\u00e7\u00e3o de liberdade, inclusive o uso de tornozeleira eletr\u00f4nica.<\/p>\n<p>Nos bastidores do Judici\u00e1rio, por\u00e9m, advogados experientes acreditam que o ministro pautar\u00e1 a atua\u00e7\u00e3o na interinidade pela modera\u00e7\u00e3o e respeito \u00e0s decis\u00f5es j\u00e1 tomadas por C\u00e1rmen L\u00facia, entre as quais est\u00e1 a defesa da execu\u00e7\u00e3o imediata da pena de pris\u00e3o ap\u00f3s condena\u00e7\u00e3o em segunda inst\u00e2ncia, caso do ex-presidente Luiz In\u00e1cio Lula da Silva. No decorrer da semana \u00e9 que saberemos o que pretende fazer, mas \u00e9 bem poss\u00edvel que os advogados de Lula fa\u00e7am mais uma tentativa de liber\u00e1-lo da pris\u00e3o em Curitiba. Dificilmente, por\u00e9m, Toffoli contrariaria o encaminhamento j\u00e1 dado ao caso pela presidente do Supremo e pela sua colega do Superior Tribunal de Justi\u00e7a (STJ) Laurita Vaz. Provocaria uma crise no Judici\u00e1rio, de propor\u00e7\u00f5es inimagin\u00e1veis.<\/p>\n<p>Temer chegou ontem \u00e0 tarde em Puerto Vallarta, para um encontro com o presidente do M\u00e9xico, Enrique Pe\u00f1a Nieto, que est\u00e1 em fim de mandato. A reuni\u00e3o \u00e9 importante por causa do contencioso do presidente norte-americano Donald Trump com os vizinhos mexicanos. O encontro do Mercosul com a Alian\u00e7a do Pac\u00edfico, da qual os Estados Unidos se retiraram, pode ser um avan\u00e7o para as rela\u00e7\u00f5es comerciais brasileiras, pois tem o prop\u00f3sito de facilitar o com\u00e9rcio, a coopera\u00e7\u00e3o regulat\u00f3ria e a agenda digital.<\/p>\n<p>Mercosul e a Alian\u00e7a do Pac\u00edfico representam 90% do Produto Interno Bruto (PIB) e dos fluxos de investimento externo direto na Am\u00e9rica Latina e Caribe. No \u00faltimo ano, o com\u00e9rcio entre os dois blocos chegou a US$ 35,3 bilh\u00f5es, 18% a mais em rela\u00e7\u00e3o a 2016. O com\u00e9rcio do Brasil com a Alian\u00e7a do Pac\u00edfico cresceu 21,4% no per\u00edodo, um aumento de US$ 25 bilh\u00f5es.<\/p>\n<p><strong>Casa de enforcado<\/strong><\/p>\n<p>A Pol\u00edcia Federal indiciou ontem 12 pessoas na investiga\u00e7\u00e3o que mira desvios de R$ 600 milh\u00f5es das obras do Rodoanel Norte durante as gest\u00f5es tucanas em S\u00e3o Paulo, entre as quais o ex-presidente da Dersa Laurence Casagrande, ex-secret\u00e1rio de Geraldo Alckmin preso pela Opera\u00e7\u00e3o Pedra no Caminho desde junho. A PF atribui ao ex-secret\u00e1rio os crimes de fraude em licita\u00e7\u00f5es, falsidade ideol\u00f3gica e associa\u00e7\u00e3o criminosa.<\/p>\n<p>O esc\u00e2ndalo do Rodoanel \u00e9 uma das dores de cabe\u00e7a de Geraldo Alckmin, o candidato tucano \u00e0 Presid\u00eancia da Rep\u00fablica, que, at\u00e9 agora, manteve-se \u00e0 margem do esc\u00e2ndalo da Opera\u00e7\u00e3o Lava-Jato. O ex-presidente da Dersa Laurence Casagrande Louren\u00e7o acumulou tamb\u00e9m o cargo de secret\u00e1rio de Transportes e Log\u00edstica do ex-governador e s\u00f3 deixou a pasta quando M\u00e1rcio Fran\u00e7a (PSB) assumiu o governo.<\/p>\n<p>Alckmin sempre lavou as m\u00e3os em rela\u00e7\u00e3o a auxiliares envolvidos em esc\u00e2ndalos, muitas vezes tomando a iniciativa de demiti-los, antes mesmo da comprova\u00e7\u00e3o de qualquer den\u00fancia. N\u00e3o por acaso \u00e9 um sobrevivente entre os tucanos, apesar do desgaste sofrido pela legenda por causa da Lava-Jato.<\/p>\n<p>O Rodoanel e o metr\u00f4 estavam entre as principais obras do portf\u00f3lio de realiza\u00e7\u00f5es administrativas de Alckmin, mas agora, na campanha eleitoral, tratar desses projetos \u00e9 mais ou menos a mesma coisa do que falar de corda em casa de enforcado. As investiga\u00e7\u00f5es da PF foram realizadas em conjunto com o Minist\u00e9rio P\u00fablico Federal, a Controladoria-Geral da Uni\u00e3o (CGU) e o Tribunal de Contas da Uni\u00e3o (TCU). As obras do Rodoanel come\u00e7aram em 2013 e ainda n\u00e3o foram conclu\u00eddas. O trecho norte, quando estiver pronto, ligar\u00e1 a Rodovia dos Bandeirantes \u00e0 Via Dutra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Temer viaja, C\u00e1rmem L\u00facia assume a Presid\u00eancia e Dias Toffoli comanda o Supremo Tribunal Federal (STF) A presidente do Supremo Tribunal Federal (STF), ministra C\u00e1rmen L\u00facia, assumiu o Pal\u00e1cio do Planalto ontem. O presidente Michel Temer viajou ao M\u00e9xico, onde participa do encontro de l\u00edderes dos pa\u00edses do Mercosul e da Alian\u00e7a do Pac\u00edfico, e depois seguir\u00e1 para a 10\u00aa [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,7,5,8,3],"tags":[128,67,18,10],"class_list":["post-2806","post","type-post","status-publish","format-standard","hentry","category-eleicoes","category-justica","category-lava-jato","category-partidos","category-politica","tag-alckmin","tag-eleicoes2018","tag-lava-jato","tag-lula"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=2806"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2806\/revisions"}],"predecessor-version":[{"id":2811,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2806\/revisions\/2811"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=2806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=2806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=2806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}