{"id":2786,"date":"2018-07-17T18:37:59","date_gmt":"2018-07-17T21:37:59","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=2786"},"modified":"2018-07-18T10:15:16","modified_gmt":"2018-07-18T13:15:16","slug":"nas-entrelinhas-quando-o-sol-nasce-quadrado","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-quando-o-sol-nasce-quadrado\/","title":{"rendered":"Nas entrelinhas: Quando o sol nasce quadrado"},"content":{"rendered":"<p><em>O pr\u00f3ximo lance de Lula ser\u00e1 antecipar a conven\u00e7\u00e3o do PT e lan\u00e7ar sua candidatura, para criar um fato consumado e tentar concorrer \u00e0 Presid\u00eancia sub judice<\/em><\/p>\n<p>O ex-presidente Luiz In\u00e1cio Lula da Silva completou ontem 100 dias numa cela improvisada da Superintend\u00eancia da Pol\u00edcia Federal em Curitiba. Condenado a 12 anos e um m\u00eas de pris\u00e3o em regime fechado, mant\u00e9m sua candidatura a presidente da Rep\u00fablica, apesar de considerado ineleg\u00edvel. A Lei da Ficha Limpa pro\u00edbe condenados em segunda inst\u00e2ncia de concorrerem \u00e0s elei\u00e7\u00f5es. Com essa estrat\u00e9gia, por\u00e9m, o nome do petista permanece nas pesquisas de inten\u00e7\u00e3o de votos e na m\u00eddia.<\/p>\n<p>Os advogados de Lula fazem uma guerrilha no Judici\u00e1rio para tentar livrar o ex-presidente da cadeia. O lance mais audacioso de Lula para manter seu protagonismo foi o pedido de habeas corpus feito por deputados petistas e aceito pelo desembargador Rog\u00e9rio Favreto, plantonista no Tribunal Regional Federal da Regi\u00e3o (TRF-4), que tentou solt\u00e1-lo, mas foi impedido por determina\u00e7\u00e3o do presidente da Corte, desembargador Thompson Flores. Os ju\u00edzes naturais do caso do tr\u00edplex de Guaruj\u00e1, no qual o petista foi condenado, s\u00e3o o juiz federal S\u00e9rgio Moro, da 13\u00aa Vara Federal, de Curitiba, respons\u00e1vel pela execu\u00e7\u00e3o da pena, e o desembargador Jo\u00e3o Pedro Gebran Neto, relator do caso no TRF-4. A decis\u00e3o de Favreto foi considerada \u201cteratol\u00f3gica\u201d pela presidente do Superior Tribunal de Justi\u00e7a, ministra Laurita Vaz.<\/p>\n<p>O pr\u00f3ximo lance de Lula ser\u00e1 antecipar a conven\u00e7\u00e3o do PT e lan\u00e7ar sua candidatura, para criar um fato consumado e tentar concorrer \u00e0 Presid\u00eancia sub judice. \u00c9 um lance ousado, porque afronta ainda mais o Judici\u00e1rio, mas que leva em conta o rito do processo eleitoral. Nesse caso, o ex-prefeito de S\u00e3o Paulo Fernando Haddad seria indicado como vice, para vincular seu nome a Lula e substitu\u00ed-lo como candidato no caso de impugna\u00e7\u00e3o do registro da candidatura. Lula tem a seu favor o fato de liderar as pesquisas de opini\u00e3o, apesar da alta taxa de rejei\u00e7\u00e3o. Com isso, refor\u00e7a o discurso de que est\u00e1 sendo v\u00edtima de uma persegui\u00e7\u00e3o para impedir no tapet\u00e3o a sua volta ao poder.<\/p>\n<p>Apesar de condenado por crime comum (receber vantagens indevidas durante o exerc\u00edcio do cargo), Lula se considera um prisioneiro pol\u00edtico e organiza uma campanha internacional de solidariedade. O Brasil vive em regime de ampla liberdade, tem um governo constitu\u00eddo legalmente (Michel Temer era vice eleito de Dilma Rousseff) e um calend\u00e1rio eleitoral \u201cimex\u00edvel\u201d. Como a narrativa do \u201cgolpe\u201d, a vers\u00e3o \u201cLula, preso pol\u00edtico\u201d tamb\u00e9m \u00e9 falsa.<\/p>\n<p>Hoje, devido \u00e0s viagens de Michel Temer, Rodrigo Maia e Eun\u00edcio Oliveira, a ministra C\u00e1rmen L\u00facia assumir\u00e1 a Presid\u00eancia da Rep\u00fablica pela terceira vez. Temer participar\u00e1 de uma c\u00fapula da Comunidade dos Pa\u00edses de L\u00edngua Portuguesa em Cabo Verde e deve retornar ao Brasil amanh\u00e3. O ministro decano, Celso de Mello, assumir\u00e1 a Corte. Ainda n\u00e3o ser\u00e1 dessa vez que o vice-presidente do STF, Dias Toffoli, que est\u00e1 no exterior, assumir\u00e1 a comando do Supremo. H\u00e1 muita expectativa de que soltar\u00e1 Lula na primeira oportunidade em uma decis\u00e3o monocr\u00e1tica. Como se sabe, Toffoli concedeu de of\u00edcio o habeas corpus que livrou da pris\u00e3o o ex-ministro Jos\u00e9 Dirceu.<\/p>\n<p>Enquanto o sol nasce quadrado para Lula, o horizonte pol\u00edtico continua encoberto pelo nevoeiro de uma disputa eleitoral que se avizinha. As incertezas come\u00e7am a repercutir no ambiente econ\u00f4mico, que ainda sente os efeitos da greve dos caminhoneiros e precifica a irresponsabilidade fiscal do Congresso, bem como a falta de popularidade do governo. Ap\u00f3s a Copa do Mundo, as articula\u00e7\u00f5es para forma\u00e7\u00e3o das coliga\u00e7\u00f5es eleitorais foram intensificadas, e o PT opera para manter sob sua influ\u00eancia os velhos aliados, mas n\u00e3o h\u00e1 garantia de que os votos de Lula ser\u00e3o transferidos para Haddad.<\/p>\n<p><strong>Sa\u00fade<\/strong><\/p>\n<p>A presidente do STF, ministra C\u00e1rmen L\u00facia, suspendeu as novas regras dos planos de sa\u00fade, que poderiam levar o consumidor a pagar at\u00e9 40% do valor de consultas e exames, na forma de coparticipa\u00e7\u00e3o. O reajuste \u00e9 considerado \u201cabusivo\u201d em rela\u00e7\u00e3o \u00e0 m\u00e9dia atual de 30% cobrada pelos planos de sa\u00fade. A ministra acolheu pedido de liminar da OAB contra a Ag\u00eancia Nacional de Sa\u00fade (ANS). \u201cSa\u00fade n\u00e3o \u00e9 mercadoria. Vida n\u00e3o \u00e9 neg\u00f3cio. Dignidade n\u00e3o \u00e9 lucro. Direitos conquistados n\u00e3o podem ser retrocedidos sequer instabilizados\u201d, escreveu na decis\u00e3o.<\/p>\n<p>Para C\u00e1rmen L\u00facia, a \u201ctutela do direito fundamental \u00e0 sa\u00fade do cidad\u00e3o \u00e9 urgente\u201d, assim como \u201ca seguran\u00e7a e a previs\u00e3o dos usu\u00e1rios de planos de sa\u00fade\u201d. Segundo a ministra, como o direito \u00e0 sa\u00fade est\u00e1 previsto em lei, altera\u00e7\u00f5es em sua presta\u00e7\u00e3o devem ser objeto de ampla discuss\u00e3o na sociedade. Da forma como foi aprovada, a resolu\u00e7\u00e3o poderia trazer instabilidade jur\u00eddica e incremento na judicializa\u00e7\u00e3o no setor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O pr\u00f3ximo lance de Lula ser\u00e1 antecipar a conven\u00e7\u00e3o do PT e lan\u00e7ar sua candidatura, para criar um fato consumado e tentar concorrer \u00e0 Presid\u00eancia sub judice O ex-presidente Luiz In\u00e1cio Lula da Silva completou ontem 100 dias numa cela improvisada da Superintend\u00eancia da Pol\u00edcia Federal em Curitiba. Condenado a 12 anos e um m\u00eas de pris\u00e3o em regime fechado, [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,7,5,3],"tags":[67,18,10],"class_list":["post-2786","post","type-post","status-publish","format-standard","hentry","category-eleicoes","category-justica","category-lava-jato","category-politica","tag-eleicoes2018","tag-lava-jato","tag-lula"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=2786"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2786\/revisions"}],"predecessor-version":[{"id":2796,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2786\/revisions\/2796"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=2786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=2786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=2786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}