{"id":2376,"date":"2018-02-09T13:06:42","date_gmt":"2018-02-09T15:06:42","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=2376"},"modified":"2018-02-09T13:06:42","modified_gmt":"2018-02-09T15:06:42","slug":"nas-entrelinhas-tumulo-do-samba","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-tumulo-do-samba\/","title":{"rendered":"Nas entrelinhas: T\u00famulo do samba"},"content":{"rendered":"<p><em>\u00a0 Fernando Henrique Cardoso est\u00e1 mais para confundir do que pra explicar. Estimula a candidatura do apresentador Luciano Huck e n\u00e3o poupa o PSDB de cr\u00edticas, o que gera inc\u00f4modos para Alckmin<\/em><\/p>\n<p>A frase \u201cS\u00e3o Paulo \u00e9 o t\u00famulo do samba\u201d \u00e9 atribu\u00edda a Vin\u00edcius de Moraes, em protesto contra o p\u00fablico da antiga boate Cave, na rua da Consola\u00e7\u00e3o, no Centro de S\u00e3o Paulo, durante apresenta\u00e7\u00e3o do pianista e compositor Johnny Alf, um dos pioneiros da bossa nova, em 1960. Parceiro de Adoniran Barbosa, o poeta carioca logo se arrependeu do que disse, pois a cidade sempre foi um grande e acolhedor mercado para os sambistas cariocas. Hoje, os desfiles de escolas de samba e a explos\u00e3o do carnaval de rua mostram que sambistas paulistas pioneiros como Germano Mathias, Geraldo Filme, Dona Inah, Oswaldinho da Cu\u00edca e Seu Nen\u00ea da Vila Matilde n\u00e3o semearam em v\u00e3o.<\/p>\n<p>Tiro ao \u00c1lvaro, Saudosa maloca, Iracema e Trem das 11, de Adoniram Barbosa, e Volta por cima, de Paulo Vansolini, s\u00e3o cl\u00e1ssicos do samba paulista, cantados em todo o pa\u00eds. A homenagem aos sambistas de S\u00e3o Paulo, na v\u00e9spera do carnaval, \u00e9 um abre-alas para pedir passagem e falar da pol\u00edtica paulista, bem na v\u00e9spera do s\u00e1bado de carnaval. Boa parte da incerteza em rela\u00e7\u00e3o ao que vai acontecer com pa\u00eds nas elei\u00e7\u00f5es deste ano tem a ver com o xadrez da pol\u00edtica de S\u00e3o Paulo, o maior col\u00e9gio eleitoral do pa\u00eds, que hegemoniza a sucess\u00e3o presidencial.<\/p>\n<p>S\u00e3o Paulo pode se tornar o t\u00famulo da velha polariza\u00e7\u00e3o PT versus PSDB, que vem pautando as disputas presidenciais desde a primeira elei\u00e7\u00e3o de Fernando Henrique Cardoso, em 1994. Nas \u00faltimas elei\u00e7\u00f5es municipais, o PT quase foi varrido do estado, onde Dilma Rousseff, ao ser reeleita, j\u00e1 havia sofrido uma derrota acachapante. Sem Lula na corrida presidencial, o PT ter\u00e1 as maiores dificuldades para se recuperar no estado, ainda que o ex-prefeito Fernando Haddad seja o substituto do l\u00edder petista na chapa. Mesmo na regi\u00e3o do ABC, onde nasceu, a situa\u00e7\u00e3o do PT \u00e9 dram\u00e1tica.<\/p>\n<p>Mas a grande novidade \u00e9 a situa\u00e7\u00e3o do PSDB, que enfrenta a sua maior crise. O governador Geraldo Alckmin, que pretende deixar o cargo em 7 de abril para se candidatar a presidente da Rep\u00fablica, n\u00e3o decola nas pesquisas. Pelos c\u00e1lculos de seus estrategistas, isso somente ocorreria ap\u00f3s o in\u00edcio do hor\u00e1rio gratuito de tev\u00ea e r\u00e1dio, em 31 de agosto. \u00c9 muito tempo para ficar no sereno, enquanto a crise na sua base eleitoral se aprofunda. O PSDB n\u00e3o aceita apoiar a reelei\u00e7\u00e3o do vice-governador M\u00e1rcio Fran\u00e7a (PSB) e entregar de m\u00e3o beijada o segundo or\u00e7amento do pa\u00eds para o aliado. Quanto mais dificuldade enfrenta Alckmin, mais corros\u00e3o ocorre na sua base.<\/p>\n<p>O prefeito de S\u00e3o Paulo, Jo\u00e3o Doria (PSDB), com menos de dois anos de mandato, ensaia a candidatura ao Pal\u00e1cio dos Bandeirantes. Tenta um acordo com o PMDB e o PSD, do ex-prefeito Gilberto Kassab. Fran\u00e7a se mobiliza na Assembleia Legislativa e junto aos prefeitos do interior. E manda recado de que passar\u00e1 o rodo nos tucanos que n\u00e3o quiserem apoi\u00e1-lo, mesmo que sejam aliados de Alckmin, que precisa de uma alian\u00e7a nacional robusta. O apoio \u00e0 reelei\u00e7\u00e3o de Fran\u00e7a poderia garantir a coliga\u00e7\u00e3o com o PSB, mas h\u00e1 resist\u00eancias por causa da pol\u00edtica de Pernambuco. O governador Paulo C\u00e2mara (PSB) namora o PT para viabilizar a reelei\u00e7\u00e3o. Ou seja, n\u00e3o \u00e9 nada f\u00e1cil a vida de Alckmin, que ainda enfrenta um desafiante nas pr\u00e9vias do partido: o prefeito de Manaus, Arthur Virg\u00edlio Neto (PSDB).<\/p>\n<p><strong>Isolamento<\/strong><\/p>\n<p>Para complicar mais, o ex-presidente Fernando Henrique Cardoso parece seguir a m\u00e1xima do Chacrinha: est\u00e1 mais para confundir do que pra explicar. O l\u00edder tucano estimula a candidatura do apresentador Luciano Huck e n\u00e3o poupa o PSDB de cr\u00edticas, o que gera inc\u00f4modos para Alckmin. \u00c9 mais uma inc\u00f3gnita das elei\u00e7\u00f5es. O presidente do PPS, Roberto Freire (SP), aliado de Alckmin, ontem escancarou sua inten\u00e7\u00e3o de filiar o apresentador \u00e0 legenda e apoiar sua candidatura, preterindo tamb\u00e9m o senador Cristovam Buarque (PPS-DF), ex-governador do Distrito Federal, cuja pr\u00e9-candidatura tem apoio de setores do partido. A se\u00e7\u00e3o paulista do PPS, por\u00e9m, permanece com Alckmin.<\/p>\n<p>Um ator silencioso na pol\u00edtica de S\u00e3o Paulo \u00e9 o presidente Michel Temer. Suas rela\u00e7\u00f5es com Alckmin n\u00e3o s\u00e3o das melhores. No Pal\u00e1cio do Planalto, os movimentos s\u00e3o para evitar que o tucano unifique o centro democr\u00e1tico. H\u00e1 expectativas de que a aprova\u00e7\u00e3o da reforma da Previd\u00eancia e seu impacto na economia possam melhorar a popularidade de Temer, mas a grande aposta \u00e9 nos indicadores de infla\u00e7\u00e3o, que em janeiro foi 0,29%, a mais baixa desde o Plano Real, em 1994. Com a taxa de juros no patamar mais baixo da hist\u00f3ria, 6,75%, o c\u00edrculo \u00edntimo de Temer acredita que ele possa ter um papel decisivo na pr\u00f3pria sucess\u00e3o, talvez at\u00e9 disputar a reelei\u00e7\u00e3o. N\u00e3o \u00e9 \u00e0 toa que Temer quer isolar o PSDB, que desembarcou da na base do governo, e tenta confinar Alckmin em S\u00e3o Paulo. Ontem, por exemplo, jogou \u00e1gua fria numa alian\u00e7a de Doria com Paulo Skaf, presidente da Fiesp e potencial candidato ao Pal\u00e1cio dos Bandeirantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Fernando Henrique Cardoso est\u00e1 mais para confundir do que pra explicar. Estimula a candidatura do apresentador Luciano Huck e n\u00e3o poupa o PSDB de cr\u00edticas, o que gera inc\u00f4modos para Alckmin A frase \u201cS\u00e3o Paulo \u00e9 o t\u00famulo do samba\u201d \u00e9 atribu\u00edda a Vin\u00edcius de Moraes, em protesto contra o p\u00fablico da antiga boate Cave, na rua da Consola\u00e7\u00e3o, [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,4,8,3],"tags":[128,67,132,10],"class_list":["post-2376","post","type-post","status-publish","format-standard","hentry","category-eleicoes","category-governo","category-partidos","category-politica","tag-alckmin","tag-eleicoes2018","tag-huck","tag-lula"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=2376"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2376\/revisions"}],"predecessor-version":[{"id":2384,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2376\/revisions\/2384"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=2376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=2376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=2376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}