{"id":2364,"date":"2018-02-06T23:56:38","date_gmt":"2018-02-07T01:56:38","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=2364"},"modified":"2018-02-06T23:57:14","modified_gmt":"2018-02-07T01:57:14","slug":"nas-entrelinhas-comeca-folia","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-comeca-folia\/","title":{"rendered":"Nas entrelinhas: Come\u00e7a a folia"},"content":{"rendered":"<p>O Congresso voltou a funcionar ontem com a agenda previs\u00edvel: nada acontecer\u00e1 antes do carnaval. O relator Arthur Maia (PPS-BA) advertiu que a reforma da Previd\u00eancia precisa ser votada pela C\u00e2mara em fevereiro, ampliando o coro dos que querem ir para o tudo ou nada e decidir logo essa quest\u00e3o. O ministro da Casa Civil, Carlos Marun, refor\u00e7a a press\u00e3o governista para que o presidente da C\u00e2mara, Rodrigo Maia (DEM-RJ), coloque a mat\u00e9ria em pauta mesmo sem garantia de maioria de votos para aprova\u00e7\u00e3o. A reforma precisa do apoio de pelo menos 308 deputados, em duas vota\u00e7\u00f5es, mas, pelas contas do governo, ainda faltam 40 votos. A primeira vota\u00e7\u00e3o estava prevista para 19 de fevereiro, mas n\u00e3o h\u00e1 garantia de que ocorra enquanto o governo estiver em minoria.<\/p>\n<p>Ontem, o presidente Michel Temer enviou sua mensagem ao Congresso na qual reafirma a posi\u00e7\u00e3o do governo: \u201cNossas aten\u00e7\u00f5es est\u00e3o voltadas para a tarefa urgente de consertar a Previd\u00eancia. O atual sistema \u00e9 socialmente injusto e financeiramente insustent\u00e1vel. \u00c9 socialmente injusto porque transfere recursos de quem menos tem para quem menos precisa, concentrando renda. \u00c9 financeiramente insustent\u00e1vel porque as contas simplesmente n\u00e3o fecham, pondo em risco as aposentadorias de hoje e de amanh\u00e3\u201d. A mensagem presidencial foi entregue pelo ministro da Casa Civil, Eliseu Padilha, e lida pelo primeiro-secret\u00e1rio da C\u00e2mara, deputado Giacobo (PR-PR).<\/p>\n<p>Maia \u00e9 a favor da reforma da Previd\u00eancia, mas n\u00e3o quer ser derrotado. Enquanto o Pal\u00e1cio do Planalto avalia que a manuten\u00e7\u00e3o do calend\u00e1rio de vota\u00e7\u00e3o ajuda a formar a maioria, obrigando todos os que desejam permanecer na base do governo a descer do muro. Maia pensa exatamente o contr\u00e1rio, tem medo de p\u00f4r a reforma em vota\u00e7\u00e3o e o governo sofrer uma derrota acachapante, o que seria um fator de desagrega\u00e7\u00e3o ainda maior da base. Os deputados est\u00e3o voltando dos estados com foco na pr\u00f3pria sobreviv\u00eancia eleitoral.<\/p>\n<p>A Previd\u00eancia seria uma \u201cagenda positiva\u201d do governo, digamos assim, que empunhou a bandeira do fim dos privil\u00e9gios dos servidores p\u00fablicos para tentar melhorar a aceita\u00e7\u00e3o popular da reforma. Mas a \u201cagenda negativa\u201d do governo se imp\u00f5e, com destaque para o caso da deputada Cristiane Brasil (PTB-RJ), cuja posse est\u00e1 suspensa por medida liminar da presidente do Supremo Tribunal Federal (STF), C\u00e1rmen L\u00facia. Nomeada em 4 de janeiro, uma a\u00e7\u00e3o trabalhista de um ex-funcion\u00e1rio colocou em xeque seus atributos para o cargo. Ela mesma tem se encarregado de aumentar o fogo da frigideira com v\u00eddeos e declara\u00e7\u00f5es que somente servem para queimar ainda mais o seu filme com a opini\u00e3o p\u00fablica.<\/p>\n<p>Em outras circunst\u00e2ncias, um outro nome j\u00e1 teria sido indicado, mas o governo Temer precisa dramaticamente do apoio do PTB, presidido por Roberto Jefferson. O PTB n\u00e3o indica outro nome em seu lugar, nem o governo desiste de nome\u00e1-la antes de uma decis\u00e3o final do Supremo. Cristiane divulgou uma nota na qual pede \u00e0 presidente do Supremo Tribunal Federal que tome uma decis\u00e3o sobre o assunto \u201co mais r\u00e1pido poss\u00edvel\u201d. \u201cVenho sofrendo uma campanha difamat\u00f3ria que busca impedir minha posse no Minist\u00e9rio do Trabalho. Pe\u00e7o, respeitosamente, \u00e0 ministra C\u00e1rmen L\u00facia que julgue o mais r\u00e1pido poss\u00edvel essa quest\u00e3o\u201d, argumenta Cristiane Brasil.<\/p>\n<p><strong>Caixa dois<\/strong><br \/>\nFora do Congresso, segue seu curso inexor\u00e1vel mais um processo contra o ex-presidente Luiz In\u00e1cio Lula da Silva, na 13\u00aa Vara Federal de Curitiba, desta vez relativo ao s\u00edtio de Atibaia (SP). A publicit\u00e1ria M\u00f4nica Moura, mulher do marqueteiro Jo\u00e3o Santana, afirmou, em depoimento ao juiz S\u00e9rgio Moro, que mais de a metade do valor cobrado pelo casal para a campanha de reelei\u00e7\u00e3o de Lula, em 2006, foi pago por meio de caixa dois. Segundo ela, a campanha custou cerca de R$ 18 milh\u00f5es, e apenas R$ 8 milh\u00f5es foram pagos pelo caixa oficial. M\u00f4nica Moura disse ainda que a decis\u00e3o de como fazer os pagamentos foi do PT e que Jo\u00e3o Santana chegou a conversar com o ex-ministro Ant\u00f4nio Palocci sobre os riscos, j\u00e1 que a imagem do ex-presidente estava abalada pelo mensal\u00e3o.<\/p>\n<p>\u201cA decis\u00e3o era absolutamente deles, de receber por caixa dois. Para mim, (pagamento oficial) era menos risco, mais tranquilo, n\u00e3o tinha que carregar mala de dinheiro para lugar nenhum \u201c, disse M\u00f4nica, que dep\u00f4s na a\u00e7\u00e3o em que o ex-presidente Lula \u00e9 acusado por ter recebido vantagens indevidas da Odebrecht com reformas no s\u00edtio de Atibaia (SP).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Congresso voltou a funcionar ontem com a agenda previs\u00edvel: nada acontecer\u00e1 antes do carnaval. O relator Arthur Maia (PPS-BA) advertiu que a reforma da Previd\u00eancia precisa ser votada pela C\u00e2mara em fevereiro, ampliando o coro dos que querem ir para o tudo ou nada e decidir logo essa quest\u00e3o. O ministro da Casa Civil, Carlos Marun, refor\u00e7a a press\u00e3o [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2364","post","type-post","status-publish","format-standard","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=2364"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2364\/revisions"}],"predecessor-version":[{"id":2370,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2364\/revisions\/2370"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=2364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=2364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=2364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}