{"id":2322,"date":"2018-01-24T09:52:43","date_gmt":"2018-01-24T11:52:43","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=2322"},"modified":"2018-01-24T10:56:26","modified_gmt":"2018-01-24T12:56:26","slug":"nas-entrelinhas-e-se-lula-for-absolvido","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-e-se-lula-for-absolvido\/","title":{"rendered":"Nas entrelinhas: E se Lula for absolvido?"},"content":{"rendered":"<p><em>O julgamento do ex-presidente Luiz In\u00e1cio Lula da Silva \u00e9 criminal, n\u00e3o \u00e9 pol\u00edtico. Se fosse pol\u00edtico, seria pelo conjunto da obra; mas, n\u00e3o, \u00e9 um caso espec\u00edfico, envolvendo o tr\u00edplex de Guaruj\u00e1<\/em><\/p>\n<p>A maior surpresa poss\u00edvel no julgamento do recurso do Luiz In\u00e1cio Lula da Silva pelo Tribunal Regional Federal da 4\u00aa Regi\u00e3o (TRF-4) hoje, em Porto Alegre, ser\u00e1 a sua absolvi\u00e7\u00e3o das acusa\u00e7\u00f5es de que seria propriet\u00e1rio do tr\u00edplex de Guaruj\u00e1, cuja aquisi\u00e7\u00e3o e reforma teriam sid&#8217; feitas pela construtora OAS. Como se sabe, Lula est\u00e1 condenado pelo juiz S\u00e9rgio Moro a nove anos e meio de pris\u00e3o, e a confirma\u00e7\u00e3o da senten\u00e7a, em caso de unanimidade, praticamente o torna ineleg\u00edvel pela Lei da Ficha Limpa, mesmo que n\u00e3o seja preso. A anula\u00e7\u00e3o da senten\u00e7a seria a maior reviravolta no processo e um golpe de morte na Opera\u00e7\u00e3o Lava-Jato.<\/p>\n<p>Muitos apontam o julgamento de hoje como o mais importante da hist\u00f3ria. N\u00e3o \u00e9 verdade, como bem assinalou o ministro da Justi\u00e7a, Torquato Jardim, um jurista renomado, especialista em legisla\u00e7\u00e3o eleitoral. O maior julgamento pol\u00edtico foi a cassa\u00e7\u00e3o do registro do Partido Comunista em 1947, pelo Tribunal Superior Eleitoral (TSE). A decis\u00e3o somente foi revogada em 8 de maio de 1985, por decreto do ex-presidente Jos\u00e9 Sarney, que tamb\u00e9m provocou a extin\u00e7\u00e3o do processo contra 72 dirigentes do PCB, com base na extinta Lei de Seguran\u00e7a Nacional, acusados de tentar reorganiz\u00e1-lo ap\u00f3s a anistia, no congresso interrompido pela pol\u00edcia em 13 de dezembro de 1982, no centro de S\u00e3o Paulo.<\/p>\n<p>O julgamento do ex-presidente Luiz In\u00e1cio Lula da Silva \u00e9 criminal, n\u00e3o \u00e9 pol\u00edtico. Se fosse pol\u00edtico, seria pelo conjunto da obra; mas, n\u00e3o, \u00e9 um caso espec\u00edfico, envolvendo o tr\u00edplex de Guaruj\u00e1, no qual as provas materiais e testemunhais foram consideradas robustas pelo juiz S\u00e9rgio Moro. A suposta falta de provas \u00e9 apenas uma narrativa. Mas vamos supor que os desembargadores do TRF da 4\u00aa Regi\u00e3o absolvam Lula, hip\u00f3tese mais improv\u00e1vel. Ficar\u00e1 a seguinte d\u00favida: ele foi absolvido porque n\u00e3o havia provas suficientes, como aconteceu com Paulo Okamotto, ou em raz\u00e3o das press\u00f5es pol\u00edticas a que os desembargadores est\u00e3o sendo submetidos, inclusive amea\u00e7as an\u00f4nimas?<\/p>\n<p>Para salvar sua imagem e evitar uma poss\u00edvel pris\u00e3o, a estrat\u00e9gia de Lula n\u00e3o foi jur\u00eddica. Foi transformar o processo num julgamento pol\u00edtico, como se estivesse diante de um tribunal de exce\u00e7\u00e3o, o que n\u00e3o \u00e9 o caso. Mas essa \u00e9 a narrativa constru\u00edda pelo petista e seus aliados. Vamos supor que tenham \u00eaxito, que Lula seja absolvido. Neste caso, o que estar\u00e1 em quest\u00e3o n\u00e3o \u00e9 o recebimento de propina e oculta\u00e7\u00e3o de patrim\u00f4nio, \u00e9 o conjunto da obra. A absolvi\u00e7\u00e3o de Lula, nessas circunst\u00e2ncias, seria a desmoraliza\u00e7\u00e3o do juiz federal S\u00e9rgio Moro e da Lava-Jato. E uma bandeira que poderia torn\u00e1-lo, a\u00ed sim, imbat\u00edvel nas elei\u00e7\u00f5es de 2018. A anula\u00e7\u00e3o da senten\u00e7a de Moro seria o melhor marketing eleitoral de sua candidatura.<\/p>\n<p>A campanha em defesa do ex-presidente Lula n\u00e3o tem nada a ver com o processo em si, tem a ver com o seu projeto pol\u00edtico e ideol\u00f3gico. A defesa de Lula pelos militantes petistas e seus aliados \u00e9 uma demonstra\u00e7\u00e3o de fidelidade ao l\u00edder carism\u00e1tico e de desejo de voltar ao poder para um ajuste de contas, que j\u00e1 foi diversas vezes reiterado pelo pr\u00f3prio petista. Qual \u00e9 o projeto anunciado: controlar os meios de comunica\u00e7\u00e3o, subjugar o Judici\u00e1rio, acabar com a Opera\u00e7\u00e3o Lava-Jato e alterar os mecanismos de promo\u00e7\u00e3o das For\u00e7as Armadas, para control\u00e1-las. N\u00e3o h\u00e1 novidade nisso, foi tentado, por\u00e9m, n\u00e3o havia uma correla\u00e7\u00e3o de for\u00e7as favor\u00e1vel.<\/p>\n<p><strong>Conjunto da obra<\/strong><br \/>\nSer\u00e1 que agora essa correla\u00e7\u00e3o de for\u00e7as j\u00e1 existe? Mesmo com Lula \u00e0 frente nas pesquisas eleitorais, ainda n\u00e3o. Mas a politiza\u00e7\u00e3o do julgamento pode ser um largo passo \u00e0 frente nessa dire\u00e7\u00e3o, porque \u00e9 uma aposta na radicaliza\u00e7\u00e3o pol\u00edtica e no confronto com setores que defendem a candidatura de Jair Bolsonaro (PSL). N\u00e3o \u00e9 \u00e0 toa que os petistas sa\u00edram do estado de letargia em que estavam desde o impeachment de Dilma Rousseff e hoje voltaram \u00e0s ruas, com suas velhas bandeiras e uma indisfar\u00e7\u00e1vel face \u201cbolivariana\u201d.<\/p>\n<p>Ao contr\u00e1rio do que muitos imaginam, Lula n\u00e3o est\u00e1 isolado. O mundo pol\u00edtico est\u00e1 traumatizado pela Lava-Jato. Cenas como a do ex-governador S\u00e9rgio Cabral algemado pelos p\u00e9s e pelas m\u00e3os, dentro de um cambur\u00e3o, tiram o sono de qualquer pol\u00edtico denunciado, com risco de perder o mandato. Por isso mesmo, esse tipo de humilha\u00e7\u00e3o de prisioneiro pode agradar a opini\u00e3o p\u00fablica, mas fortalece e unifica as for\u00e7as que se op\u00f5em \u00e0 Lava-Jato.<\/p>\n<p>O processo de Lula gera sentimentos contradit\u00f3rios entre seus advers\u00e1rios pol\u00edticos. Sua condena\u00e7\u00e3o ser\u00e1 um sinal de que todos, cedo ou tarde, ser\u00e3o julgados e condenados se houver provas suficientes; sua absolvi\u00e7\u00e3o, um sinal de que o vento mudou e a Lava-Jato bateu no teto. O que est\u00e1 em jogo no julgamento de Porto Alegre \u00e9 o futuro da democracia no Brasil. Por essa raz\u00e3o, \u00e9 mais importante discutir o conjunto da obra e deixar o julgamento da materialidade das provas para os ju\u00edzes. Essa \u00e9 a discuss\u00e3o a ser feita caso Lula seja condenado ou absolvido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O julgamento do ex-presidente Luiz In\u00e1cio Lula da Silva \u00e9 criminal, n\u00e3o \u00e9 pol\u00edtico. Se fosse pol\u00edtico, seria pelo conjunto da obra; mas, n\u00e3o, \u00e9 um caso espec\u00edfico, envolvendo o tr\u00edplex de Guaruj\u00e1 A maior surpresa poss\u00edvel no julgamento do recurso do Luiz In\u00e1cio Lula da Silva pelo Tribunal Regional Federal da 4\u00aa Regi\u00e3o (TRF-4) hoje, em Porto Alegre, ser\u00e1 [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,22,5,3],"tags":[67,34],"class_list":["post-2322","post","type-post","status-publish","format-standard","hentry","category-eleicoes","category-impeachment","category-lava-jato","category-politica","tag-eleicoes2018","tag-lavajato"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=2322"}],"version-history":[{"count":5,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2322\/revisions"}],"predecessor-version":[{"id":2330,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2322\/revisions\/2330"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=2322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=2322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=2322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}