{"id":2313,"date":"2018-01-21T10:25:18","date_gmt":"2018-01-21T12:25:18","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=2313"},"modified":"2018-01-21T15:55:00","modified_gmt":"2018-01-21T17:55:00","slug":"nas-entrelinhas-por-que-somos-assim","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-por-que-somos-assim\/","title":{"rendered":"Nas entrelinhas:  Por que somos assim?"},"content":{"rendered":"<p><em>Nada indica que a renova\u00e7\u00e3o dos nossos costumes pol\u00edticos ocorrer\u00e1 com a implos\u00e3o dos atuais partidos ou seu colapso nas elei\u00e7\u00f5es, por causa das elei\u00e7\u00f5es proporcionais e regionais<\/em><\/p>\n<p>Ao contr\u00e1rio do que aparenta a pol\u00edtica brasileira, na qual a \u201ctransa\u201d substituiu os projetos, o Brasil \u00e9 fruto das ideias. Elas antecederam o Estado e a na\u00e7\u00e3o, antes mesmo do descobrimento. E n\u00e3o h\u00e1 nenhum momento relevante da nossa hist\u00f3ria que n\u00e3o tenha resultado de um projeto ambicioso ou mesmo de um devaneio. Bras\u00edlia, por exemplo. A crise que estamos vivendo na pol\u00edtica brasileira \u00e9 resultado da falta de ideias? Ou ser\u00e1 fruto de um ajuste de contas entre uma esp\u00e9cie de novo \u201camericanismo\u201d, emergente no Judici\u00e1rio, e o velho \u201ciberismo\u201d predominante no Executivo e no Legislativo?<\/p>\n<p>Pode ser que sim. Mas a crise, indiscutivelmente, \u00e9 coadjuvada por fen\u00f4menos que modificaram a face do Brasil e sua rela\u00e7\u00e3o com o mundo. A urbaniza\u00e7\u00e3o acelerada e a globaliza\u00e7\u00e3o, respectivamente, ocorreram sem que o pa\u00eds estivesse preparado pol\u00edtica e culturalmente para isso. Ao mesmo tempo em que transitaram da taipa para a alvenaria, as favelas e periferias s\u00e3o sendo plugadas pela revolu\u00e7\u00e3o tecnol\u00f3gica em curso, na qual a velocidade da comunica\u00e7\u00e3o e das inova\u00e7\u00f5es entre em choque com velhas estruturas e institui\u00e7\u00f5es.<\/p>\n<p>O livro Brasil, brasileiros. Por que somos assim? (Editora Verbena\/Funda\u00e7\u00e3o Astrojildo Pereira), uma colet\u00e2nea de artigos e ensaios organizada por Cristovam Buarque, Francisco Almeida e Zander Navarro, lan\u00e7a luzes sobre o momento que vivemos. Re\u00fane textos de Alberto Aggio, Augusto de Franco, Bol\u00edvar Lamounier, Cristovam Buarque, Fl\u00e1vio R. Kothe, John W Garrison II, Jos\u00e9 de Souza Martins, Loreley Garcia, Lourdes Sola, Lu\u00eds Mir, Marco Aur\u00e9lio Nogueira, Marcus Andr\u00e9 Mello, M\u00e9cio Pereira Gomes, Paulo Cesar Nascimento, Socorro Ferraz e pr\u00f3prio Zander Navarro.<\/p>\n<p>Esse grupo de historiadores, cientistas pol\u00edticos e antrop\u00f3logos realiza um esfor\u00e7o de interpreta\u00e7\u00e3o da crise atual, na qual se registra um \u201cdeficit brutal de consenso e intelig\u00eancia cr\u00edtica\u201d, nas palavras de Nogueira. Ser\u00e1 que o brasileiro \u201cperdeu a guerra para si mesmo\u201d, como afirma Fl\u00e1vio Kothe, ao ressaltar que fomos incapazes de p\u00f4r para funcionar o nosso aparelho de estado e a economia? Talvez uma das chaves para compreens\u00e3o de tudo isso esteja na evolu\u00e7\u00e3o do nosso pensamento pol\u00edtico.<\/p>\n<p>O professor Francisco Weffort, em seu livro Forma\u00e7\u00e3o do pensamento pol\u00edtico brasileiro, destaca: primeiro, nos prim\u00f3rdios da coloniza\u00e7\u00e3o a meados do Imp\u00e9rio, nossos intelectuais e as elites n\u00e3o reconheciam a exist\u00eancia do povo como um ator do processo; segundo, a emerg\u00eancia tardia do Estado, que somente ocorre a partir da chegada de dom Jo\u00e3o VI e da Independ\u00eancia; terceiro, uma forte heran\u00e7a medieval, que mistura os aspectos sociais, culturais, econ\u00f4micos e pol\u00edticos da nossa realidade. N\u00e3o \u00e9 \u00e0 toa que as marcas registradas do nosso \u201ciberismo\u201d s\u00e3o o patrimonialismo e o \u201csebastianismo\u201d.<\/p>\n<p><strong>Longas transi\u00e7\u00f5es<\/strong><br \/>\nFoi apenas na Segunda Rep\u00fablica, a partir dos anos 1920 e 1930, que resolvemos as velhas d\u00favidas sobre a exist\u00eancia do povo e da sociedade. Tr\u00eas s\u00e9culos de col\u00f4nia, um s\u00e9culo de Imp\u00e9rio e meio s\u00e9culo de rep\u00fablica agr\u00e1ria antecederam 50 anos de moderniza\u00e7\u00e3o, industrializa\u00e7\u00e3o, urbaniza\u00e7\u00e3o, expans\u00e3o da educa\u00e7\u00e3o e cria\u00e7\u00e3o das universidades aceleradas. Para isso, foram decisivas ideias de homens como Ant\u00f4nio Vieira, Jos\u00e9 Bonif\u00e1cio, Joaquim Nabuco, Euclides da Cunha, Oliveira Viana, Gilberto Freyre, Caio Prado Junior, H\u00e9lio Jaguaribe e Roberto Campos. Sem eles, n\u00e3o ter\u00edamos as institui\u00e7\u00f5es pol\u00edticas que deram sustenta\u00e7\u00e3o a tudo isso, com todas as suas vicissitudes, nem pol\u00edticos que ainda hoje influenciam o comportamento da nossa elite pol\u00edtica, como Marques de Paran\u00e1, Rio Branco, Rui Barbosa, Get\u00falio Vargas, Juscelino Kubitschek e Tancredo Neves.<\/p>\n<p>\u00c9 preciso lan\u00e7ar um olhar para a hist\u00f3ria para compreender as mudan\u00e7as no Brasil. A aboli\u00e7\u00e3o da escravatura foi um ciclo longo, da proibi\u00e7\u00e3o do tr\u00e1fico (1850) \u00e0 Lei \u00c1urea (1888). Se desconsiderarmos a abertura de Ernesto Geisel, em 1974, a recente transi\u00e7\u00e3o \u00e0 democracia come\u00e7ou com a anistia, em 1979, e somente se completou com a elei\u00e7\u00e3o de Collor de Mello (1989). Todas as rupturas modernizantes no Brasil, por\u00e9m, se deram de forma golpista e autorit\u00e1ria (1889, 1930, 1964).<\/p>\n<p>Por causa das regras das elei\u00e7\u00f5es proporcionais, nada indica que a renova\u00e7\u00e3o dos nossos costumes pol\u00edticos ocorrer\u00e1 com a implos\u00e3o dos atuais partidos ou seu colapso nas elei\u00e7\u00f5es; se houver um estouro de boiada, ser\u00e1 em elei\u00e7\u00f5es majorit\u00e1rias, seja para presidente da Rep\u00fablica, ou seja em alguns estados. A presen\u00e7a das redes sociais \u00e9 um terreno em que predominam pensamentos radicais e as fake news, como nos revela a excelente s\u00e9rie de reportagens de Leonardo Cavalcanti, editor de Pol\u00edtica do Correio.<\/p>\n<p>Esses e outros temas ser\u00e3o objeto de um debate imperd\u00edvel entre o senador Cristovam Buarque (PPS-DF), ex-governador de Bras\u00edlia, um dos autores citados, e o professor de Hist\u00f3ria Contempor\u00e2nea Francisco Jos\u00e9 Barbosa, da Universidade de Bras\u00edlia, na pr\u00f3xima ter\u00e7a-feira, a partir das 18h30, com media\u00e7\u00e3o do jornalista Francisco Almeida. Local: audit\u00f3rio da Biblioteca Salom\u00e3o Malina, no Conic (em frente \u00e0 Pra\u00e7a Vermelha), no Setor de Divers\u00f5es Norte, em Bras\u00edlia. Haver\u00e1 sess\u00e3o de aut\u00f3grafos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nada indica que a renova\u00e7\u00e3o dos nossos costumes pol\u00edticos ocorrer\u00e1 com a implos\u00e3o dos atuais partidos ou seu colapso nas elei\u00e7\u00f5es, por causa das elei\u00e7\u00f5es proporcionais e regionais Ao contr\u00e1rio do que aparenta a pol\u00edtica brasileira, na qual a \u201ctransa\u201d substituiu os projetos, o Brasil \u00e9 fruto das ideias. Elas antecederam o Estado e a na\u00e7\u00e3o, antes mesmo do descobrimento. [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,46,4,7,113,8,3],"tags":[67,90],"class_list":["post-2313","post","type-post","status-publish","format-standard","hentry","category-congresso","category-eleicoes","category-governo","category-justica","category-militares","category-partidos","category-politica","tag-eleicoes2018","tag-reformas"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=2313"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2313\/revisions"}],"predecessor-version":[{"id":2320,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2313\/revisions\/2320"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=2313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=2313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=2313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}