{"id":2279,"date":"2018-01-10T10:47:43","date_gmt":"2018-01-10T12:47:43","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=2279"},"modified":"2018-01-10T10:47:43","modified_gmt":"2018-01-10T12:47:43","slug":"nas-entrelinhas-espinhos-do-recesso","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-espinhos-do-recesso\/","title":{"rendered":"Nas entrelinhas: Espinhos do recesso"},"content":{"rendered":"<p><em>uma mudan\u00e7a trivial na composi\u00e7\u00e3o do minist\u00e9rio tem todos os ingredientes de uma grande trapalhada, na qual o erro de conceito foi a escolha de nomes que n\u00e3o t\u00eam nada a ver com o mundo do trabalho<\/em><\/p>\n<p>O que era para ser uma rosa nos jardins do presidente Michel Temer, cujo minist\u00e9rio tem uma car\u00eancia cr\u00f4nica de integrantes do sexo feminino, perdoem-me os mestres N\u00e9lson Cavaquinho, Guilherme de Brito e Alcides Caminha pelo trocadilho, virou um tremendo espinho entre as flores do recesso. A eventual ministra do Trabalho, Cristiane Brasil (PTB-RJ), filha do presidente do PTB, Roberto Jefferson, foi duas vezes impedida de tomar posse pela Justi\u00e7a Federal, em primeira e segunda inst\u00e2ncias, e corre o s\u00e9rio risco de ser mais uma vez impedida pelo Supremo Tribunal Federal (STF).<\/p>\n<p>Dois ex-motoristas contratados sem carteira assinada, uma condena\u00e7\u00e3o na Justi\u00e7a trabalhista no valor de R$ 60 mil, uma funcion\u00e1ria laranja e um advogado carne de pesco\u00e7o que resolveu fazer esc\u00e2ndalo com o caso est\u00e3o inviabilizando a posse da deputada fluminense, que tamb\u00e9m decidiu pagar pra ver e n\u00e3o pretende desistir do cargo. O que parecia ser uma mudan\u00e7a trivial na composi\u00e7\u00e3o do minist\u00e9rio, desde a sa\u00edda do antigo titular, Ronaldo Nogueira (PTB-RS), tem todos os ingredientes de uma grande trapalhada pol\u00edtica, na qual o erro de conceito foi a escolha de nomes que n\u00e3o t\u00eam nada a ver com o mundo do trabalho.<\/p>\n<p>A primeira trapalhada foi a indica\u00e7\u00e3o do deputado Pedro Fernandes (MA), pelo l\u00edder da bancada na C\u00e2mara, Jovair Arantes (GO), que acabou vetado pelo ex-presidente Jos\u00e9 Sarney porque \u00e9 ligado ao governador do Maranh\u00e3o, Fl\u00e1vio Dino (PCdoB), o principal advers\u00e1rio do velho cl\u00e3 pol\u00edtico maranhense. Roberto Jefferson aproveitou a situa\u00e7\u00e3o e emplacou a filha, que estava com a posse marcada, mas um juiz federal de Niter\u00f3i resolveu aceitar uma a\u00e7\u00e3o popular e suspendeu a posse, com o argumento de que a conduta patronal de Cristiane n\u00e3o era compat\u00edvel com o cargo.<\/p>\n<p>O governo recorreu da decis\u00e3o, mas perdeu a liminar no Tribunal Regional Federal da 2\u00aa Regi\u00e3o, com sede no Rio de Janeiro. J\u00e1 era para a deputada ter jogado a toalha, ou o presidente da Rep\u00fablica desistir da nomea\u00e7\u00e3o, mas n\u00e3o \u00e9 o que acontece no governo. O Pal\u00e1cio do Planalto \u00e9 devedor da solidariedade dos aliados nas vota\u00e7\u00f5es da C\u00e2mara para barrar duas den\u00fancias do ex-procurador da Rep\u00fablica Rodrigo Janot contra o presidente Temer e os ministros da Casa Civil, Eliseu Padilha, e da Secretaria-geral da Presid\u00eancia, Moreira Franco.<\/p>\n<p>Um dos credores \u00e9 o ex-deputado Roberto Jefferson, um pol\u00edtico bom de briga, que n\u00e3o leva desaforo para casa e se tornou ainda mais temido depois que denunciou a exist\u00eancia do mensal\u00e3o no primeiro mandato do ex-presidente Luiz In\u00e1cio Lula da Silva. Na ocasi\u00e3o, derrubou do cargo o ent\u00e3o poderoso ministro-chefe da Casa Civil, Jos\u00e9 Dirceu. Naquela crise, ambos foram cassados; depois, condenados, no julgamento do mensal\u00e3o, pelo Supremo Tribunal Federal (STF). A op\u00e7\u00e3o do governo \u00e9 empurrar a situa\u00e7\u00e3o com a barriga, na esperan\u00e7a de que o PTB acabe por indicar outro nome para a pasta.<\/p>\n<p>Esse \u00e9 mais um contencioso envolvendo a Justi\u00e7a Federal, o Congresso e o Executivo. E reacendeu a pol\u00eamica sobre a atua\u00e7\u00e3o de procuradores e ju\u00edzes federais. Forma-se entre os pol\u00edticos uma opini\u00e3o majorit\u00e1ria de que haveria uma \u201ccruzada\u201d contra os demais poderes, de vi\u00e9s autorit\u00e1rio e moralista, nos moldes do movimento tenentista da d\u00e9cada de 1920 contra a Rep\u00fablica Velha, que desaguou na Revolu\u00e7\u00e3o de 1930 e na ditadura de Get\u00falio Vargas. Os \u201ctenentes de toga\u201d, em contrapartida, denunciam a exist\u00eancia de uma ampla coaliz\u00e3o de pol\u00edticos enrolados na Justi\u00e7a para acabar com a Opera\u00e7\u00e3o Lava-Jato.<\/p>\n<p><strong>Embrapa<\/strong><\/p>\n<p>A Empresa Brasileira de Pesquisa Agropecu\u00e1ria (Embrapa) enfrenta sua maior crise, denunciada pelo pesquisador Zander Navarro, que questionou os rumos da empresa de pesquisa agr\u00edcola, que est\u00e1 perdendo o bonde da revolu\u00e7\u00e3o tecnol\u00f3gica em curso no agroneg\u00f3cio. Estudos recentes mostram que ser\u00e1 necess\u00e1rio aumentar em 60% a produ\u00e7\u00e3o de alimentos em todo o mundo nos pr\u00f3ximos 40 anos sem a amplia\u00e7\u00e3o da \u00e1rea cultiv\u00e1vel. E o Brasil corre o risco de perder a condi\u00e7\u00e3o estrat\u00e9gica que ocupa na cadeia global de produ\u00e7\u00e3o de alimentos.<\/p>\n<p>O presidente da Embrapa, Maur\u00edcio Lopes, incomodado com a repercuss\u00e3o de um artigo publicado pelo pesquisador, resolveu demiti-lo sumariamente. A decis\u00e3o provocou forte rea\u00e7\u00e3o entre os secret\u00e1rios de agricultura de diversos estados, entre os quais os de S\u00e3o Paulo, Arnaldo Jardim, e do Esp\u00edrito Santo, Octaciano Neto, que entraram na briga e resolveram dar continuidade ao debate p\u00fablico sobre a linha de atua\u00e7\u00e3o da Embrapa. Soci\u00f3logo, Navarro \u00e9 um dos principais especialistas em assuntos agr\u00e1rios do pa\u00eds, reconhecido internacionalmente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>uma mudan\u00e7a trivial na composi\u00e7\u00e3o do minist\u00e9rio tem todos os ingredientes de uma grande trapalhada, na qual o erro de conceito foi a escolha de nomes que n\u00e3o t\u00eam nada a ver com o mundo do trabalho O que era para ser uma rosa nos jardins do presidente Michel Temer, cujo minist\u00e9rio tem uma car\u00eancia cr\u00f4nica de integrantes do sexo [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,4,7,8,3,48],"tags":[27,95],"class_list":["post-2279","post","type-post","status-publish","format-standard","hentry","category-congresso","category-governo","category-justica","category-partidos","category-politica","category-trabalho","tag-governotemer","tag-trabalho"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=2279"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2279\/revisions"}],"predecessor-version":[{"id":2285,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2279\/revisions\/2285"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=2279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=2279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=2279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}