{"id":2108,"date":"2017-11-14T10:13:30","date_gmt":"2017-11-14T12:13:30","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=2108"},"modified":"2017-11-14T10:13:30","modified_gmt":"2017-11-14T12:13:30","slug":"nas-entrelinhas-temer-e-o-queremismo","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-temer-e-o-queremismo\/","title":{"rendered":"Nas entrelinhas: Temer e o queremismo"},"content":{"rendered":"<p><em> A ideia no Pal\u00e1cio do Planalto \u00e9 reconstituir o governo com base nos aliados que garantiram a rejei\u00e7\u00e3o das duas den\u00fancias do ex-procurador-geral da Rep\u00fablica Rodrigo Janot<\/em><\/p>\n<p>Come\u00e7a a ser urdido nos bastidores do Pal\u00e1cio do Planalto o projeto de reelei\u00e7\u00e3o do presidente Michel Temer, que j\u00e1 se movimenta como quem pretende ser candidato, quando nada para estancar o processo de desagrega\u00e7\u00e3o do seu governo, que se acelerou ontem com o pedido de demiss\u00e3o do ministro das Cidades, Bruno Ara\u00fajo (PSDB-PE). Um dos quatro tucanos no primeiro escal\u00e3o de Temer, o parlamentar pernambucano chegou a anunciar sua sa\u00edda do governo quando foi divulgada a grava\u00e7\u00e3o da conversa comprometedora entre o presidente da Rep\u00fablica e o empres\u00e1rio Joesley Batista, mas voltou atr\u00e1s a pedido do ex-presidente Fernando Henrique Cardoso. Agora, por\u00e9m, saiu para valer.<\/p>\n<p>A tese da candidatura \u00e0 reelei\u00e7\u00e3o vem sendo defendida pelos ministros da Casa Civil, Eliseu Padilha, e da Secretaria-Geral da Presid\u00eancia, Moreira Franco, como uma necessidade para segurar a base do governo e evitar a deriva antecipada de setores do PMDB e outros aliados para a campanha de candidatos da oposi\u00e7\u00e3o, em raz\u00e3o da proximidade das elei\u00e7\u00f5es. Isso j\u00e1 aconteceu com o ex-presidente do Senado Renan Calheiros (PMDB-AL), engajado na campanha do ex-presidente Luiz In\u00e1cio Lula da Silva. N\u00e3o foi \u00e0 toa que o petista alertou o seu partido que os \u201cgolpistas\u201d que o apoiarem nas elei\u00e7\u00f5es de 2018 ser\u00e3o recebidos de bra\u00e7os abertos nos seus palanques regionais.<\/p>\n<p>Temer ainda n\u00e3o se convenceu inteiramente da ideia, mas resolveu fazer um esfor\u00e7o em v\u00e1rias frentes para melhorar a imagem do governo. A propaganda oficial trabalhar\u00e1 em tr\u00eas frentes: primeira, comparar os indicadores econ\u00f4micos de quando assumiu com os do seu primeiro anivers\u00e1rio de governo, que s\u00e3o quase todos excelentes, diante da profunda recess\u00e3o em que o pa\u00eds foi lan\u00e7ado no governo Dilma Rousseff; segunda, a manuten\u00e7\u00e3o dos programas sociais do governo, como o Minha Casa, Minha Vida e o Bolsa Fam\u00edlia, que ser\u00e1 reajustado acima da infla\u00e7\u00e3o, conforme anunciou ontem o ministro do Desenvolvimento Social, Osmar Terra; terceira, a reforma da Previd\u00eancia, que Temer voltou a defender, convencido de que enfrentar as corpora\u00e7\u00f5es aumentar\u00e1 sua popularidade e criar\u00e1 condi\u00e7\u00f5es de o pa\u00eds crescer a taxas acima de 3% no pr\u00f3ximo ano, na avalia\u00e7\u00e3o de seus estrategistas, a premissa para o projeto eleitoral dar certo.<\/p>\n<p>A tese audaciosa ganhou mais for\u00e7a com o desembarque do PSDB do governo, que estava previsto para a conven\u00e7\u00e3o de 9 de dezembro, mas acabou antecipado por Bruno Ara\u00fajo. Temer n\u00e3o pretende esperar a deser\u00e7\u00e3o dos aliados para fazer a reforma ministerial. A ideia no Pal\u00e1cio do Planalto \u00e9 reconstituir o governo com base nos aliados que garantiram a rejei\u00e7\u00e3o das duas den\u00fancias do ex-procurador-geral da Rep\u00fablica Rodrigo Janot. Temer obteve apenas 240 votos na vota\u00e7\u00e3o, o suficiente para blind\u00e1-lo constitucionalmente, mas n\u00e3o para aprovar as reformas. Acontece que a reforma da Previd\u00eancia \u00e9 uma bandeira dos aliados que est\u00e3o deixando o governo, o que permitiria atender a base fisiol\u00f3gica que barganha mais cargos no governo para aprov\u00e1-la e, ao mesmo tempo, tamb\u00e9m negociar com os tucanos e outros aliados que deixaram o governo.<\/p>\n<p>Um dos argumentos para convencer Temer a concorrer \u00e0s elei\u00e7\u00f5es de 2018 \u00e9 o fato de que o ex-presidente Jos\u00e9 Sarney, em 1989, virou saco de pancadas de todos os candidatos e n\u00e3o teve como se defender porque n\u00e3o disputava a reelei\u00e7\u00e3o. O pr\u00f3prio Sarney costuma avaliar que o governo, na pior das hip\u00f3teses, garantiria de 15 a 20% dos votos do primeiro turno para seu candidato. Temer teria oportunidade de se defender e capitalizar suas realiza\u00e7\u00f5es. N\u00e3o \u00e9 uma ideia sem sentido, em raz\u00e3o do tempo de televis\u00e3o e dos recursos do fundo partid\u00e1rio do PMDB, que teria, al\u00e9m do peso da m\u00e1quina do governo a seu favor, grande capilaridade nos grot\u00f5es do pa\u00eds.<\/p>\n<p><strong>N\u00e3o colou<\/strong><\/p>\n<p>Mas sempre \u00e9 bom lembrar o risco de a proposta n\u00e3o colar, como aconteceu com o movimento Queremista em 1945, cujo objetivo era defender a perman\u00eancia de Get\u00falio Vargas na Presid\u00eancia da Rep\u00fablica. O nome se originou do slogan utilizado pelo movimento: \u201cQueremos Get\u00falio\u201d. Naquela \u00e9poca, diante do esgotamento da ditadura do Estado Novo e do fim da II Guerra Mundial, as for\u00e7as pol\u00edticas que haviam se oposto ao regime iniciaram o ano reivindicando a redemocratiza\u00e7\u00e3o do pa\u00eds. Pressionado, Vargas comprometeu-se a realizar elei\u00e7\u00f5es e manteve-se numa posi\u00e7\u00e3o d\u00fabia em rela\u00e7\u00e3o \u00e0 possibilidade de se candidatar.<\/p>\n<p>No fim de outubro, quando Vargas tentou substituir o chefe de Pol\u00edcia do Distrito Federal, Jo\u00e3o Alberto Lins de Barros, por Benjamin Vargas, seu irm\u00e3o, a manobra acabou interpretada por seus advers\u00e1rios como um golpe para preparar a continuidade no poder. No dia 29, o alto comando do Ex\u00e9rcito, tendo \u00e0 frente o ministro da Guerra, general G\u00f3es Monteiro, dep\u00f4s Vargas da presid\u00eancia, que em seguida foi entregue ao presidente do Supremo Tribunal Federal, Jos\u00e9 Linhares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ideia no Pal\u00e1cio do Planalto \u00e9 reconstituir o governo com base nos aliados que garantiram a rejei\u00e7\u00e3o das duas den\u00fancias do ex-procurador-geral da Rep\u00fablica Rodrigo Janot Come\u00e7a a ser urdido nos bastidores do Pal\u00e1cio do Planalto o projeto de reelei\u00e7\u00e3o do presidente Michel Temer, que j\u00e1 se movimenta como quem pretende ser candidato, quando nada para estancar o processo [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36,46,4,3,9],"tags":[67,27,90],"class_list":["post-2108","post","type-post","status-publish","format-standard","hentry","category-economia","category-eleicoes","category-governo","category-politica","category-politica-2","tag-eleicoes2018","tag-governotemer","tag-reformas"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=2108"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2108\/revisions"}],"predecessor-version":[{"id":2115,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/2108\/revisions\/2115"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=2108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=2108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=2108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}