{"id":1468,"date":"2017-04-06T06:51:09","date_gmt":"2017-04-06T09:51:09","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=1468"},"modified":"2017-04-06T06:51:09","modified_gmt":"2017-04-06T09:51:09","slug":"nas-entrelinhas-primeira-fissura","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-primeira-fissura\/","title":{"rendered":"Nas entrelinhas: Primeira fissura"},"content":{"rendered":"<p><em>Renan tem poder para emparedar as reformas que forem aprovadas na C\u00e2mara. A simples altera\u00e7\u00e3o pelo Senado faz o processo dar um largo passo atr\u00e1s<\/em><\/p>\n<p>Surgem as primeiras grandes fissuras na base do governo Temer, a principal delas no Senado, encabe\u00e7ada pelo l\u00edder da bancada do PMDB, Renan Calheiros (AL), que assumiu uma clara dissid\u00eancia em rela\u00e7\u00e3o \u00e0 orienta\u00e7\u00e3o do governo. Renan \u00e9 um sobrevivente de todos os governos, desde o de Fernando Collor, que o revelou para a pol\u00edtica nacional. \u00c9 um \u00e1s da baldea\u00e7\u00e3o: carregou o caix\u00e3o de Dilma Rousseff at\u00e9 a porta do cemit\u00e9rio. Considerado um dos melhores estrategistas do Senado, ao lado de Jader Barbalho (PMDB-PA), que atua na surdina, seu desembarque do governo \u00e9 iminente e perigoso.<\/p>\n<p>Na manh\u00e3 de ontem, Renan criticou mais uma vez a condu\u00e7\u00e3o dada ao pa\u00eds pelo presidente Temer, o qual acusou de n\u00e3o ouvir ningu\u00e9m, o que n\u00e3o \u00e9 verdade. O presidente da Rep\u00fablica ouve pelo menos tr\u00eas integrantes da equipe de governo, o ministro da Fazenda, Henrique Meirelles, e os ministros da Casa Civil, Eliseu Padilha, e da secretaria de Governo, Moreira Franco, al\u00e9m de Rodrigo Maia, presidente da C\u00e2mara, e Romero Juc\u00e1, presidente do PMDB e l\u00edder do governo, que disputa influ\u00eancia no Senado com o l\u00edder da bancada.<\/p>\n<p>Renan fez ontem uma compara\u00e7\u00e3o de Temer com a ex-presidente Dilma: \u201cE a impress\u00e3o de agora, com o presidente Michel, \u00e9 que com essa pol\u00edtica econ\u00f4mica, com esse aumento de imposto, com essa renega\u00e7\u00e3o da folha, com tudo isso, parece que, diferentemente da Dilma, que n\u00e3o sabia o que fazer, o Michel n\u00e3o tem o que fazer. E isso \u00e9 pior para o Brasil\u201d, disparou. E voltou a atacar a reforma da Previd\u00eancia: \u201cUma reforma da banca, querendo arrecadar R$ 780 bilh\u00f5es em 10 anos. Tem que fazer uma reforma da Previd\u00eancia ideal\u201d.<\/p>\n<p>Ao atacar a pol\u00edtica econ\u00f4mica deu uma pista do verdadeiro alvo: \u201cO governo est\u00e1 errando ao querer resolver a crise econ\u00f4mica, colocar a infla\u00e7\u00e3o na meta com mais recess\u00e3o. Isso \u00e9 um horror. Isso vai levar o pa\u00eds, em um curt\u00edssimo espa\u00e7o de tempo, infelizmente, a uma crise maior\u201d. O problema de Renan \u00e9 a negocia\u00e7\u00e3o da d\u00edvida dos estados, em aprecia\u00e7\u00e3o na C\u00e2mara, que est\u00e1 sendo conduzida pelo ministro da Fazenda. Quer flexibilizar o acordo com os estados para favorecer o governo de Renan Calheiros Filho (PMDB), em Alagoas, candidato \u00e0 reelei\u00e7\u00e3o junto com o pai.<\/p>\n<p>Outro ator importante no jogo parece se manter ao largo da disputa, o presidente do Senado, Eun\u00edcio de Oliveira (PMDB-CE), que tem boas rela\u00e7\u00f5es com Temer, mas jamais seria eleito para o posto que ocupa sem o apoio de Renan. Eun\u00edcio costuma virar uma esfinge nessas horas e esperar o vento firmar para escolher o rumo a seguir. Somente assume uma posi\u00e7\u00e3o mais agressiva quando se sente amea\u00e7ado. Todos est\u00e3o citados nas dela\u00e7\u00f5es premiadas da Opera\u00e7\u00e3o Lava-Jato, o que aumenta o estresse entre eles.<\/p>\n<p>Temer j\u00e1 passou por muitas disputas com Renan, que inclusive tentou remov\u00ea-lo da presid\u00eancia do PMDB. \u00c9 dispens\u00e1vel dizer quem foi que at\u00e9 agora riu por \u00faltimo. Quando parecia na imin\u00eancia de ser derrotado dentro da legenda, Temer fez um acordo com os deputados do PT, foi eleito presidente da C\u00e2mara e, depois, vice-presidente da Rep\u00fablica na chapa de Dilma Rousseff, em 2010. Hoje, \u00e9 o presidente da Rep\u00fablica, depois de romper com Dilma Rousseff e atrair o apoio de Renan.<\/p>\n<p>A recidiva dessa velha disputa, por\u00e9m, pode desestabilizar o governo. Renan tem poder para emparedar as reformas que forem aprovadas na C\u00e2mara. A simples altera\u00e7\u00e3o pelo Senado do que foi aprovado pelos deputados faz o processo dar um largo passo atr\u00e1s. Al\u00e9m disso, caso Renan consiga manter a bancada de senadores do PMDB coesa, dificilmente isso n\u00e3o dividir\u00e1 a bancada de deputados. N\u00e3o \u00e9 \u00e0 toa que o Pal\u00e1cio do Planalto preferiu n\u00e3o alimentar a pol\u00eamica. A op\u00e7\u00e3o foi correr com a vota\u00e7\u00e3o do acordo das d\u00edvidas dos estados na C\u00e2mara.<\/p>\n<p><strong>A renegocia\u00e7\u00e3o<\/strong><br \/>\nEsse assunto vem se arrastando desde o ano passado, quando os deputados retiraram as contrapartidas do projeto original do Minist\u00e9rio da Fazenda, sob forte press\u00e3o dos governadores. Temer enviou um novo texto para socorrer os estados em situa\u00e7\u00e3o mais dram\u00e1tica, principalmente Rio de Janeiro e o Rio Grande do Sul. H\u00e1 duas semanas, uma batalha surda se desenvolve entre a equipe econ\u00f4mica e base do governo na C\u00e2mara para votar o projeto.<\/p>\n<p>Para renegociar as d\u00edvidas, a Fazenda quer que o acordo autorize a privatiza\u00e7\u00e3o de empresas dos setores financeiro, de energia e de saneamento para quitar d\u00edvidas, como j\u00e1 aconteceu com a Cedae, no Rio de Janeiro; que eleve a al\u00edquota de contribui\u00e7\u00e3o previdenci\u00e1ria dos servidores estaduais; e que reduza incentivos ou benef\u00edcios tribut\u00e1rios. Tudo engui\u00e7a na hora em que o acordo pro\u00edbe estados de conceder vantagem, aumento, reajuste ou adequa\u00e7\u00e3o de sal\u00e1rios a servidores; criar cargos ou fun\u00e7\u00f5es que impliquem aumento de despesa; alterar a estrutura de carreira que gere aumento de gastos; realizar concurso p\u00fablico, ressalvadas hip\u00f3teses de reposi\u00e7\u00e3o de cargos vagos; criar ou aumentar aux\u00edlios, vantagens, b\u00f4nus, abonos ou benef\u00edcios de qualquer natureza. S\u00e3o mat\u00e9rias indigestas para candidatos ao Senado e governadores candidatos \u00e0 reelei\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Renan tem poder para emparedar as reformas que forem aprovadas na C\u00e2mara. A simples altera\u00e7\u00e3o pelo Senado faz o processo dar um largo passo atr\u00e1s Surgem as primeiras grandes fissuras na base do governo Temer, a principal delas no Senado, encabe\u00e7ada pelo l\u00edder da bancada do PMDB, Renan Calheiros (AL), que assumiu uma clara dissid\u00eancia em rela\u00e7\u00e3o \u00e0 orienta\u00e7\u00e3o do [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,4,8,3,87],"tags":[27,14],"class_list":["post-1468","post","type-post","status-publish","format-standard","hentry","category-congresso","category-governo","category-partidos","category-politica","category-previdencia","tag-governotemer","tag-pmdb"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/1468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=1468"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/1468\/revisions"}],"predecessor-version":[{"id":1474,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/1468\/revisions\/1474"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=1468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=1468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=1468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}