{"id":1464,"date":"2017-04-05T08:07:11","date_gmt":"2017-04-05T11:07:11","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=1464"},"modified":"2017-04-05T08:07:11","modified_gmt":"2017-04-05T11:07:11","slug":"nas-entrelinhas-nas-entranhas-do-pt","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-nas-entranhas-do-pt\/","title":{"rendered":"Nas entrelinhas: Nas entranhas do PT"},"content":{"rendered":"<p><em>A Pol\u00edcia Federal e o Minist\u00e9rio P\u00fablico j\u00e1 t\u00eam provas robustas de que a origem do dinheiro era a propina da Petrobras<\/em><\/p>\n<p>O ministro Luiz Edson Fachin, relator da Opera\u00e7\u00e3o Lava-Jato no Supremo Tribunal Federal (STF), homologou ontem o acordo de dela\u00e7\u00e3o premiada do ex-marqueteiro do PT Jo\u00e3o Santana, de sua mulher, M\u00f4nica Moura, e de Andr\u00e9 Luis Reis Santana, funcion\u00e1rio do marqueteiro. Agora, a Procuradoria-Geral da Rep\u00fablica (PGR) pode avan\u00e7ar nas investiga\u00e7\u00f5es sobre as campanhas eleitorais do PT de 2006, 2010 e 2014, nas quais o casal foi pe\u00e7a chave.<\/p>\n<p>Em liberdade provis\u00f3ria, a dela\u00e7\u00e3o premiada do casal \u00e9 mantida em sigilo, mas \u00e9 uma bomba para a c\u00fapula do PT, que, desde o in\u00edcio da Opera\u00e7\u00e3o Lava-Jato, vem sustentando a tese de que toda a campanha foi financiada por \u201cdoa\u00e7\u00f5es legais\u201d. A Pol\u00edcia Federal e o Minist\u00e9rio P\u00fablico, por\u00e9m, j\u00e1 t\u00eam provas robustas de que a origem do dinheiro era a propina da Petrobras e de que parte da campanha foi financiada diretamente pelo caixa dois da Odebrecht. As dela\u00e7\u00f5es premiadas de Marcelo Odebrecht e executivos da empreiteira, por exemplo, corroboram as informa\u00e7\u00f5es.<\/p>\n<p>Santana e M\u00f4nica j\u00e1 haviam sido condenados pelo juiz S\u00e9rgio Moro, mas como o caso agora envolve ministros e parlamentares, est\u00e1 na esfera do Supremo. Marqueteiro nas campanhas de Luiz In\u00e1cio Lula da Silva (2006) e Dilma Rousseff (2010 e 2014), Jo\u00e3o Santana recebeu US$ 3 milh\u00f5es de offshores ligadas \u00e0 Odebrecht, entre 2012 e 2013, e US$ 4,5 milh\u00f5es do engenheiro Zwi Skornicki, entre 2013 e 2014. O dinheiro era oriundo de propina de contratos da Petrobras. Ele e M\u00f4nica confirmaram o recebimento de US$ 4,5 milh\u00f5es do caixa dois da campanha de Dilma em 2010. Mas a quest\u00e3o \u00e9: diante de tudo o que j\u00e1 se sabe, em que o casal pode colaborar com as investiga\u00e7\u00f5es?<\/p>\n<p>A resposta est\u00e1 nas entranhas da campanha, ou seja, na rela\u00e7\u00e3o entre quem mandava e quem pagava, quanto pagava e como pagava. \u00c9 a\u00ed que a situa\u00e7\u00e3o do PT, de Lula e de Dilma pode se complicar ainda mais, como aconteceu, por exemplo, com o PP, que recentemente foi denunciado pela for\u00e7a-tarefa da Lava-Jato, que requereu inclusive a cassa\u00e7\u00e3o do registro do partido. Ao contr\u00e1rio do PMDB e do PSDB, tamb\u00e9m citados nas dela\u00e7\u00f5es premiadas, o PT tinha um centro financeiro que operava o esquema, a tesouraria do partido. Essa centraliza\u00e7\u00e3o j\u00e1 havia sido detectada no esc\u00e2ndalo do mensal\u00e3o, o que resultou na condena\u00e7\u00e3o do ex-tesoureiro Del\u00fabio Soares. E se tornou muito mais sofisticada a partir da campanha de 2010, o que resultou na pris\u00e3o de Jo\u00e3o Vaccari Neto, o ex-tesoureiro flagrado pela Lava-Jato como um dos operadores do esquema de desvio de recursos da Petrobras.<\/p>\n<p>At\u00e9 agora, o PT vinha se blindando das acusa\u00e7\u00f5es porque seus principais operadores do esquema de caixa dois n\u00e3o aceitaram as propostas de dela\u00e7\u00e3o premiada da for\u00e7a-tarefa da Lava-Jato, como o ex-diretor da Petrobras Renato Duque e o pr\u00f3prio ex-tesoureiro Vaccari. As den\u00fancias chegavam apenas aos ex-ministros Antonio Palocci e Guido Mantega, particularmente no caso da dela\u00e7\u00e3o premiada de Marcelo Odebrecht. Todos, sem exce\u00e7\u00e3o, seguiram o padr\u00e3o de Del\u00fabio e Jos\u00e9 Dirceu, que rejeitaram a dela\u00e7\u00e3o premiada. Agiram como aqueles gladiadores romanos quando eram lan\u00e7ados aos le\u00f5es: Ave, Caezar, morituri te salutant (Ave, C\u00e9sar, aqueles que est\u00e3o prestes a morrer o sa\u00fadam).<\/p>\n<p>Blindagem<br \/>\nA senten\u00e7a latina \u00e9 citada na vida dos C\u00e9sares e teria sido usada em 52 d.C., no Lago Furino, na presen\u00e7a de Cl\u00e1udio. O imperador romano teria respondido: \u201cOu n\u00e3o!\u201d. Os C\u00e9sares tinham poder de poupar da morte ou n\u00e3o os gladiadores derrotados na arena, quando eles n\u00e3o eram estra\u00e7alhados pelos le\u00f5es, \u00e9 claro. Os quadros principais do PT envolvidos no esc\u00e2ndalo, mesmo presos e condenados, est\u00e3o se comportando de maneira a proteger o partido e seus principais l\u00edderes, inclusive o ex-presidente Lula. Essa blindagem n\u00e3o havia sido rompida por ningu\u00e9m no cora\u00e7\u00e3o das campanhas eleitorais. As dela\u00e7\u00f5es do marqueteiro da campanha e sua mulher, por\u00e9m, representam um rompimento dessa carca\u00e7a. O que n\u00e3o se sabe ainda \u00e9 at\u00e9 onde isso pode chegar. Ou seja, se Lula e Dilma foram delatados.<\/p>\n<p>Diante das fragilidades do governo de Michel Temer e das dificuldades que enfrenta para concretizar sua agenda de reformas, especialmente a da Previd\u00eancia e trabalhista, o PT parece nadar de bra\u00e7ada. Opera em duas dire\u00e7\u00f5es: numa delas, tece acordos de interesse m\u00fatuo com advers\u00e1rios para aprovar uma reforma pol\u00edtica que facilite a sobreviv\u00eancia da legenda e de seus quadros principais; na outra, lan\u00e7a a candidatura de Lula \u00e0 Presid\u00eancia, antecipando a campanha eleitoral de 2018, para proteg\u00ea-lo das investiga\u00e7\u00f5es da Opera\u00e7\u00e3o Lava-Jato, preservar seu \u201clegado\u201d populista e vitimiz\u00e1-lo perante o juiz federal S\u00e9rgio Moro, de Curitiba, que tem a atribui\u00e7\u00e3o de julg\u00e1-lo em primeira inst\u00e2ncia.<\/p>\n<p>A estrat\u00e9gia do PT est\u00e1 sendo bem-sucedida. Lula parece pinto no lixo, como diria o falecido Jamel\u00e3o, quando vai aos eventos partid\u00e1rios. Os militantes petistas voltaram \u00e0s ruas com suas bandeiras vermelhas, como se o partido passasse uma borracha em tudo o que aconteceu. A expectativa de poder petista \u00e9 proporcional \u00e0 competitividade eleitoral de Lula, essa \u00e9 a verdade. Como elas hoje s\u00e3o razo\u00e1veis, ainda mais porque os tucanos tamb\u00e9m est\u00e3o sendo citados nas dela\u00e7\u00f5es premiadas, a c\u00fapula do partido sufoca as cr\u00edticas internas, ignora as externas e atua como nos velhos tempos de oposi\u00e7\u00e3o ao governo de Fernando Henrique Cardoso. V\u00ea-se a alegria nos olhos dos petistas diante das agruras do atual governo de transi\u00e7\u00e3o. Varreram para debaixo do tapete o que fizeram de errado no governo e nas campanhas presidenciais. Com as dela\u00e7\u00f5es premiadas do casal de marqueteiros Jo\u00e3o Santana e M\u00f4nica Moura, por\u00e9m, tudo pode naufragar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Federal e o Minist\u00e9rio P\u00fablico j\u00e1 t\u00eam provas robustas de que a origem do dinheiro era a propina da Petrobras O ministro Luiz Edson Fachin, relator da Opera\u00e7\u00e3o Lava-Jato no Supremo Tribunal Federal (STF), homologou ontem o acordo de dela\u00e7\u00e3o premiada do ex-marqueteiro do PT Jo\u00e3o Santana, de sua mulher, M\u00f4nica Moura, e de Andr\u00e9 Luis Reis Santana, [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,7,5,8,3],"tags":[34],"class_list":["post-1464","post","type-post","status-publish","format-standard","hentry","category-eleicoes","category-justica","category-lava-jato","category-partidos","category-politica","tag-lavajato"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/1464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=1464"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/1464\/revisions"}],"predecessor-version":[{"id":1470,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/1464\/revisions\/1470"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=1464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=1464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=1464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}