{"id":8090,"date":"2016-08-19T03:28:13","date_gmt":"2016-08-19T06:28:13","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/?p=8090"},"modified":"2016-08-24T08:31:48","modified_gmt":"2016-08-24T11:31:48","slug":"8090-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/8090-2\/","title":{"rendered":"Um fantasma na \u00f3pera"},"content":{"rendered":"<p>DESDE 1960<\/p>\n<p>aricunha@dabr.com.br<\/p>\n<p>com Circe Cunha  com MAMFIL<\/p>\n<p>Cartas, sobretudo aquelas escritas de pr\u00f3prio punho, possuem um poder revelador t\u00e3o fascinante que, analisando o desenho ou um tra\u00e7o de uma simples letra, \u00e9 poss\u00edvel acessar os mais rec\u00f4nditos labirintos da alma do autor. Mais do que revelar o interior de quem escreve, uma carta, quando manuscrita, se converte num documento fidedigno, pois cada linha riscada na folha branca \u00e9 como uma pr\u00f3pria assinatura, lavrada e garantida.<\/p>\n<p>Nesse sentido, a carta de dona Dilma aos senadores e \u00e0 na\u00e7\u00e3o, finalmente tornada p\u00fablica na ter\u00e7a-feira, como missiva, soa totalmente falsa. Nela, nem as pessoas que desfrutam do conv\u00edvio \u00edntimo da presidente reconheceriam nos escritos quem foi o autor de fato. Para muitos, o texto \u00e9 inteiramente de autoria de seu advogado de defesa, Jos\u00e9 Eduardo Cardoso, sendo que a presidente, nesse caso se limitou a ler o que estava \u00e0 sua frente.<\/p>\n<p>Fosse esse um documento manuscrito, apresentando o desenho personalizado de sua letra, mesmo com erros de portugu\u00eas e gram\u00e1tica, a carta exalaria aquele ar de autenticidade. Mais uma vez a presidente abandona o caminho reto da verdade para se embrenhar pela via larga da fal\u00e1cia, levando ao destinat\u00e1rio para uma esp\u00e9cie de areia movedi\u00e7a, onde os fatos e as vers\u00f5es afundam no mesmo terreno. Mais uma vez dona Dilma desperdi\u00e7a a oportunidade de usar a sinceridade. Essa \u00e9 a derradeira chance.<\/p>\n<p>Durante os longos anos em que ocupou os mais destacados cargos p\u00fablicos, em nenhum momento dona Dilma se permitiu mostrar quem realmente \u00e9. Cargos p\u00fablicos s\u00e3o para pessoas que se apresentam cristalinas, sem medo de mostrar o que s\u00e3o, o que pensan e ao que vieram. Entre as coisas p\u00fablicas, numa rep\u00fablica de fato, o que se deveria encontrar, al\u00e9m da total transpar\u00eancia das pessoas ungidas pelos cargos, o respeito irrestrito \u00e0s leis.<\/p>\n<p>De toda forma, a carta ficar\u00e1 com o registro lido pela alegada autora para a posteridade e, no futuro, ser\u00e1 lida e esmiu\u00e7ada por historiadores que, \u00e0 semelhan\u00e7a de arque\u00f3logos e paleont\u00f3logos, buscar\u00e3o entender quem foi realmente o personagem por tr\u00e1s da carta, quais foram suas raz\u00f5es e ang\u00fastias. Pelo que se tem at\u00e9 agora, n\u00e3o d\u00e1 para saber ao certo. Restar\u00e1 aos cidad\u00e3os buscar, por conta pr\u00f3pria, o fantasma escritor por tr\u00e1s das linhas.<\/p>\n<p>Discurso que foi pronunciado:<\/p>\n<p>\u201cAo longo da campanha, anunciei medidas que v\u00e3o ser muito importantes para que a sociedade brasileira enfrente a corrup\u00e7\u00e3o e acabe com a impunidade.\u201d<\/p>\n<p>Discurso de dona Dilma<\/p>\n<p>Criatividade no ar<\/p>\n<p>Jorge Antunes leva para a UnB, na ter\u00e7a-feira, a \u00f3pera de rua Olympia ou Sujadevez, de sua autoria. A apresenta\u00e7\u00e3o est\u00e1 marcada para as 12h30, no Restaurante Universit\u00e1rio, na \u00e1rea voltada para o Minhoc\u00e3o. Coro, solos e orquestra.<\/p>\n<p>Imbr\u00f3glio<\/p>\n<p>Recebemos da Mesa Diretora da CLDF o seguinte esclarecimento: \u201cA Mesa Diretora da C\u00e2mara Legislativa do Distrito Federal esclarece que aprovou Projeto de Emenda Aditiva, proposto pela pr\u00f3pria deputada Liliane Roriz, que destina recursos para a Sa\u00fade. E que os \u00e1udios divulgados, hoje, pela imprensa est\u00e3o evidentemente editados e as conversas est\u00e3o fora de contexto. A Mesa ainda esclarece que os deputados cumpriram com seu dever de legislar, que rejeita qualquer acusa\u00e7\u00e3o de pr\u00e1tica de ato il\u00edcito e que confia nas investiga\u00e7\u00f5es para a apura\u00e7\u00e3o da verdade. Ademais, a deputada Liliane Roriz est\u00e1 sendo investigada pela Mesa Diretora da C\u00e2mara, podendo sofrer a perda do mandato em tr\u00eas processos pela pr\u00e1tica de atos il\u00edcitos e quebra de decoro parlamentar\u201d, encerra a nota.<\/p>\n<p>Desapego &amp; necessidade<\/p>\n<p>Cena comum para os frequentadores de restaurantes em Bras\u00edlia s\u00e3o pessoas necessitadas que pedem dinheiro, vendem flores etc. O Sant\u00e9 13, na 413 Norte, resolveu a situa\u00e7\u00e3o com a campanha: \u201cQuem tem P\u00d5E. Quem n\u00e3o tem PEGA\u201d. Com o apoio da Secretaria do Trabalho, Desenvolvimento Social, Mulheres, Igualdade Racial e Direitos Humanos (Sedestmidh), a proposta funciona da seguinte forma: o restaurante \u00e9 um ponto de troca, que recebe as doa\u00e7\u00f5es de roupas e agasalhos em bom estado e distribui \u00e0s pessoas em situa\u00e7\u00e3o de vulnerabilidade. E o montante arrecadado ao longo de toda a semana tamb\u00e9m ser\u00e1 distribu\u00eddo, \u00e0s sextas-feiras, em uma das institui\u00e7\u00f5es indicadas pela Secretaria. A campanha n\u00e3o tem data para acabar, os organizadores pretendem que a ideia estimule o desapego na popula\u00e7\u00e3o de Bras\u00edlia. \u00c9 s\u00f3 fazer sua parte.<\/p>\n<p>Hist\u00f3ria de Bras\u00edlia<\/p>\n<p>Agora, seja dada a solu\u00e7\u00e3o que bem convier, desde que a nomea\u00e7\u00e3o do prefeito \u00e9 de exclusiva responsabilidade do presidente da Rep\u00fablica. Mas o que o sr. Jo\u00e3o Goulart fizer de bom ou de mau para a capital todos n\u00f3s saberemos conhecer. (Publicado em 13\/9\/1961)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DESDE 1960 aricunha@dabr.com.br com Circe Cunha com MAMFIL Cartas, sobretudo aquelas escritas de pr\u00f3prio punho, possuem um poder revelador t\u00e3o fascinante que, analisando o desenho ou um tra\u00e7o de uma simples letra, \u00e9 poss\u00edvel acessar os mais rec\u00f4nditos labirintos da alma do autor. Mais do que revelar o interior de quem escreve, uma carta, quando manuscrita, se converte num documento [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-8090","post","type-post","status-publish","format-standard","hentry","category-integra"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/8090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=8090"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/8090\/revisions"}],"predecessor-version":[{"id":8092,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/8090\/revisions\/8092"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=8090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=8090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=8090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}