{"id":7741,"date":"2016-05-10T01:23:07","date_gmt":"2016-05-10T04:23:07","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/?p=7741"},"modified":"2016-07-04T05:59:09","modified_gmt":"2016-07-04T08:59:09","slug":"celeiro-de-venenos","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/celeiro-de-venenos\/","title":{"rendered":"Celeiro de venenos"},"content":{"rendered":"<p><i>DESDE 1960<\/i><\/p>\n<p>aricunha@dabr.com.br<\/p>\n<p>com Circe Cunha \/\/ circecunha.df@dabr.com.br com MAMFIL<\/p>\n<p><b>\u00a0<\/b><\/p>\n<p>Quando se fala em produ\u00e7\u00e3o agr\u00edcola, os n\u00fameros apresentados pelo Brasil s\u00e3o verdadeiramente astron\u00f4micos. Para um pa\u00eds de propor\u00e7\u00f5es continentais e que nas \u00faltimas d\u00e9cadas vem expandindo progressivamente suas fronteiras agr\u00edcolas atrav\u00e9s do uso intensivo de maquin\u00e1rio de \u00faltima gera\u00e7\u00e3o, falar em produ\u00e7\u00e3o recorde da safra a cada ano virou lugar-comum.<\/p>\n<p>A safra 2014\/2015 de 209,5 milh\u00f5es de toneladas superou a anterior, crescendo 8,2% e tem sido assim, ano ap\u00f3s ano. Esses dados tamb\u00e9m se repetem no aumento das \u00e1reas abertas \u00e0 agricultura. Hoje, s\u00e3o aproximadamente 60 milh\u00f5es de hectares de \u00e1rea plantada, que se expande cerca de 1% a 1,5 % a cada ano.<\/p>\n<p>Com n\u00fameros dessa magnitude, o pa\u00eds consolida sua posi\u00e7\u00e3o como celeiro do mundo. N\u00e3o \u00e9 por outro motivo tamb\u00e9m que o poder de lobby do setor \u00e9, de longe, o mais o mais poderoso e eficaz de todos, superando a pr\u00f3pria ind\u00fastria. Tendo por tr\u00e1s um imp\u00e9rio com essa for\u00e7a, n\u00e3o \u00e9 de se estranhar que a bancada do agroneg\u00f3cio venha sendo o fiel da balan\u00e7a na maioria das vota\u00e7\u00f5es no Congresso. H\u00e1 quem afirme, inclusive, que foi a retirada do apoio dessa bancada, contrariada em suas pretens\u00f5es por medidas do governo Dilma, que abriu o caminho para o impeachment da presidente.<\/p>\n<p>Portanto, falar em contrariar a turma \u00e9 receita certa para turbul\u00eancia de toda a ordem. Poderosos na produ\u00e7\u00e3o agr\u00edcola e na pol\u00edtica, organizados em um grupo coeso, n\u00e3o espanta que o governo federal, no caso o Minist\u00e9rio da Agricultura, o Minist\u00e9rio do Meio Ambiente e o pr\u00f3prio Minist\u00e9rio da Sa\u00fade, fa\u00e7a vistas grossas. H\u00e1 quem denuncie que at\u00e9 mesmo impede que as fiscaliza\u00e7\u00f5es neste setor se fa\u00e7am como manda a legisla\u00e7\u00e3o.<\/p>\n<p>O desrespeito \u00e0s m\u00ednimas regras do meio ambiente, atrav\u00e9s do assoreamento de rios, de derrubada de mata nativa, da contamina\u00e7\u00e3o do solo e outras infra\u00e7\u00f5es, se esconde por baixo dos n\u00fameros superlativos do setor.<\/p>\n<p>Falar em fiscalizar o setor \u00e9 comprar briga que nenhum governo, de qualquer partido, topa de frente. N\u00e3o \u00e9 por outra raz\u00e3o que dados apresentados a pouco pelo Instituto Nacional do C\u00e2ncer (Inca) mostram que os brasileiros consomem aproximadamente cinco litros de agrot\u00f3xicos variados a cada ano.<\/p>\n<p>Desde 2008, o Brasil ocupa a primeira posi\u00e7\u00e3o no ranking mundial de consumo de agrot\u00f3xicos. Segundo a Anvisa, enquanto nos \u00faltimos 10 anos o mercado desses venenos cresceu 93%, no Brasil esse crescimento foi de 190%.<\/p>\n<p>Entidades como a Abrasco alertam que 70% dos alimentos in natura consumidos no pa\u00eds est\u00e3o fortemente contaminados por agrot\u00f3xicos. Al\u00e9m disso, alerta a pr\u00f3pria Anvisa, 28% desses produtos vendidos ao p\u00fablico em geral apresentaram contamina\u00e7\u00e3o por produtos n\u00e3o autorizados. Tamb\u00e9m os alimentos feitos a partir de gr\u00e3os geneticamente modificados apresentam subst\u00e2ncias t\u00f3xicas e n\u00e3o autorizadas.<\/p>\n<p>Fato mais aterrorizante ainda \u00e9 quando se sabe que mais da metade dos agrot\u00f3xicos usados no Brasil hoje h\u00e1 tempos foram banidos da Europa e dos Estados Unidos. O resultado direto do consumo dessas subst\u00e2ncias perigosas \u00e9 que tem aumentado exponencialmente o n\u00famero de casos de c\u00e2ncer e de outras doen\u00e7as gen\u00e9ticas.<\/p>\n<p>Subst\u00e2ncias como o glifosato, banido em v\u00e1rias partes do mundo por sua potencialidade carcinog\u00eanica, continuam a ser vendidas livremente no pa\u00eds. Uma simples ida ao verdureiro ou ao hortifr\u00fati dos supermercados \u00e9 receita para uma mesa farta de venenos dos mais poderosos.<\/p>\n<p>Para os vegetarianos, um prato de salada variada, consumida hoje, equivale \u00e0 ingest\u00e3o de colheradas de veneno, repletos de metais pesados e outros elementos mort\u00edferos. O problema maior \u00e9 que os efeitos desses elementos s\u00e3o cumulativos e delet\u00e9rios, agindo em sil\u00eancio.<\/p>\n<p>Ou o Brasil adota medidas urgentes e duras no disciplinamento do uso dessas subst\u00e2ncias, ou as gera\u00e7\u00f5es futuras pagar\u00e3o o pre\u00e7o com a pr\u00f3pria vida.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Hist\u00f3ria de Bras\u00edlia<\/b><\/p>\n<p>Estas not\u00edcias foram feitas por jornalistas pagos pelo governo, para difamar autoridades, lan\u00e7ando a desconfian\u00e7a e o descr\u00e9dito para os que n\u00e3o concordam com as id\u00e9ias dos atuais dirigentes da Ag\u00eancia. (Publicado em 05\/09\/1961)<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DESDE 1960 aricunha@dabr.com.br com Circe Cunha \/\/ circecunha.df@dabr.com.br com MAMFIL \u00a0 Quando se fala em produ\u00e7\u00e3o agr\u00edcola, os n\u00fameros apresentados pelo Brasil s\u00e3o verdadeiramente astron\u00f4micos. Para um pa\u00eds de propor\u00e7\u00f5es continentais e que nas \u00faltimas d\u00e9cadas vem expandindo progressivamente suas fronteiras agr\u00edcolas atrav\u00e9s do uso intensivo de maquin\u00e1rio de \u00faltima gera\u00e7\u00e3o, falar em produ\u00e7\u00e3o recorde da safra a cada ano [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-7741","post","type-post","status-publish","format-standard","hentry","category-integra"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/7741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=7741"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/7741\/revisions"}],"predecessor-version":[{"id":7987,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/7741\/revisions\/7987"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=7741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=7741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=7741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}