{"id":7071,"date":"2015-12-17T09:08:58","date_gmt":"2015-12-17T11:08:58","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/?p=7071"},"modified":"2015-12-30T09:09:20","modified_gmt":"2015-12-30T11:09:20","slug":"boa-vontade","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/boa-vontade\/","title":{"rendered":"Boa vontade"},"content":{"rendered":"<p>Enquanto o Or\u00e7amento de 2015 n\u00e3o estiver efetivado para 2016, os hospitais do DF penam. Quem viu o Hmib no auge e v\u00ea as dificuldades de hoje fica horrorizado. O Hospital de Base tamb\u00e9m \u00e9 movido por boa vontade e verba m\u00ednima.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enquanto o Or\u00e7amento de 2015 n\u00e3o estiver efetivado para 2016, os hospitais do DF penam. Quem viu o Hmib no auge e v\u00ea as dificuldades de hoje fica horrorizado. O Hospital de Base tamb\u00e9m \u00e9 movido por boa vontade e verba m\u00ednima.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7071","post","type-post","status-publish","format-standard","hentry","category-integra-integra"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/7071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=7071"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/7071\/revisions"}],"predecessor-version":[{"id":7072,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/7071\/revisions\/7072"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=7071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=7071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=7071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}