{"id":7069,"date":"2015-12-17T09:08:28","date_gmt":"2015-12-17T11:08:28","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/?p=7069"},"modified":"2015-12-30T09:08:48","modified_gmt":"2015-12-30T11:08:48","slug":"massa-de-manobra","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/massa-de-manobra\/","title":{"rendered":"Massa de manobra"},"content":{"rendered":"<p>Uma pena que o Sindicato dos Professores use a institui\u00e7\u00e3o para causas ideol\u00f3gicas. Certamente n\u00e3o representou toda a classe exibindo a opini\u00e3o contra o impeachment da presidente. Quando um pai de aluno aceita a frase da campanha publicit\u00e1ria \u201cMexeu com professor, mexeu comigo\u201d, significa que o professor deve ter o reconhecimento pela responsabilidade de educar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma pena que o Sindicato dos Professores use a institui\u00e7\u00e3o para causas ideol\u00f3gicas. Certamente n\u00e3o representou toda a classe exibindo a opini\u00e3o contra o impeachment da presidente. Quando um pai de aluno aceita a frase da campanha publicit\u00e1ria \u201cMexeu com professor, mexeu comigo\u201d, significa que o professor deve ter o reconhecimento pela responsabilidade de educar.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7069","post","type-post","status-publish","format-standard","hentry","category-integra-integra"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/7069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=7069"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/7069\/revisions"}],"predecessor-version":[{"id":7070,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/7069\/revisions\/7070"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=7069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=7069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=7069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}