{"id":7025,"date":"2015-12-13T08:32:31","date_gmt":"2015-12-13T10:32:31","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/?p=7025"},"modified":"2015-12-30T08:32:50","modified_gmt":"2015-12-30T10:32:50","slug":"lente","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/lente\/","title":{"rendered":"Lente"},"content":{"rendered":"<p>De olho na C\u00e2mara Legislativa. Telma Rufino tem pressa para a aprecia\u00e7\u00e3o do projeto aprovado pela Comiss\u00e3o de Assuntos Fundi\u00e1rios que prop\u00f5e a desafeta\u00e7\u00e3o de \u00e1reas p\u00fablicas e autoriza a transfer\u00eancia de propriedade ou de direito de im\u00f3veis em diversas Regi\u00f5es Administrativas do DF.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De olho na C\u00e2mara Legislativa. Telma Rufino tem pressa para a aprecia\u00e7\u00e3o do projeto aprovado pela Comiss\u00e3o de Assuntos Fundi\u00e1rios que prop\u00f5e a desafeta\u00e7\u00e3o de \u00e1reas p\u00fablicas e autoriza a transfer\u00eancia de propriedade ou de direito de im\u00f3veis em diversas Regi\u00f5es Administrativas do DF.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7025","post","type-post","status-publish","format-standard","hentry","category-integra-integra"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/7025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=7025"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/7025\/revisions"}],"predecessor-version":[{"id":7026,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/7025\/revisions\/7026"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=7025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=7025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=7025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}