{"id":6894,"date":"2015-12-03T09:45:39","date_gmt":"2015-12-03T11:45:39","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/?p=6894"},"modified":"2015-12-18T09:46:07","modified_gmt":"2015-12-18T11:46:07","slug":"as-mil-palavras-presas-no-lamacal","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/as-mil-palavras-presas-no-lamacal\/","title":{"rendered":"As mil palavras presas no lama\u00e7al"},"content":{"rendered":"<p>Num mundo em que as not\u00edcias viajam na velocidade da luz e os sat\u00e9lites vigiam diuturnamente cada canto da Terra, os discursos, mesmo feitos a milhares de quil\u00f4metros, precisam guardar, ao menos, proximidade com os fatos e com a verdade. No caso do pronunciamento da presidente na abertura da Confer\u00eancia Global sobre o Clima (COP 21) em Paris, a maioria da plateia, com o m\u00ednimo de informa\u00e7\u00e3o, percebeu que ali na tribuna estava uma chefe de governo que internamente enfrenta a maior crise pol\u00edtica e econ\u00f4mica de todos os tempos, cujo partido e muitos de seus membros est\u00e3o na al\u00e7a de mira da Justi\u00e7a.<\/p>\n<p>Relat\u00f3rios di\u00e1rios elaborados pelas embaixadas credenciadas no Brasil, com centenas de correspondentes internacionais espalhados por todo o territ\u00f3rio nacional, com a velha e conhecida m\u00e1 vontade com pol\u00edticos locais, cuidaram de informar ao restante do planeta que a mulher que ocupa a tribuna para falar do meio ambiente \u00e9 figura que extrapola a fronteira de fragilizada.<\/p>\n<p>Com os \u00edndices de popularidade pessoal e da economia situados no subsolo, com as notas negativas atribu\u00eddas pelas ag\u00eancias de avalia\u00e7\u00e3o de risco ao pa\u00eds e pela imin\u00eancia de sofrer processo de impeachment, as declara\u00e7\u00f5es de dona Dilma, infelizmente, ca\u00edram no vazio da descren\u00e7a. Nem mesmo o pretenso realismo de lavar a roupa suja em p\u00fablico, ao falar do maior desastre ambiental da hist\u00f3ria do Brasil, convenceram a audi\u00eancia das promessas da representante do Brasil para minorar os efeitos do aquecimento global.<\/p>\n<p>\u201cEstamos reagindo ao desastre, com medidas de redu\u00e7\u00e3o de danos, apoio \u00e0s popula\u00e7\u00f5es atingidas, preven\u00e7\u00e3o de ocorr\u00eancias e tamb\u00e9m punindo, severamente, os respons\u00e1veis pela trag\u00e9dia\u201d, afirmou a presidente, quando, na verdade, todos sabem que seu governo, por causa da crise interna, levou uma semana para visitar e se inteirar da realidade em Mariana e, mesmo depois disso, as medidas para minorar os efeitos da cat\u00e1strofe s\u00e3o consideradas aqu\u00e9m das necessidades.<\/p>\n<p>Da mesma forma, a fala sobre as medidas para conter o desmatamento na Amaz\u00f4nia, que, segundo ela, caiu 80% na \u00faltima d\u00e9cada, fica prejudicada quando o mundo sabe que apenas entre 2014 e 2015 houve incremento de mais de 16% na derrubada da mata, com o desaparecimento de uma \u00e1rea cinco vezes maior do que a cidade de S\u00e3o Paulo.<\/p>\n<p>J\u00e1 dizia o fil\u00f3sofo de Mondubim: contra os fatos, n\u00e3o h\u00e1 discurso poss\u00edvel. Contra a realidade interna em que um mar de lama varre o governo, melhor entregar a batuta para quem sabe reger a administra\u00e7\u00e3o. Cr\u00e9ditos de carbono, cobrados do mundo, devem ser necessariamente precedidos de cr\u00e9dito pessoal. Confiabilidade externa requer, ao menos, apoio da sociedade internamente. Ou seja, PT sauda\u00e7\u00f5es finais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Num mundo em que as not\u00edcias viajam na velocidade da luz e os sat\u00e9lites vigiam diuturnamente cada canto da Terra, os discursos, mesmo feitos a milhares de quil\u00f4metros, precisam guardar, ao menos, proximidade com os fatos e com a verdade. No caso do pronunciamento da presidente na abertura da Confer\u00eancia Global sobre o Clima (COP 21) em Paris, a maioria [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6894","post","type-post","status-publish","format-standard","hentry","category-integra-integra"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/6894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=6894"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/6894\/revisions"}],"predecessor-version":[{"id":6895,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/6894\/revisions\/6895"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=6894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=6894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=6894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}