{"id":6890,"date":"2015-12-03T09:43:14","date_gmt":"2015-12-03T11:43:14","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/?p=6890"},"modified":"2015-12-18T09:43:53","modified_gmt":"2015-12-18T11:43:53","slug":"prejuizo","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/prejuizo\/","title":{"rendered":"Preju\u00edzo"},"content":{"rendered":"<p>Interditaram o passeio das batatas fritas. Um carregamento que chegou de Vit\u00f3ria foi parado em uma inspe\u00e7\u00e3o de rotina da Secretaria da Fazenda. Como o documento apontava a entrega no Polo JK, em Santa Maria, a carga foi apreendida no Gama. A empresa n\u00e3o est\u00e1 autorizada a mudar o documento nem o itiner\u00e1rio da carga. R$ 200 mil de multa e a multa de 200% pela infra\u00e7\u00e3o fiscal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Interditaram o passeio das batatas fritas. Um carregamento que chegou de Vit\u00f3ria foi parado em uma inspe\u00e7\u00e3o de rotina da Secretaria da Fazenda. Como o documento apontava a entrega no Polo JK, em Santa Maria, a carga foi apreendida no Gama. A empresa n\u00e3o est\u00e1 autorizada a mudar o documento nem o itiner\u00e1rio da carga. R$ 200 mil de multa [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6890","post","type-post","status-publish","format-standard","hentry","category-integra-integra"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/6890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=6890"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/6890\/revisions"}],"predecessor-version":[{"id":6891,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/6890\/revisions\/6891"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=6890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=6890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=6890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}