{"id":6880,"date":"2015-12-02T09:38:29","date_gmt":"2015-12-02T11:38:29","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/?p=6880"},"modified":"2017-12-14T16:18:21","modified_gmt":"2017-12-14T18:18:21","slug":"a-frase-que-foi-pronunciada-3","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/a-frase-que-foi-pronunciada-3\/","title":{"rendered":"A frase que foi pronunciada"},"content":{"rendered":"<p>\u201cSete pecados sociais: pol\u00edtica sem princ\u00edpios, riqueza sem trabalho, prazer sem consci\u00eancia, conhecimento sem car\u00e1ter, com\u00e9rcio sem moralidade, ci\u00eancia sem humanidade e culto sem sacrif\u00edcio.\u201d<\/p>\n<p>Mahatma Gandhi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSete pecados sociais: pol\u00edtica sem princ\u00edpios, riqueza sem trabalho, prazer sem consci\u00eancia, conhecimento sem car\u00e1ter, com\u00e9rcio sem moralidade, ci\u00eancia sem humanidade e culto sem sacrif\u00edcio.\u201d Mahatma Gandhi<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,23],"tags":[67],"class_list":["post-6880","post","type-post","status-publish","format-standard","hentry","category-integra-integra","category-integra","tag-brasilia-historiadebrasilia-aricunha-circecunha-mamfil"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/6880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=6880"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/6880\/revisions"}],"predecessor-version":[{"id":6881,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/6880\/revisions\/6881"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=6880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=6880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=6880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}