{"id":299,"date":"2015-09-17T01:40:00","date_gmt":"2015-09-17T01:40:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/visto_lido_e_ouvido-31-2\/"},"modified":"2015-11-18T15:40:26","modified_gmt":"2015-11-18T17:40:26","slug":"visto_lido_e_ouvido-31-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/visto_lido_e_ouvido-31-2\/","title":{"rendered":"VISTO, LIDO E OUVIDO"},"content":{"rendered":"<p>circecunha@gmail.com; arigcunha@ig.com.br&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<br style=\"padding: 0px;margin: 0px;border: 0px currentcolor\"><br \/>Interina: Circe Cunha&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<br \/>Colabora\u00e7\u00e3o Mamfil&nbsp;&nbsp;&nbsp;&nbsp;   <\/p>\n<div>\n<\/div>\n<div>\n<\/div>\n<div>\n<div><b>Consumindo desgovernos<\/b><\/div>\n<div>\n<\/div>\n<div>Para os cidad\u00e3os e, por extens\u00e3o para os contribuintes e consumidores, interessa um Estado enxuto, racional e eficiente na presta\u00e7\u00e3o de todos os servi\u00e7os que s\u00e3o de sua responsabilidade e, para os quais, a lei obriga que sejam bem realizados. Acontece que o cumprimento da lei s\u00f3 cabe a quem est\u00e1 fora da roda do compadrio. Qualquer aluno de Direito fica confuso ao ler a Constitui\u00e7\u00e3o. Ela \u00e9 ideal e n\u00e3o real. As leis s\u00e3o tecidas com tramas propositadamente. A inten\u00e7\u00e3o \u00e9 que em v\u00e1rias interpreta\u00e7\u00f5es caiba a que for de interesse da parte mais forte, como apostou Tras\u00edmaco em um dos &nbsp;dez livros da Rep\u00fablica de Plat\u00e3o(380 e 370 a.C).\u201c A justi\u00e7a n\u00e3o \u00e9 outra coisa, e em toda parte, sen\u00e3o a conveni\u00eancia do mais forte\u201d, concluiu o fil\u00f3sofo.<\/div>\n<div>\n<\/div>\n<div>O rombo nos cofres do GDF, deixado pela gest\u00e3o passada, ser\u00e1 matematicamente equacionado, sangrando-se, um pouco mais, o contribuinte brasiliense. Chega o aumento de impostos, pre\u00e7os de servi\u00e7os e alimentos muito mais caros.<\/div>\n<div>\n<\/div>\n<div>Apesar de haver \u00f3rg\u00e3os para o controle das finan\u00e7as p\u00fablicas, como se v\u00ea, eles n\u00e3o funcionam. Deveriam prevenir coibindo gastos indevidos e desvios dos recursos p\u00fablicos. Restam &nbsp;poucas alternativas ao cidad\u00e3o. Aos crentes, a ora\u00e7\u00e3o; aos insurretos, a repeti\u00e7\u00e3o dos epis\u00f3dios da Derrama; aos extremistas , a sonega\u00e7\u00e3o e aos acomodados, pagar sem protestos.<\/div>\n<div>\n<\/div>\n<div>Guardadas as propor\u00e7\u00f5es, o que ocorre em nossas casas, &nbsp;se repete em nosso estado e no pa\u00eds de forma geral e similar. Receitas e gastos devem coexistir em equil\u00edbrio, em quaisquer \u00e2mbitos. As contas no vermelho &nbsp;repercutem tanto para dona de casa como para o governo. A diferen\u00e7a \u00e9 que a dona de casa n\u00e3o pode repassar a outrem, as despesas feitas em excesso. Contrariamente, a inc\u00faria perdul\u00e1ria dos governos, mesmo sob a condi\u00e7\u00e3o de penalidades previstas na lei de responsabilidade fiscal, s\u00e3o sempre repassadas para o cidad\u00e3o, sem puni\u00e7\u00e3o \u00e0 m\u00e1 ger\u00eancia.<\/div>\n<div>\n<\/div>\n<div>A afirma\u00e7\u00e3o de que n\u00e3o existe dinheiro p\u00fablico, existe apenas dinheiro do contribuinte, atribu\u00edda a ex-primeira ministra brit\u00e2nica Margaret Thatcher, &nbsp;serve como par\u00e2metro na &nbsp;hora de cobrar do cidad\u00e3o pelos rombos nas contas p\u00fablicas.<\/div>\n<div>\n<\/div>\n<div>N\u00e3o bastassem as repercuss\u00f5es extremamente &nbsp;negativas decorrentes dos desequil\u00edbrios nas contas do governo federal, os brasilienses ser\u00e3o brindados tamb\u00e9m como uma contra extra a ser paga em decorr\u00eancia da contabilidade &nbsp;criminosa do desgoverno passado.<\/div>\n<div>\n<\/div>\n<div>Os recentes atalhos sofridos no longo caminho que leva \u00e0 cidadania e \u00e0 democracia de direitos, &nbsp;parecem conduzir a popula\u00e7\u00e3o, ao beco sem sa\u00edda da desobedi\u00eancia civil, tal a discrep\u00e2ncia existente entre os anseios da coletividade e a vontade de uma minoria instalada no poder .<\/div>\n<div>\n<\/div>\n<div>Atingido por todos os lados, quem sabe n\u00e3o \u00e9 chegada a hora de o cidad\u00e3o comum sacar da algibeira a derradeira oportunidade de se proteger e mostrar ao governo local e federal um exemplar da Lei n\u00ba 8.078\/90, conhecida como C\u00f3digo do Consumidor. Talvez esteja nesse documento a alternativa desesperada para resolver, de vez, &nbsp;a rela\u00e7\u00e3o insana e hist\u00f3rica entre quem paga e n\u00e3o recebe e quem cobra e n\u00e3o cumpre .<\/div>\n<div>\n<\/div>\n<div>\n<\/div>\n<div><b>A frase que foi pronunciada:<\/b><\/div>\n<div>\n<\/div>\n<div>\u201cA hist\u00f3ria nunca vai nos deixar. Quem aprende com ela evita incorrer nos erros do passado.\u201d<\/div>\n<div>\n<\/div>\n<div>Professora Dorot\u00e9a Kerr, do Departamento de M\u00fasica da UNESP,<\/div>\n<div>\n<\/div>\n<div>&nbsp;<\/div>\n<div>\n<\/div>\n<div><b>Resgate<\/b><\/div>\n<div>\n<\/div>\n<div>Prova de que a frase de hoje funciona \u00e9 que enquanto o Minist\u00e9rio da Educa\u00e7\u00e3o planeja o curr\u00edculo \u00fanico com o contexto das disciplinas apresentados a partir da experi\u00eancia dos alunos, os professores penam nos col\u00e9gios para segurar a aten\u00e7\u00e3o da meninada. Voltar ao que pensou Paulo Freire parece ser a sa\u00edda para os estudiosos.<\/div>\n<div>\n<\/div>\n<div>&nbsp;<\/div>\n<div>\n<\/div>\n<div><b>Cultura<\/b><\/div>\n<div>\n<\/div>\n<div>Na comiss\u00e3o que sabatinou D\u00e9bora R. Ivanov para a Ancine, a senadora Simone Tebet lembrou que se 60% dos munic\u00edpios brasileiros t\u00eam menos que 20 mil habitantes, pelas regras do governo 60% dos munic\u00edpios n\u00e3o t\u00eam salas de cinema.<\/div>\n<div>\n<\/div>\n<div>&nbsp;<\/div>\n<div>\n<\/div>\n<div><b>Imprevis\u00edveis<\/b><\/div>\n<div>\n<\/div>\n<div>Senador Donizeti Nogueira contou que levou um susto quando a prefeitura de Goi\u00e2nia resolver apresentar concertos eruditos ao ar livre para a popula\u00e7\u00e3o. Ele tinha certeza da rejei\u00e7\u00e3o. No entanto o povo se sentiu agraciado com a arte que n\u00e3o conhecia. Arte \u00e9 assim. Povo \u00e9 assim.&nbsp;<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>circecunha@gmail.com; arigcunha@ig.com.br&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Interina: Circe Cunha&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Colabora\u00e7\u00e3o Mamfil&nbsp;&nbsp;&nbsp;&nbsp; Consumindo desgovernos Para os cidad\u00e3os e, por extens\u00e3o para os contribuintes e consumidores, interessa um Estado enxuto, racional e eficiente na presta\u00e7\u00e3o de todos os servi\u00e7os que s\u00e3o de sua responsabilidade e, para os quais, a lei obriga que sejam bem realizados. Acontece que o cumprimento da lei s\u00f3 cabe a quem est\u00e1 fora da [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-299","post","type-post","status-publish","format-standard","hentry","category-integra-integra"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=299"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/299\/revisions"}],"predecessor-version":[{"id":6668,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/299\/revisions\/6668"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}