{"id":236,"date":"2015-07-17T09:13:00","date_gmt":"2015-07-17T12:13:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/visto_lido_e_ouvido-193\/"},"modified":"2016-05-13T19:29:35","modified_gmt":"2016-05-13T22:29:35","slug":"visto_lido_e_ouvido-193","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/visto_lido_e_ouvido-193\/","title":{"rendered":"VISTO, LIDO E OUVIDO"},"content":{"rendered":"<p>circecunha@gmail.com; arigcunha@ig.com.br   <\/p>\n<p><b>Ser ou n\u00e3o ser curinga?<\/b>  Nos jogos de baralho, o Curinga \u00e9 aquela carta que tem seu valor determinado conforme a combina\u00e7\u00e3o com outras sequ\u00eancia de cartas que o jogador possui em m\u00e3os. &nbsp;Segundo alguns dicion\u00e1rios da l\u00edngua portuguesa, o Curinga, cuja etimologia significa \u201cmatar\u201d, \u00e9 &nbsp;tamb\u00e9m aquela pessoa que assume o valor de outras ou que pode atuar em v\u00e1rias posi\u00e7\u00f5es.   Por extens\u00e3o, o termo resume, com certo grau de realidade crua, a posi\u00e7\u00e3o da &nbsp;presidente da rep\u00fablica dentro do atual cen\u00e1rio pol\u00edtico do pa\u00eds. Guindada do quase anonimato para o centro do poder, por obra e gra\u00e7a do seu antecessor, que via primeiramente nesta estrat\u00e9gia uma maneira f\u00e1cil de retornar \u00e0 presid\u00eancia em 2018, Dilma Rousseff, que n\u00e3o era do meio pol\u00edtico e muito menos expertise em administra\u00e7\u00e3o assumiu o leme do Titanic Brasil , cuja a rota j\u00e1 havia sido tra\u00e7ada desde 2003.  &nbsp;Em qualquer cen\u00e1rio que se analise o momento atual, sobram d\u00favidas sobre a continuidade ou interrup\u00e7\u00e3o do mandato da presidente. Sobram tamb\u00e9m sentimentos e press\u00e1gios de mau agouro sobre o que esta por vir.   Posicionada no meio do jogo de cartas de Lula com um objetivo predeterminado, Dilma \u201cmatou\u201d a jogada e de quebra, conseguiu unir o pa\u00eds todo contra o modus operandi do partido no poder e do seu l\u00edder maior. Com a silhueta &nbsp;\u201csugada\u201d por um regime de dieta brutal, essa Dilma remodelada, &nbsp;vai cuidando do novo guarda-roupa e de outros afazeres menos importantes , enquanto aguarda inerte o desenrolar dos acontecimentos que n\u00e3o pode mais controlar e cujo desfecho se anuncia grave para todos.   \u00c0 medida em que as investiga\u00e7\u00f5es da Opera\u00e7\u00e3o Lava Jato avan\u00e7am, mais e mais s\u00e3o solapados o terreno em que est\u00e3o assentados os poderes da Rep\u00fablica, amea\u00e7ando a cada um, de acordo com seu envolvimento no caso. Quem quer um pa\u00eds diferente agradece aos esfor\u00e7os da Pol\u00edcia Federal. Para fechar esse tempo de agruras com um toque popular, come\u00e7am a se mobilizar por todo o pa\u00eds, mais uma grande manifesta\u00e7\u00e3o de rua, em agosto.  <b> <\/p>\n<p><\/b><b>A frase que &nbsp;foi pronunciada:<\/b>  \u201cEu poderia ser a pessoa mais agrad\u00e1vel do mundo, mas optei por ser eu mesma!\u201d  Li por a\u00ed  <b> <\/p>\n<p><\/b><b>Seletivo<\/b>  Encantado com a plaquinha \u201cAqui tem carregador de celular\u201d na parada de \u00f4nibus, perto do Galois, na L2 Sul, o passageiro rodeava as paredes tentando localizar uma tomada. Enquanto isso uma moto estaciona, desce um rapaz e anuncia o assalto. S\u00f3 queria os celulares. Era ele o carregador! Os assaltos desse tipo s\u00e3o constantes em v\u00e1rios pontos da cidade.  <b> <\/p>\n<p><\/b><b>Cuidados<\/b>  Dayane Cosac envia um lembrete assinado pela CEB. Ventos fortes e f\u00e9rias s\u00e3o a combina\u00e7\u00e3o perfeita para soltar pipa. A companhia alerta para que os pais orientem os filhos a brincar longe das redes el\u00e9tricas.  <b> <\/p>\n<p><\/b><b>Verdade<\/b>  Segue para o plen\u00e1rio do Senado o PL8078\/14 do Executivo que regulamenta as atividades de n\u00edvel superior como perito criminal, perito m\u00e9dico-legista, agente de pol\u00edcia de cust\u00f3dia, escriv\u00e3o de pol\u00edcia, papiloscopista policial e agente penitenci\u00e1rio . O projeto foi aprovado por unanimidade na C\u00e2mara dos Deputados.  <b> <\/p>\n<p><\/b><b>Conseq\u00fc\u00eancia<\/b>  Quem comemorou a aprova\u00e7\u00e3o do Projeto de Lei foi o presidente da Associa\u00e7\u00e3o Brasiliense de Peritos Papiloscopistas &#8211; ASBRAPP, Rodrigo Meneses. Ele afirmou que reconhecimento qualifica e possibilita melhorias para a carreira na PCDF e tamb\u00e9m \u00e9 importante para o reconhecimento dos peritos papiloscopistas como peritos oficiais.   &nbsp;  <b>Desburocratiza<\/b>  &nbsp;  Embora muitos tenham dado maior import\u00e2ncia aos R$5 bilh\u00f5es do Plano de Obras que ser\u00e3o investidos em constru\u00e7\u00f5es na cidade, o governador Rollemberg destacou a import\u00e2ncia de se diminuir a burocracia na aprova\u00e7\u00e3o de projetos. A agilidade contribui para a melhoria do ambiente econ\u00f4mico e a gera\u00e7\u00e3o de empregos.  &nbsp;  <b>Terr\u00edveis<\/b>  &nbsp;  <\/p>\n<div class=\"ecxMsoNormal\" style=\"text-align:justify;text-indent:35.4pt\">S\u00e3o dois lados da moeda quando se fala em micro\u00f4nibus de cooperativas. H\u00e1 os que defendem por falta de op\u00e7\u00e3o, mas que preferem a substitui\u00e7\u00e3o das linhas por \u00f4nibus convencionais. H\u00e1 os que abominam as m\u00fasicas e tratamento sofr\u00edvel dispensado pelos profissionais. <\/div>\n<div class=\"ecxMsoNormal\" style=\"text-align:justify;text-indent:35.4pt\">&nbsp;<\/div>\n<p><b>Proteja-se rollemberg<\/b><b>&nbsp;<\/b>  Nem uma c\u00e2mera de TV inibiu a a\u00e7\u00e3o da nova modalidade de furto dentro da Ceasa. Ao contratar um carrinho de m\u00e3o para levar as compras ao carro, no meio do percurso os lar\u00e1pios passam a m\u00e3o nos legumes e verduras at\u00e9 formar uma caixa mista com os produtos surrupiados. Cobram ent\u00e3o, R$50 pelo produto do furto.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>circecunha@gmail.com; arigcunha@ig.com.br Ser ou n\u00e3o ser curinga? Nos jogos de baralho, o Curinga \u00e9 aquela carta que tem seu valor determinado conforme a combina\u00e7\u00e3o com outras sequ\u00eancia de cartas que o jogador possui em m\u00e3os. &nbsp;Segundo alguns dicion\u00e1rios da l\u00edngua portuguesa, o Curinga, cuja etimologia significa \u201cmatar\u201d, \u00e9 &nbsp;tamb\u00e9m aquela pessoa que assume o valor de outras ou que pode [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-236","post","type-post","status-publish","format-standard","hentry","category-integra-integra"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=236"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/236\/revisions"}],"predecessor-version":[{"id":7758,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/236\/revisions\/7758"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}