{"id":232,"date":"2015-07-13T09:05:00","date_gmt":"2015-07-13T12:05:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/visto_lido_e_ouvido-189\/"},"modified":"2016-05-13T19:29:39","modified_gmt":"2016-05-13T22:29:39","slug":"visto_lido_e_ouvido-189","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/visto_lido_e_ouvido-189\/","title":{"rendered":"VISTO, LIDO E OUVIDO"},"content":{"rendered":"<p>circecunha@gmail.com; arigcunha@ig.com.br <\/p>\n<p>  <b>HIST\u00d3RIA DE BRAS\u00cdLIA<\/b>  O Plano de economia do governo \u00e9 no sentido de evitar viagens ao exterior \u00e0 custa do povo, despesas com passagens para cima e para baixo \u00e0 custa do povo, compras, educa\u00e7\u00e3o, n\u00e3o. Para o ensino, devem sair todas as verbas necess\u00e1rias, contanto que nenhuma crian\u00e7a fique sem escola, e nenhuma escola fique sem material.  <b>(Publicado em 19\/08\/1961)<\/b>    <b> <\/p>\n<p><\/b><b>HIST\u00d3RIA DE BRAS\u00cdLIA<\/b>  Ningu\u00e9m disse ao presidente da Rep\u00fablica, e fez mal o sr. Ney Braga. Quando o sr. J\u00e2nio Quadros esteve em Curitiba, os inativos organizaram uma passeata da fome, e o cortejo presidencial, \u00e0 \u00faltima hora, mudou de itiner\u00e1rio. O presidente sabe das dificuldades dos inativos em toda a parte, e n\u00e3o \u00e9 s\u00f3 dos inativos, n\u00e3o. Dos ativos, tamb\u00e9m. Pena que um governo estadual t\u00e3o esclarecido cometa ainda os erros do tempo da ditadura, em que o presidente da Rep\u00fablica sempre tinha a informa\u00e7\u00e3o de que o pa\u00eds estava na melhor das maravilhas.  <b>(Publicado em 19\/08\/1961)<\/b>    <b> <\/p>\n<p><\/b><b>HIST\u00d3RIA DE BRAS\u00cdLIA<\/b>  O governador do Piau\u00ed volta a reafirmar a convic\u00e7\u00e3o da elei\u00e7\u00e3o do governador Parsifal Barroso, do Cear\u00e1, \u00e0 C\u00e2mara Federal, pela representa\u00e7\u00e3o piauiense. Voc\u00ea que \u00e9 piauiense defenda seu Estado. Barganha eleitoral n\u00e3o \u00e9 mais para os nossos dias.  <b>(Publicado em 19\/08\/1961)<\/b>    <b> <\/p>\n<p><\/b><b>HIST\u00d3RIA DE BRAS\u00cdLIA<\/b>  Uma das vantagens de Bras\u00edlia \u00e9 o nivelamento entre as pessoas. Deputados, senadores, ministros, s\u00e3o aqui, homens comuns. No Rio andam cercados de bajuladores, de interessados, de cavadores. Aqui s\u00e3o o que s\u00e3o: ministros, deputados, senadores.  <b>(Publicado em 19\/08\/1961)<\/b>    <b> <\/p>\n<p><\/b><b>HIST\u00d3RIA DE BRAS\u00cdLIA<\/b>  Outra vantagem desse nivelamento \u00e9 esta: quem n\u00e3o veio transferido compulsoriamente, est\u00e1 aqui por necessidade. Pode ser o paulista mais tradicional, o carioca mais rebolante, o ga\u00facho mais apegado aos pagos ou o \u201cpau de arara\u201d n\u00f4made. Todos est\u00e3o aqui por uma \u00fanica raz\u00e3o, e quando aparece algu\u00e9m querendo dizer que veio por outra causa, a gente ri baixinho, para n\u00e3o envergonhar.  <b>(Publicado em 19\/08\/1961)<\/b>    <b> <\/p>\n<p><\/b><b>HIST\u00d3RIA DE BRAS\u00cdLIA<\/b>  Necessidade de expans\u00e3o profissional, necessidade de sair de certa cidade, necessidade de independ\u00eancia financeira, necessidade de dinheiro mesmo, mas todo o mundo est\u00e1 por necessidade.  <b>(Publicado em 19\/08\/1961)<\/b>   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>circecunha@gmail.com; arigcunha@ig.com.br HIST\u00d3RIA DE BRAS\u00cdLIA O Plano de economia do governo \u00e9 no sentido de evitar viagens ao exterior \u00e0 custa do povo, despesas com passagens para cima e para baixo \u00e0 custa do povo, compras, educa\u00e7\u00e3o, n\u00e3o. Para o ensino, devem sair todas as verbas necess\u00e1rias, contanto que nenhuma crian\u00e7a fique sem escola, e nenhuma escola fique sem material. [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-232","post","type-post","status-publish","format-standard","hentry","category-integra-integra"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=232"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/232\/revisions"}],"predecessor-version":[{"id":7762,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/232\/revisions\/7762"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}