{"id":207,"date":"2015-06-17T08:48:00","date_gmt":"2015-06-17T11:48:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/visto_lido_e_ouvido-163\/"},"modified":"2016-05-13T19:30:10","modified_gmt":"2016-05-13T22:30:10","slug":"visto_lido_e_ouvido-163","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/visto_lido_e_ouvido-163\/","title":{"rendered":"VISTO, LIDO E OUVIDO"},"content":{"rendered":"<p>circecunha@gmail.com; arigcunha@ig.com.br  <\/p>\n<p><b>Ci\u00eancia, democracia e regime<\/b>  \u00c9 poss\u00edvel existir ci\u00eancia sem democracia? Infelizmente sim. Da mesma forma \u00e9 poss\u00edvel a exist\u00eancia da arte na aus\u00eancia de \u00e9tica. Mas a ci\u00eancia, como arte humana do saber, n\u00e3o pode prescindir da \u00e9tica democr\u00e1tica .&nbsp; Se existe uma rela\u00e7\u00e3o entre a ci\u00eancia e a democracia ela est\u00e1 no fato de que o exerc\u00edcio do saber humano encontra na liberdade de pensamento e a\u00e7\u00e3o seu principal est\u00edmulo e fato catalizador. Ou seja, ao respirar ares menos polu\u00eddos pelo cerceamento de id\u00e9ias, a ci\u00eancia flui e cresce naturalmente.  Em seu livro As universidades e o regime militar, o professor Rodrigo Patto S\u00e1 Motta, afirma que : \u201cO programa do regime militar n\u00e3o foi enfraquecer as universidades, mas expandi-las para os seus fins\u201d, esclareceu, acrescentando que foram privilegiadas as \u00e1reas tecnol\u00f3gicas, seguidas da sa\u00fade p\u00fablica.\u201d&nbsp; Para o professor, durante aquele per\u00edodo houve&nbsp; um aumento das verbas para pesquisa e bolsas, a cria\u00e7\u00e3o de uma nova carreira docente com dedica\u00e7\u00e3o exclusiva, a cria\u00e7\u00e3o do Plano Nacional de P\u00f3s-gradua\u00e7\u00e3o e a constru\u00e7\u00e3o de novas universidades e campi. Ele contou que, na esfera federal, houve um crescimento de 50% das universidades p\u00fablicas e uma expans\u00e3o de 150% do corpo docente e de 300% do corpo discente. Em termos puramente materiais,&nbsp; isso foi feito.  &nbsp;No entanto, ao lado do crescimento material foi implementado um trabalho de limpeza dos quadros humanos,&nbsp; afastando do meio acad\u00eamico e dos centros de pesquisa do pa\u00eds todos aqueles que o regime suspeitava de tend\u00eancias esquerdistas.&nbsp; Com a decreta\u00e7\u00e3o do AI5 e do decreto 477, os principais&nbsp; cientistas e pesquisadores do pa\u00eds foram sumariamente afastados e aposentados compulsoriamente.&nbsp; Somente no Instituto Oswaldo Cruz, respeitado em todo o mundo pelo alto n\u00edvel em pesquisas na \u00e1rea de sa\u00fade p\u00fablica, dez pesquisadores&nbsp; foram cassados, tiveram seus direitos pol\u00edticos suspensos e foram impedidos de trabalhar, no caso que ficou conhecido por Massacre ou Expurgo de Manguinhos.&nbsp; Tamb\u00e9m a UNB , a partir de 1964 o reitor An\u00edsio Teixeira e o vice foram surpreendidos com a entrada no campus de 14 \u00f4nibus para levar os subversivos. 12 professores eram buscados. Em 1965, nova invas\u00e3o, com novas pris\u00f5es e demiss\u00f5es. Como rea\u00e7\u00e3o 223 dos 305 professores da Universidade pediram demiss\u00e3o. Os expurgos na UNB duraram at\u00e9 1978. Muitos cientistas e professores foram trabalhar no exterior. Os que aqui ficaram , foram silenciados ou partiram para trabalhar em outras \u00e1reas.&nbsp; O desenvolvimento das pesquisas cient\u00edficas que vinham sendo realizadas,&nbsp; ficaram congeladas no tempo com preju\u00edzos gigantescos para o desenvolvimento do pa\u00eds, sobretudo numa era em que a tecnologia passou ser vista como principal fator de riqueza de uma na\u00e7\u00e3o.  <b> <\/p>\n<p><\/b><b>A frase que n\u00e3o foi pronunciada:<\/b>  \u201cO melhor de ser cadela no Brasil \u00e9 n\u00e3o ter nenhuma lei que permita o aborto nas f\u00eameas de nossa ra\u00e7a.\u201d  Orca, a famosa cadelinha do ex-ministro Magri.  <b> <\/p>\n<p><\/b><b>Simples<\/b>  Na reuni\u00e3o da Frente Nacional dos Prefeitos houve uma demanda que, se resolvida, trar\u00e1 ganhos \u00e0 Educa\u00e7\u00e3o. A proposta \u00e9 de um regime de colabora\u00e7\u00e3o entre estados e munic\u00edpios para financiar o transporte escolar de alunos de redes p\u00fablicas de ensino. O Projeto de Lei sobre esse assunto est\u00e1 em processo de an\u00e1lise na C\u00e2mara. A autoria \u00e9 do Poder Executivo e est\u00e1 a seis anos aguardando aprova\u00e7\u00e3o.  <b> <\/p>\n<p><\/b><b>La\u00e7os<\/b>  Banda larga para o estado de Goi\u00e1s e um viaduto na regi\u00e3o do aeroporto de Goi\u00e2nia. Esse \u00e9 o resultado do jogo de cintura do tucano Marconi Perillo. Nos encontros com a presidente ele parece bem \u00e0 vontade. Ela tamb\u00e9m.  <b> <\/p>\n<p><\/b><b>Desapega!<\/b>  Nas m\u00eddias sociais, uma pesquisa mais apurada \u00e9 capaz de apontar sem sombra de d\u00favidas que as pessoas que admiram o senador Paulo Paim n\u00e3o se conformam com a sigla do PT vir logo ap\u00f3s o nome dele. Nas notas taquigr\u00e1ficas da C\u00e2mara dos Deputados de 10 de maio de 2006 o deputado Darc\u00edsio Perondi disse: \u201clogo, logo Paulo Paim sai do PT.\u201d  <b> <\/p>\n<p><\/b><b>Compet\u00eancia<\/b>  Ontem foi o \u00faltimo dia de um semin\u00e1rio em Corumb\u00e1 que discutiu os impactos causados pela agricultura&nbsp; sobre os recursos h\u00eddricos. \u00c9 poss\u00edvel conciliar o desenvolvimento da produ\u00e7\u00e3o com o uso sustent\u00e1vel das \u00e1guas e terras. Com a ministra K\u00e1tia Abreu \u00e0 frente da pasta da Agricultura e uma assessoria afinada com o uso inteligente dos recursos naturais, o futuro \u00e9 promissor.  <b> <\/p>\n<p><\/b><b>Preven\u00e7\u00e3o<\/b>  Pr\u00e9dios do Setor de Divers\u00f5es Sul est\u00e3o sendo vistoriados. Agentes da Subsecretaria de Prote\u00e7\u00e3o e Defesa Civil da Secretaria da Seguran\u00e7a P\u00fablica e da Paz Social fazem uma averigua\u00e7\u00e3o por todo o Conic. As redes el\u00e9tricas e hidr\u00e1ulicas al\u00e9m da estrutura f\u00edsica e equipamentos de seguran\u00e7a ser\u00e3o devidamente fiscalizados.                                                                                                                                                               <\/p>\n<div class=\"v-InboxFooterContainer\">              <\/div>\n<div class=\"AppContainer\">\n<div id=\"c_base\" class=\"c_base\">\n<div id=\"c_content\" class=\"c_main\">\n<div id=\"pageContent\">\n<div class=\"v-Page\" id=\"pageInbox\">\n<div id=\"inboxControl0f\">\n<div class=\"containsYSizerBar\">\n<div class=\"ContentRight WithRightRail FullView\">\n<div class=\"v-InboxFooterContainer\">          <\/div>\n<\/p><\/div>\n<div id=\"RightRailContainer\" class=\"c-RightRail RightRailContainerWidth t_sbgc\">\n<div id=\"RadAd_Skyscraper\" class=\"RightRailContent\">\n<div id=\"adbarContainer\">      <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"reauthenticationDiv\">              <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>                  &nbsp;&nbsp; &nbsp;                                                                                                                        <\/p>\n","protected":false},"excerpt":{"rendered":"<p>circecunha@gmail.com; arigcunha@ig.com.br Ci\u00eancia, democracia e regime \u00c9 poss\u00edvel existir ci\u00eancia sem democracia? Infelizmente sim. Da mesma forma \u00e9 poss\u00edvel a exist\u00eancia da arte na aus\u00eancia de \u00e9tica. Mas a ci\u00eancia, como arte humana do saber, n\u00e3o pode prescindir da \u00e9tica democr\u00e1tica .&nbsp; Se existe uma rela\u00e7\u00e3o entre a ci\u00eancia e a democracia ela est\u00e1 no fato de que o exerc\u00edcio [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-207","post","type-post","status-publish","format-standard","hentry","category-integra-integra"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=207"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/207\/revisions"}],"predecessor-version":[{"id":7788,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/207\/revisions\/7788"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}