{"id":206,"date":"2015-06-16T08:41:00","date_gmt":"2015-06-16T11:41:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/visto_lido_e_ouvido-162\/"},"modified":"2016-05-13T19:30:12","modified_gmt":"2016-05-13T22:30:12","slug":"visto_lido_e_ouvido-162","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/visto_lido_e_ouvido-162\/","title":{"rendered":"VISTO, LIDO E OUVIDO"},"content":{"rendered":"<p>circecunha@gmail.com; arigcunha@ig.com.br <\/p>\n<p><b>Diz-me com quem andas<\/b>  Prefer\u00eancia pessoal n\u00e3o se discute, pois tem gente que gosta da fruta e outros, do caro\u00e7o. Agora, quando essas mesmas prefer\u00eancias avan\u00e7am do circulo \u00edntimo e tocam no p\u00fablico , a coisa ganha uma dimens\u00e3o grave e acaba por atingir a todos indiscriminadamente.   Depois de treze anos no poder, ningu\u00e9m mais parece se surpreender com as amizades e as boas rela\u00e7\u00f5es do PT com pessoas e regimes ditatoriais&nbsp; claramente acusados de viola\u00e7\u00f5es aos direitos humanos. No caso da visita ao Brasil do intitulado chefe do poder Legislativo da Venezuela, Diosdado Cabello&nbsp; o problema \u00e9 ainda mais grave. Consciente da amizade problem\u00e1tica o Pal\u00e1cio do Planalto tratou de n\u00e3o divulgar o encontro com a presidente Dilma , feito, mais uma vez de forma secreta, fora da agenda e longe dos olhares dos curiosos e da imprensa. Cabello \u00e9 hoje, ao lado de Nicolas Maduro e do falecido Hugo Chavez , a&nbsp; principal figura a quem poder\u00edamos debitar a ru\u00edna pol\u00edtico econ\u00f4mica e social daquele pa\u00eds. Envolvido diretamente na persegui\u00e7\u00e3o de opositores ao regime, pesa tamb\u00e9m sobre esse indiv\u00edduo a acusa\u00e7\u00e3o feita pelas autoridades americanas de combate ao narcotr\u00e1fico, de chefiar&nbsp; o maior cartel do tr\u00e1fico de coca\u00edna da Venezuela, conhecido como S\u00f3is. Falidos e sem ningu\u00e9m mais a quem possam recorrer, essa figura do regime teria vindo ao Brasil chefiando uma miss\u00e3o de \u201calto n\u00edvel\u201d , para comprar de \u201ctudo\u201d.   Aproveitando o tour, o visitante, que tem mandato de captura e pris\u00e3o expedido pela Interpol, se encontrou tamb\u00e9m a sorrelfa com o ex-presidente Lula, por quem confessa uma grande admira\u00e7\u00e3o.&nbsp; O pr\u00eamio Nobel de literatura M\u00e1rio Vargas Llosa, ao descrever a visita do ex-primeiro ministro espanhol Felipe Gonz\u00e1lez \u00e0 Venezuela \u00e0 servi\u00e7o da causa da liberdade, em certo trecho comentou: \u201calguns dos defensores do regime de Maduro, como os presidentes Rafael Correa, do Equador, Evo Morales, da Bol\u00edvia e Dilma Rousseff, do Brasil, o fazem com hipocrisia e duplicidade, elogiando-o em discursos demag\u00f3gicos, defendendo-o nos organismos internacionais, mas evitando sistematicamente imit\u00e1-lo em suas pol\u00edticas econ\u00f4micas e sociais, conscientes de que, se seguirem o modelo chavista precipitar\u00e3o seus pa\u00edses numa cat\u00e1strofe semelhante \u00e0 da Venezuela.\u201d<b> <\/p>\n<p><\/b><b>  <\/b><b>A frase que n\u00e3o foi pronunciada:<\/b>  \u201cO poder de autodestrui\u00e7\u00e3o da humanidade \u00e9 o que a destaca como inteligente. Por mais burro que isso possa parecer.\u201d <\/p>\n<p>  Dona Dita contando as not\u00edcias sobre viol\u00eancia contra humanos e contra a natureza.<b> <\/p>\n<p><\/b><b>  <\/b><b>Sem raz\u00e3o<\/b>  Perguntaram \u00e0 coluna sobre a fun\u00e7\u00e3o de um carro da pol\u00edcia que fica em frente a papelaria Risk com o rotolight ligado. S\u00f3 sai dali depois que a loja fecha. N\u00e3o sabemos responder mas aguardamos a resposta das autoridades. <\/p>\n<p>  <b>Nada<\/b>  V\u00e1rios senadores disseram na mesma linha mel\u00f3dica. N\u00e3o vamos deixar que aconte\u00e7a com essa CPI a mesma coisa que aconteceu com a CPI da Petrobr\u00e1s. O caso \u00e9 que os 19 bilh\u00f5es em redu\u00e7\u00e3o de tributos e sonega\u00e7\u00e3o investigados pela opera\u00e7\u00e3o Zelotes ainda est\u00e1 sem resposta. Nelson Mallmann, Leonardo Siade Manzan e Paulo Roberto Cortez recusaram o convite para depor. Agora o convite ser\u00e1 diferente. <\/p>\n<p>  <b>MP 673<\/b>  Est\u00e1 um Deus nos acuda a hist\u00f3ria de cobrar placas de tratores. Qualquer coisa menos envolver Detran e Denatran com essa hist\u00f3ria. A ideia surgida \u00e9 de que a responsabilidade de identifica\u00e7\u00e3o e autoriza\u00e7\u00e3o parta das prefeituras que informariam o Minist\u00e9rio da Agricultura sobre os registros. <\/p>\n<p>  <b>Quase parando<\/b>  Tudo bem que o jornal distrital dispon\u00edvel na p\u00e1gina da C\u00e2mara Legislativa seja de dezembro de 2014. Pelo menos a imprensa da CLDF come\u00e7a a aparecer. A TV Distrital tamb\u00e9m j\u00e1 est\u00e1 acess\u00edvel. Um doce para quem conseguir o plen\u00e1rio em a\u00e7\u00e3o. <\/p>\n<p>  <b>Corrup\u00e7\u00e3o n\u00e3o!<\/b>  J\u00e1 que nem a OAB nem qualquer institui\u00e7\u00e3o brasileira tomou a iniciativa, a Associa\u00e7\u00e3o Iberoamericana de Minist\u00e9rios P\u00fablicos est\u00e1 cada vez com mais adeptos \u00e0 campanha #CORRUP\u00c7\u00c3ON\u00c3O Quanto mais compartilhamento das pe\u00e7as de divulga\u00e7\u00e3o, melhor. Importante \u00e9 registrar que os contribuintes est\u00e3o atentos. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>circecunha@gmail.com; arigcunha@ig.com.br Diz-me com quem andas Prefer\u00eancia pessoal n\u00e3o se discute, pois tem gente que gosta da fruta e outros, do caro\u00e7o. Agora, quando essas mesmas prefer\u00eancias avan\u00e7am do circulo \u00edntimo e tocam no p\u00fablico , a coisa ganha uma dimens\u00e3o grave e acaba por atingir a todos indiscriminadamente. Depois de treze anos no poder, ningu\u00e9m mais parece se surpreender [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-206","post","type-post","status-publish","format-standard","hentry","category-integra-integra"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=206"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/206\/revisions"}],"predecessor-version":[{"id":7789,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/206\/revisions\/7789"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}