{"id":186,"date":"2015-05-29T01:40:00","date_gmt":"2015-05-29T04:40:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/visto_lido_e_ouvido-146\/"},"modified":"2016-05-13T19:30:33","modified_gmt":"2016-05-13T22:30:33","slug":"visto_lido_e_ouvido-146","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/visto_lido_e_ouvido-146\/","title":{"rendered":"VISTO, LIDO E OUVIDO"},"content":{"rendered":"\n<p>circecunha@gmail.com; arigcunha @ig.com.br <\/p>\n<p><b>Casa da Mulher Brasileira<\/b> <\/p>\n<p>Ontem,  com a inaugura\u00e7\u00e3o da Casa da Mulher Brasileira, &nbsp;Bras\u00edlia passa a  integrar com outros Estados da federa\u00e7\u00e3o , uma rede de acolhimento e  atendimento humanizado \u00e0s mulheres v\u00edtimas de viol\u00eancia. Situada na  quadra 601 da L2 Norte, o espa\u00e7o , com 3.600 metros quadrados ir\u00e1  &nbsp;atender mulheres de todas as Regi\u00f5es Administrativas do DF.O  projeto , que faz parte do programa do governo federal \u201cMulher, Viver  sem Viol\u00eancia\u201d , facilitar\u00e1 o acesso a servi\u00e7os especializados de  assist\u00eancia. Para um pa\u00eds que se prop\u00f5e integrar a elite das na\u00e7\u00f5es  desenvolvidas, as estat\u00edsticas referentes ao tratamento dispensado \u00e0s  mulheres brasileiras nos aproxima mais da barb\u00e1rie do que do grau  evolutivo de civiliza\u00e7\u00e3o, fazendo de todos n\u00f3s, em graus variados,  cumplices e\/ou part\u00edcipes indiretos &nbsp;dessa covardia hist\u00f3rica.Pesquisa  do Ipea demonstra que entre 2001 e 2011, ocorreram no Brasil mais de 50  mil feminic\u00eddios, &nbsp;com uma m\u00e9dia vergonhosa de uma morte a cada 1h30. O  DataSenado demonstrou por pesquisa cientificamente comprovada que 23,3%  das v\u00edtimas de viol\u00eancia dom\u00e9stica n\u00e3o denunciam os parceiros \u00e0  pol\u00edcia, por acreditarem que eles n\u00e3o ser\u00e3o punidos. Para 30% das  pessoas pesquisadas, as leis do pa\u00eds n\u00e3o s\u00e3o capazes de proteger  adequadamente as mulheres contra a viol\u00eancia que normalmente ocorrem  dentro do pr\u00f3prio lar. O Instituto Patr\u00edcia Galv\u00e3o revelou na busca de  dados que 7 em cada 10 casos de viol\u00eancia contra a mulher s\u00e3o praticados  dentro de casa.&nbsp;O Mapa da Viol\u00eancia,  publicado anualmente aponta que em cada 10 brasileiros, 6 conhecem  alguma mulher que j\u00e1 foi v\u00edtima de viol\u00eancia. O mesmo informe atribui ao  machismo (46% ) e ao alcoolismo (31%) as principais causas que levam \u00e0  esse tipo de viol\u00eancia. Embora muito bem vindo, este novo espa\u00e7o de  amparo \u00e0s mulheres, demonstra claramente que um pa\u00eds que necessita desse  tipo assist\u00eancia estatal para estancar a brutalidade contra as  mulheres, ainda est\u00e1 longe do grau ideal de civilidade e desenvolvimento  humano adequado. <\/p>\n<p><b>A frase que n\u00e3o foi pronunciada:<\/b> <\/p>\n<p>\u201cEst\u00e1 Na Hora de voltar&#8230;\u201dPensamento da popula\u00e7\u00e3o que paga e da popula\u00e7\u00e3o que quer o servi\u00e7o! <\/p>\n<p><b>Caixa fechado<\/b>Quem  ser\u00e1 o Anderson? Foi o \u00fanico contato que sobrou na p\u00e1gina da  Subsecretaria de Moderniza\u00e7\u00e3o do Atendimento Imediato ao Cidad\u00e3o \u2013 Na  Hora.&nbsp; O caso Na Hora vem se complicando a cada dia. Quem vai querer  receber menos R$432 mil para fazer os mesmos servi\u00e7os?&nbsp; <\/p>\n<p><b>Aut\u00f3grafos<\/b>Uma  CPI no Congresso articulada pelo senador Rom\u00e1rio pode at\u00e9 levar  holofotes para o Senado. Talvez como foi a CPI da Nike. Mas s\u00f3 isso. <\/p>\n<p><b>Lebre por gato<\/b>Voc\u00ea  deve estar se perguntando. O que tem a ver a pol\u00edcia dos Estados Unidos  com a FIFA? Por que os americanos est\u00e3o articulando essas pris\u00f5es,  indiciamentos e confiscos? A resposta veio de Alexandra Wrage: A raz\u00e3o \u00e9  simples. Muitos pa\u00edses s\u00e3o intimidados pela Fifa e essa foi a solu\u00e7\u00e3o.  Talvez a Fifa n\u00e3o soubesse ao contratar a senhora Alexandra que ela j\u00e1  presidiu o Comit\u00ea Anticorrup\u00e7\u00e3o da Ordem dos Advogados dos Estados  Unidos. <\/p>\n<p><b>Aprenda l\u00e1 d\u00e1 c\u00e1<\/b>A  Funda\u00e7\u00e3o Estudar encampou a ideia desde o preparo dos alunos at\u00e9  lan\u00e7a-los no mundo. S\u00e3o 26 jovens que conquistaram a dif\u00edcil tarefa de  passar no teste para fazer parte do corpo docente de uma universidade  conceituada e estrangeira. Todos foram aceitos por m\u00e9rito pr\u00f3prio, em  v\u00e1rias delas, &nbsp;e agora n\u00e3o podem pagar o seguro viagem. <\/p>\n<p><b>Em tempo<\/b>Ia fechar a coluna quando chegou a missiva de Luiz Felipe  Costa Gomide, um dos alunos que participa da campanha para arrecadar  fundos e levar nossos brilhantes estudantes a buscar novas experi\u00eancias  em novos ares. Ele explica que precisam arrecadar R$350 mil reais para  cobrir o m\u00ednimo da necessidade de todos os envolvidos. Trata-se de um  suporte para 2 anos de custos de educa\u00e7\u00e3o de apenas um estudante. O  custo anual \u00e9 de US$64 mil. <\/p>\n<p><b>Contrapartidas 1<\/b>&nbsp;Luiz Felipe explica que quem ajudar pelo site &nbsp;<a href=\"http:\/\/juntos.com.vc\/pt\/aprendaladaca\" target=\"_blank\">http:\/\/juntos.com.vc\/pt\/aprendaladaca<\/a>  receber\u00e1 contrapartidas como receber um cart\u00e3o postal da faculdade,  tomar um sorvete conosco \u201c(por nossa conta!)\u201d e at\u00e9 a concorrer \u00e0 camisa  de manga comprida oficial do Schweinsteiger para a final da Copa do  Mundo. As doa\u00e7\u00f5es est\u00e3o aumentando. <\/p>\n<p><b>Contrapartidas 2<\/b>Outro  bloco de contrapartidas atinge quem tiver interesse em estudar fora  tamb\u00e9m. Eles podem dar dicas de provas, corrigir reda\u00e7\u00f5es ou assessoria  por um bate papo para ajudar na escolha de universidades. Se a pessoa  n\u00e3o tiver interesse em nenhuma das recompensas, tem mais uma. Ela poder\u00e1  converter todo o processo de assessoria que oferecemos a um aluno do  programa ISMART, programa o qual busca talentos em escolas p\u00fablicas e os  auxiliam a atingir grandes feitos.. <\/p>\n<p><b>Confiram<\/b>Vejam  a lista das universidades que os esperam: Assumption College, Brown  University, Carleton College, Columbia University, Georgetown  University, Georgia Institute of Technology (Georgia Tech), Harvard  University, Johns Hopkins University, Massachusetts Institute of  Technology (MIT), Princeton University, Project Minerva, Stanford  University, University of British Columbia, University of Chicago,  University of Notre Dame, University of Pennsylvania (UPenn), Wesleyan  University, Yale University. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>circecunha@gmail.com; arigcunha @ig.com.br Casa da Mulher Brasileira Ontem, com a inaugura\u00e7\u00e3o da Casa da Mulher Brasileira, &nbsp;Bras\u00edlia passa a integrar com outros Estados da federa\u00e7\u00e3o , uma rede de acolhimento e atendimento humanizado \u00e0s mulheres v\u00edtimas de viol\u00eancia. Situada na quadra 601 da L2 Norte, o espa\u00e7o , com 3.600 metros quadrados ir\u00e1 &nbsp;atender mulheres de todas as Regi\u00f5es Administrativas [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-186","post","type-post","status-publish","format-standard","hentry","category-integra-integra"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=186"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/186\/revisions"}],"predecessor-version":[{"id":7805,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/186\/revisions\/7805"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}