{"id":181,"date":"2015-05-25T08:47:00","date_gmt":"2015-05-25T11:47:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/visto_lido_e_ouvido-141\/"},"modified":"2016-05-13T19:30:39","modified_gmt":"2016-05-13T22:30:39","slug":"visto_lido_e_ouvido-141","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/visto_lido_e_ouvido-141\/","title":{"rendered":"VISTO, LIDO E OUVIDO"},"content":{"rendered":"<p>  circecunha@gmail.com; arigcunha@ig.com.br<b> <\/p>\n<p><\/b><b>HIST\u00d3RIA DE BRAS\u00cdLIA<\/b>  Com isto, qualquer pessoa poder\u00e1 verificar isto: No trecho do Paran\u00e1 ao Vale do Ribeira, em vinte quil\u00f4metros, anteontem havia oito carros quebrados, por defeitos da estrada.  <b>&nbsp;(Publicado em 16\/08\/1961)<\/b>    <b> <\/p>\n<p><\/b><b>HIST\u00d3RIA DE BRAS\u00cdLIA<\/b>  Quanto \u00e0 BR-2, est\u00e1 assim: o leito cede ao peso dos transportes de carga, o que eq\u00fcivale dizer que a estrada foi constru\u00edda para os autom\u00f3veis de passeio, e n\u00e3o para transportar a produ\u00e7\u00e3o dos dois Grandes Estados.  <b>&nbsp;(Publicado em 16\/08\/1961)<\/b>    <b> <\/p>\n<p><\/b><b>HIST\u00d3RIA DE BRAS\u00cdLIA<\/b>  O sr. Ibrahim Sued, diz que ficou revoltado quando viu numa revista estrangeira, o sr. J\u00e2nio Quadros vestido de slack, recebendo os russos da Miss\u00e3o da Boa Vontade. Mais uma vez o colunista social se revolta contra o presidente que ele mesmo elegeu, exatamente por causa da vestimenta, o que certifica o nosso ponto de vista, de que o sr. Ibrahim Sued votou no sr. J\u00e2nio Quadros para ter um elegante na presid\u00eancia.  <b>&nbsp;(Publicado em 16\/08\/1961)<\/b>    <b> <\/p>\n<p><\/b><b>HIST\u00d3RIA DE BRAS\u00cdLIA<\/b>  Enquanto o governo aperta o cerco dos contrabandistas, no Cear\u00e1 uma maleta \u00e9 apreendida no aeroporto cheia de j\u00f3ias japonesas, e um avi\u00e3o hidroplano pousa no A\u00e7ude Pentecoste, descarrega a muamba num caminh\u00e3o, vai embora, e ningu\u00e9m sabe quem \u00e9.  <b>&nbsp;(Publicado em 16\/08\/1961)<\/b>    <b> <\/p>\n<p><\/b><b>HIST\u00d3RIA DE BRAS\u00cdLIA<\/b>  Nada mais imbecil do que o artigo de ontem do sr. Ferreira Goulart no \u201cJornal do Brasil\u201d. Dizer que em Bras\u00edlia n\u00e3o se consegue tirar uma fotografia 3&#215;4 em cinco minutos \u00e9 \u201cmorar no Rio\u201d.  <b>&nbsp;(Publicado em 16\/08\/1961)<\/b>    <b> <\/p>\n<p><\/b><b>HIST\u00d3RIA DE BRAS\u00cdLIA<\/b>  Quando quiser escrever dessas besteiras, seu Goulart, me procure, e eu lhe direi que o Guimar\u00e3es da Quadra 105 tira retrato at\u00e9 de madrugada, porque mora no local.  <b>&nbsp;(Publicado em 16\/08\/1961)<\/b>     <\/p>\n","protected":false},"excerpt":{"rendered":"<p>circecunha@gmail.com; arigcunha@ig.com.br HIST\u00d3RIA DE BRAS\u00cdLIA Com isto, qualquer pessoa poder\u00e1 verificar isto: No trecho do Paran\u00e1 ao Vale do Ribeira, em vinte quil\u00f4metros, anteontem havia oito carros quebrados, por defeitos da estrada. &nbsp;(Publicado em 16\/08\/1961) HIST\u00d3RIA DE BRAS\u00cdLIA Quanto \u00e0 BR-2, est\u00e1 assim: o leito cede ao peso dos transportes de carga, o que eq\u00fcivale dizer que a estrada foi [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-181","post","type-post","status-publish","format-standard","hentry","category-integra-integra"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/comments?post=181"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/181\/revisions"}],"predecessor-version":[{"id":7810,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/posts\/181\/revisions\/7810"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/media?parent=181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/categories?post=181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/aricunha\/wp-json\/wp\/v2\/tags?post=181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}