{"id":865,"date":"2020-05-04T20:35:19","date_gmt":"2020-05-04T23:35:19","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/?p=865"},"modified":"2020-05-04T20:35:19","modified_gmt":"2020-05-04T23:35:19","slug":"focos-de-incendio-no-pantanal-atingem-maior-patamar-em-10-anos","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/2020\/05\/04\/focos-de-incendio-no-pantanal-atingem-maior-patamar-em-10-anos\/","title":{"rendered":"Focos de inc\u00eandio no Pantanal atingem maior patamar em 10 anos"},"content":{"rendered":"<p>Seis meses ap\u00f3s um dos piores per\u00edodos de inc\u00eandios florestais dos \u00faltimos anos, os registros de sat\u00e9lites no Pantanal em 2020 preocupam. De janeiro a abril de 2020, foram registrados 1.456 focos de inc\u00eandio ante 674 no mesmo per\u00edodo de 2019. Isso indica que a ocorr\u00eancia de queimadas na regi\u00e3o mais que dobrou de um ano para o outro, com aumento de 116%. O n\u00famero \u00e9 o maior dos \u00faltimos 10 anos e, aproximadamente, seis vezes maior que a m\u00e9dia deste per\u00edodo.<\/p>\n<p>A \u00e1rea queimada nos quatro primeiros meses de 2019 foi de 1.172 km\u00b2. Em 2020 j\u00e1 foi de 1.628 km\u00b2, aumento de 38%, percentual que deve se elevar ainda mais com a crescente detec\u00e7\u00e3o de focos de calor. Os maiores focos est\u00e3o no localizados no Parque Nacional do Pantanal Matogrossense e \u00e1reas pr\u00f3ximas da Serra do Amolar. Veja no quadro abaixo o salto nos focos de inc\u00eandio este ano.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-866 size-full\" src=\"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/05\/focos-de-inc\u00eandio.jpg\" alt=\"\" width=\"757\" height=\"439\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/05\/focos-de-inc\u00eandio.jpg 757w, https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/05\/focos-de-inc\u00eandio-300x174.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/05\/focos-de-inc\u00eandio-550x319.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/05\/focos-de-inc\u00eandio-230x133.jpg 230w\" sizes=\"auto, (max-width: 757px) 100vw, 757px\" \/><\/p>\n<h2 style=\"text-align: center\"><strong>Focos de inc\u00eandio<\/strong><\/h2>\n<p>J\u00falio Sampaio, gerente do Programa Cerrado Pantanal do WWF-Brasil, diz que a situa\u00e7\u00e3o \u00e9 bastante at\u00edpica este ano. \u201cChoveu bem menos na \u00e9poca \u00famida. Segundo dados da Embrapa, s\u00f3 choveu a metade do que era esperado para o per\u00edodo. O n\u00edvel da \u00e1gua praticamente n\u00e3o subiu. As lagoas que deveriam estar cheias de jacar\u00e9 est\u00e3o secas. E o fogo voltou a aparecer com for\u00e7a\u201d, conta. O per\u00edodo n\u00e3o \u00e9 de combate, mas de planejamento para a seca. No entanto, em Mato Grosso do Sul, quatro aeronaves est\u00e3o fazendo combate di\u00e1rio.<\/p>\n<p>\u201cO combate \u00e9 um desafio, ainda mais agora em tempos de pandemia. S\u00e3o \u00e1reas isoladas, com acesso por barco pelo rio ou por aeronaves. Qualquer tr\u00e2nsito, neste momento, \u00e9 uma preocupa\u00e7\u00e3o a mais nos munic\u00edpios\u201d, ressalta.<\/p>\n<p>A fuma\u00e7a e fuligem geradas pelos inc\u00eandios tamb\u00e9m preocupam. \u201cIsso vai pressionar ainda mais o sistema de sa\u00fade, al\u00e9m de representar mais risco de contamina\u00e7\u00e3o pelo novo coronav\u00edrus, uma vez que afeta o sistema respirat\u00f3rio\u201d, explica Sampaio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-867 alignright\" src=\"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/05\/focos-wwf.png\" alt=\"\" width=\"407\" height=\"569\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/05\/focos-wwf.png 407w, https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/05\/focos-wwf-215x300.png 215w, https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/05\/focos-wwf-230x322.png 230w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/p>\n<p>Segundo o especialista, a legisla\u00e7\u00e3o ambiental \u00e9 forte sobre a restri\u00e7\u00e3o do fogo, no entanto n\u00e3o \u00e9 respeitada e a fiscaliza\u00e7\u00e3o \u00e9 falha. \u201cO propriet\u00e1rio rural precisa de autoriza\u00e7\u00e3o e comunicar o uso do fogo. O que se percebe \u00e9 que a autoriza\u00e7\u00e3o n\u00e3o \u00e9 solicitada, o inc\u00eandio \u00e9 feito no per\u00edodo que n\u00e3o podia, com maior propaga\u00e7\u00e3o\u201d, lamenta.<\/p>\n<p>O munic\u00edpio mais afetado, Corumb\u00e1 (<strong>veja no quadro acima<\/strong>), \u00e9 principal respons\u00e1vel pela produ\u00e7\u00e3o de gado no Pantanal. \u201cO fogo vem sendo utilizado para renova\u00e7\u00e3o das pastagens. E isso aumenta o risco de inc\u00eandio\u201d, diz Sampaio.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seis meses ap\u00f3s um dos piores per\u00edodos de inc\u00eandios florestais dos \u00faltimos anos, os registros de sat\u00e9lites no Pantanal em 2020 preocupam. De janeiro a abril de 2020, foram registrados 1.456 focos de inc\u00eandio ante 674 no mesmo per\u00edodo de 2019. Isso indica que a ocorr\u00eancia de queimadas na regi\u00e3o mais que dobrou de um ano para o outro, com [&hellip;]<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[155,242],"tags":[4,253,143,93,62],"class_list":["post-865","post","type-post","status-publish","format-standard","hentry","category-catastrofe-ambiental","category-denuncia","tag-4elementos1planeta","tag-focos-de-incendio","tag-pantanal","tag-queimadas","tag-wwf-brasil"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-json\/wp\/v2\/posts\/865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-json\/wp\/v2\/comments?post=865"}],"version-history":[{"count":5,"href":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-json\/wp\/v2\/posts\/865\/revisions"}],"predecessor-version":[{"id":872,"href":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-json\/wp\/v2\/posts\/865\/revisions\/872"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-json\/wp\/v2\/media?parent=865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-json\/wp\/v2\/categories?post=865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-json\/wp\/v2\/tags?post=865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}