{"id":1608,"date":"2020-09-18T16:59:11","date_gmt":"2020-09-18T19:59:11","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30.jpeg"},"modified":"2020-09-18T17:05:11","modified_gmt":"2020-09-18T20:05:11","slug":"whatsapp-image-2020-09-18-at-16-26-30","status":"inherit","type":"attachment","link":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/2020\/09\/18\/queimadas-em-setembro-aumento-de-86-na-amazonia-e-5-mil-focos-no-pantanal\/whatsapp-image-2020-09-18-at-16-26-30\/","title":{"rendered":"WhatsApp Image 2020-09-18 at 16.26.30"},"author":114,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-1608","attachment","type-attachment","status-inherit","hentry"],"smush":{"stats":{"percent":2.284787817416181,"bytes":4129,"size_before":180717,"size_after":176588,"time":0.19,"api_version":"1.0","lossy":false,"keep_exif":true},"sizes":{"thumbnail":{"percent":0,"bytes":0,"size_before":4334,"size_after":4334,"time":0.01},"medium":{"percent":0,"bytes":0,"size_before":9103,"size_after":9103,"time":0.01},"medium_large":{"percent":2.5,"bytes":1242,"size_before":49738,"size_after":48496,"time":0.06},"large":{"percent":2.7,"bytes":2287,"size_before":84842,"size_after":82555,"time":0.03},"sunet-medium-thumb":{"percent":2.23,"bytes":600,"size_before":26877,"size_after":26277,"time":0.07},"sunet-small-thumb":{"percent":0,"bytes":0,"size_before":5823,"size_after":5823,"time":0.01}}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30-300x169.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30-300x169.jpeg 300w, https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30-768x432.jpeg 768w, https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30-1024x576.jpeg 1024w, https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30-550x309.jpeg 550w, https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30-230x129.jpeg 230w, https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Parque Nacional do Xingu em 10 de setembro \/ Cr\u00e9dito: Brigada do Ibama<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":720,"file":"2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30.jpeg","sizes":{"thumbnail":{"file":"WhatsApp-Image-2020-09-18-at-16.26.30-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30-150x150.jpeg"},"medium":{"file":"WhatsApp-Image-2020-09-18-at-16.26.30-300x169.jpeg","width":300,"height":169,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30-300x169.jpeg"},"medium_large":{"file":"WhatsApp-Image-2020-09-18-at-16.26.30-768x432.jpeg","width":768,"height":432,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30-768x432.jpeg"},"large":{"file":"WhatsApp-Image-2020-09-18-at-16.26.30-1024x576.jpeg","width":1024,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30-1024x576.jpeg"},"sunet-medium-thumb":{"file":"WhatsApp-Image-2020-09-18-at-16.26.30-550x309.jpeg","width":550,"height":309,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30-550x309.jpeg"},"sunet-small-thumb":{"file":"WhatsApp-Image-2020-09-18-at-16.26.30-230x129.jpeg","width":230,"height":129,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30-230x129.jpeg"},"full":{"file":"WhatsApp-Image-2020-09-18-at-16.26.30.jpeg","width":1280,"height":720,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0"}},"post":1607,"source_url":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-content\/uploads\/sites\/53\/2020\/09\/WhatsApp-Image-2020-09-18-at-16.26.30.jpeg","filename":"WhatsApp-Image-2020-09-18-at-16.26.30.jpeg","filesize":111098,"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-json\/wp\/v2\/media\/1608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-json\/wp\/v2\/comments?post=1608"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":1607,"href":"https:\/\/blogs.correiobraziliense.com.br\/4elementos\/wp-json\/wp\/v2\/posts\/1607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}